{"id":143345,"date":"2024-11-14T17:19:13","date_gmt":"2024-11-14T16:19:13","guid":{"rendered":"https:\/\/loudavymkrokem.cz\/?p=143345"},"modified":"2026-04-02T16:21:42","modified_gmt":"2026-04-02T14:21:42","slug":"wroclaw-polonia-o-que-fazer","status":"publish","type":"post","link":"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/","title":{"rendered":"Wroc\u0142aw, Pol\u00f4nia: 31 dicas do que ver e fazer em Bresl\u00e1via"},"content":{"rendered":"<p>Wroc\u0142aw, ou Bresl\u00e1via em portugu\u00eas, \u00e9 uma daquelas cidades que conquistam voc\u00ea instantaneamente. <strong>A Wroc\u0142aw Pol\u00f4nia \u00e9 a terceira maior cidade do pa\u00eds, localizada na regi\u00e3o da Baixa Sil\u00e9sia, com um lindo centro hist\u00f3rico, caf\u00e9s incr\u00edveis, museus, um bar tem\u00e1tico de Harry Potter, um zool\u00f3gico fant\u00e1stico e an\u00f5es espalhados por toda a cidade.<\/strong><\/p>\n\n<p>Vamos juntos descobrir tudo o que a <strong>cidade polonesa de Wroc\u0142aw tem a oferecer, o que ver, o que fazer e quando visit\u00e1-la.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-14.jpg\" alt=\"Wroc\u0142aw, Pol\u00f4nia: Dicas de pontos tur\u00edsticos em Bresl\u00e1via\" class=\"wp-image-89603\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-14.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-14-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-14-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-14-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-14-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Wroc\u0142aw, Pol\u00f4nia<\/figcaption><\/figure>\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Obsah \u010dl\u00e1nku<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Breslavia_Historia_da_cidade_de_Wroclaw\" >Bresl\u00e1via: Hist\u00f3ria da cidade de Wroc\u0142aw<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Quando_visitar_Wroclaw_Clima_e_turismo\" >Quando visitar Wroc\u0142aw? Clima e turismo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Hoteis_baratos_em_Wroclaw_Onde_se_hospedar\" >Hot\u00e9is baratos em Wroc\u0142aw: Onde se hospedar<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Wroclaw_Polonia_31_dicas_de_pontos_turisticos_e_lugares_interessantes\" >Wroc\u0142aw Pol\u00f4nia: 31 dicas de pontos tur\u00edsticos e lugares interessantes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#1_Cidade_Velha_e_Rynek\" >1. Cidade Velha e Rynek<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#2_Anoes_em_cada_esquina\" >2. An\u00f5es em cada esquina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#3_Ostrow_Tumski_A_parte_mais_antiga_da_cidade\" >3. Ostr\u00f3w Tumski: A parte mais antiga da cidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#4_Ponte_Tumski\" >4. Ponte Tumski<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#5_Plac_Solny\" >5. Plac Solny<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#6_Jardim_Japones\" >6. Jardim Japon\u00eas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#7_Wyspa_Slodowa_%E2%80%93_um_lugar_com_verdadeira_atmosfera_local\" >7. Wyspa S\u0142odowa \u2013 um lugar com verdadeira atmosfera local<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#7_Panorama_Raclawicka\" >7. Panorama Rac\u0142awicka<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#8_Nadodrze\" >8. Nadodrze<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#9_Vida_noturna_e_dicas_de_bares\" >9. Vida noturna e dicas de bares<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#10_Mercado_de_Natal_encantador\" >10. Mercado de Natal encantador<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#11_Universidade_de_Wroclaw_e_seus_interiores_deslumbrantes\" >11. Universidade de Wroc\u0142aw e seus interiores deslumbrantes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#12_Zoo_e_Afrykarium\" >12. Zoo e Afrykarium<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#13_Dzielnica_Czterech_Wyznan\" >13. Dzielnica Czterech Wyzna\u0144<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#14_Salao_do_Centenario_UNESCO\" >14. Sal\u00e3o do Centen\u00e1rio (UNESCO)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#15_Fonte_Multimidia\" >15. Fonte Multim\u00eddia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#16_Memorial_da_Passagem_Anonima\" >16. Memorial da Passagem An\u00f4nima<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#17_Teleferico_Polinka\" >17. Telef\u00e9rico Polinka<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#18_Tour_guiado_a_pe\" >18. Tour guiado a p\u00e9<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#19_Experimente_a_culinaria_polonesa_tradicional\" >19. Experimente a culin\u00e1ria polonesa tradicional<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Pierogi\" >Pierogi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Sopas_tradicionais_polonesas\" >Sopas tradicionais polonesas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Entradas_e_petiscos_para_acompanhar_cerveja\" >Entradas e petiscos para acompanhar cerveja<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Paczki\" >P\u0105czki<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Food_tours_em_Wroclaw\" >Food tours em Wroc\u0142aw<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#20_Feiras_de_pulgas\" >20. Feiras de pulgas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#21_Bar_do_Harry_Potter_%E2%80%93_Pod_Trzema_Miotlami\" >21. Bar do Harry Potter \u2013 Pod Trzema Miot\u0142ami<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#22_Antigo_cemiterio_judaico\" >22. Antigo cemit\u00e9rio judaico<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#23_Hydropolis\" >23. Hydropolis<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#24_Conjunto_habitacional_WuWa\" >24. Conjunto habitacional WuWa<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#25_Sky_Tower_%E2%80%93_o_edificio_mais_alto_de_Wroclaw\" >25. Sky Tower \u2013 o edif\u00edcio mais alto de Wroc\u0142aw<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#26_Fosso_da_cidade\" >26. Fosso da cidade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-37\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#27_Colina_dos_Partisanos\" >27. Colina dos Partisanos<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-38\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#28_Mirante_da_torre_da_Basilica_de_Santa_Isabel\" >28. Mirante da torre da Bas\u00edlica de Santa Isabel<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-39\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Wroclaw_Mapa_com_pontos_de_interesse_para_o_celular\" >Wroc\u0142aw: Mapa com pontos de interesse para o celular<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-40\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#29_Mirante_da_Ponte_dos_Penitentes\" >29. Mirante da Ponte dos Penitentes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-41\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#30_Melhores_cafes_em_Wroclaw\" >30. Melhores caf\u00e9s em Wroc\u0142aw<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-42\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#31_Melhores_restaurantes_em_Wroclaw\" >31. Melhores restaurantes em Wroc\u0142aw<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-43\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Perguntas_frequentes\" >Perguntas frequentes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-44\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#O_que_fazer_com_criancas_em_Wroclaw\" >O que fazer com crian\u00e7as em Wroc\u0142aw?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-45\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#O_que_fazer_em_Wroclaw_quando_chove\" >O que fazer em Wroc\u0142aw quando chove?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-46\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/wroclaw-polonia-o-que-fazer\/#Quantos_dias_ficar_em_Wroclaw\" >Quantos dias ficar em Wroc\u0142aw?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Breslavia_Historia_da_cidade_de_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"Breslavia_Historia_da_cidade_de_Wroclaw\"><\/span>Bresl\u00e1via: Hist\u00f3ria da cidade de Wroc\u0142aw<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p><strong>O que saber sobre a hist\u00f3ria de Wroc\u0142aw antes de visit\u00e1-la?<\/strong> E de onde vem o nome da cidade? A hist\u00f3ria de Wroc\u0142aw remonta aos tempos em que os primeiros colonos fundaram seu assentamento em uma posi\u00e7\u00e3o estrat\u00e9gica junto ao rio Oder, onde se cruzavam importantes rotas comerciais.<\/p>\n\n<p>A cidade surgiu como entroncamento de antigas <strong>rotas que ligavam o sul da Europa ao Mar B\u00e1ltico e o oeste ao leste, at\u00e9 o Mar Negro.<\/strong><\/p>\n\n<p>No s\u00e9culo X, a regi\u00e3o da Sil\u00e9sia ficou sob o <strong>dom\u00ednio do pr\u00edncipe tcheco Vratislav,<\/strong> <strong>de quem a cidade provavelmente herdou seu nome.<\/strong> No final do s\u00e9culo X, tornou-se parte da <strong>Pol\u00f4nia e, no ano 1000, durante o reinado de Boles\u0142aw I, o Bravo, foi fundado um bispado subordinado ao arcebispado de Gniezno.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1.jpg\" alt=\"O que ver e fazer em Wroc\u0142aw\" class=\"wp-image-89555\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">O que ver e fazer em Wroc\u0142aw<\/figcaption><\/figure>\n\n<p>No s\u00e9culo XIII, a cidade passou por uma grande transforma\u00e7\u00e3o \u2013 <strong>foi gradualmente unificada e reconstru\u00edda segundo o direito alem\u00e3o.<\/strong> Houve um grande fluxo de colonos alem\u00e3es, convidados pelos Piast da Sil\u00e9sia para impulsionar o desenvolvimento da regi\u00e3o. <strong>Em 1261, Wroc\u0142aw tornou-se uma cidade administrada por um conselho municipal segundo o Direito de Magdeburgo.<\/strong><\/p>\n\n<p><strong>Em 1335, ap\u00f3s a extin\u00e7\u00e3o do ramo silesiano dos Piast, Wroc\u0142aw passou para a Coroa da Bo\u00eamia e, posteriormente, ficou sob o dom\u00ednio dos Habsburgos.<\/strong> Durante a Reforma Protestante no s\u00e9culo XVI, a cidade se tornou um dos principais centros do protestantismo. Em 1741, a Sil\u00e9sia, incluindo Wroc\u0142aw, passou para o dom\u00ednio prussiano, e a cidade se tornou um importante ponto de apoio do reino da Pr\u00fassia.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-16.jpg\" alt=\"\" class=\"wp-image-89611\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-16.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-16-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-16-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-16-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-16-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Wroc\u0142aw, Pol\u00f4nia<\/figcaption><\/figure>\n\n<p><strong>Durante as Guerras Napole\u00f4nicas, a cidade foi ocupada por tropas francesas,<\/strong> o que levou \u00e0 demoli\u00e7\u00e3o das antigas muralhas. Isso, paradoxalmente, permitiu o desenvolvimento da cidade. No s\u00e9culo XIX, Wroc\u0142aw se tornou um importante polo industrial e de transportes, gra\u00e7as \u00e0 inaugura\u00e7\u00e3o do primeiro trecho ferrovi\u00e1rio entre Wroc\u0142aw e O\u0142awa em 1842.<\/p>\n\n<p><strong>Na primeira metade do s\u00e9culo XX, Wroc\u0142aw fazia parte da Alemanha<\/strong> e se tornou um dos seus principais centros culturais. A Segunda Guerra Mundial trouxe enormes perdas \u00e0 cidade \u2013 no final da guerra, quase toda a cidade havia sido destru\u00edda. <strong>Ap\u00f3s a guerra, em 1945, Wroc\u0142aw voltou a fazer parte da Pol\u00f4nia e come\u00e7ou o processo de reconstru\u00e7\u00e3o e repovoamento com habitantes poloneses.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-12-700x467.jpg\" alt=\"Wroc\u0142aw ap\u00f3s a Segunda Guerra Mundial\" class=\"wp-image-89595\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-12-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-12-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-12-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-12-696x464.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-12.jpg 1200w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\"><figcaption class=\"wp-element-caption\">Wroc\u0142aw ap\u00f3s a Segunda Guerra Mundial<\/figcaption><\/figure>\n\n<p><strong>Durante o per\u00edodo comunista, a cidade se tornou um dos principais centros de oposi\u00e7\u00e3o ao regime.<\/strong> Em 1980, nasceu aqui o forte movimento Solidariedade e, em 1983, o Papa Jo\u00e3o Paulo II visitou a cidade, fortalecendo o \u00e2nimo dos moradores.<\/p>\n\n<p><strong>Ap\u00f3s a queda do comunismo em 1989, Wroc\u0142aw come\u00e7ou a passar por uma grande transforma\u00e7\u00e3o e hoje \u00e9 um dos mais importantes centros culturais, acad\u00eamicos e econ\u00f4micos da Pol\u00f4nia.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-21.jpg\" alt=\"Wroc\u0142aw, Pol\u00f4nia\" class=\"wp-image-89631\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-21.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-21-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-21-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-21-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-21-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">O que ver e fazer em Wroc\u0142aw<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Quando_visitar_Wroclaw_Clima_e_turismo\"><\/span><span class=\"ez-toc-section\" id=\"Quando_visitar_Wroclaw_Clima_e_turismo\"><\/span>Quando visitar Wroc\u0142aw? Clima e turismo<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Wroc\u0142aw \u00e9 uma \u00f3tima escolha para visitar praticamente em qualquer \u00e9poca do ano, mas se voc\u00ea quer saber qual \u00e9 a melhor \u00e9poca, vamos l\u00e1: <strong>se voc\u00ea gosta de calor, v\u00e1 no ver\u00e3o. O m\u00eas com mais turistas \u00e9 agosto, ent\u00e3o se prefere temperaturas agrad\u00e1veis com menos gente, opte por junho ou setembro<\/strong>\u2026<\/p>\n\n<p>A primavera e o outono tamb\u00e9m s\u00e3o lindos, embora possa fazer um pouco de frio. Se voc\u00ea quiser vivenciar a magia dos <strong><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/mercados-natal-wroclaw-polonia\/\" target=\"_blank\" data-type=\"post\" data-id=\"89419\" rel=\"noreferrer noopener\">mercados de Natal<\/a><\/strong>, ent\u00e3o a resposta \u00e9 clara: v\u00e1 em dezembro.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Hoteis_baratos_em_Wroclaw_Onde_se_hospedar\"><\/span><span class=\"ez-toc-section\" id=\"Hoteis_baratos_em_Wroclaw_Onde_se_hospedar\"><\/span><strong>Hot\u00e9is baratos em Wroc\u0142aw: Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Se voc\u00ea procura uma hospedagem mais em conta, mas ainda assim limpa e estilosa, recomendamos o <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"Legnicka Business Apartments\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/legnicka-business-apartments\/\" data-shortcode=\"true\">Legnicka Business Apartments<\/a><\/strong>. Ainda mais barato e bem no centro est\u00e3o os apartamentos <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"Staycity Apartments Sukiennice 6\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/staycity-apartments-sukiennice-6\/\" data-shortcode=\"true\">Staycity Apartments Sukiennice 6<\/a><\/strong>, por\u00e9m o estacionamento \u00e9 mais caro (cerca de 18 \u20ac por dia), ent\u00e3o vale mais a pena se voc\u00ea estiver viajando de \u00f4nibus ou trem.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wroclaw_Polonia_31_dicas_de_pontos_turisticos_e_lugares_interessantes\"><\/span><span class=\"ez-toc-section\" id=\"Wroclaw_Polonia_31_dicas_de_pontos_turisticos_e_lugares_interessantes\"><\/span>Wroc\u0142aw Pol\u00f4nia: 31 dicas de pontos tur\u00edsticos e lugares interessantes<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p>Monumentos lindos, mirantes, an\u00f5es e at\u00e9 um restaurante tem\u00e1tico de Harry Potter. Vamos conferir tudo o que voc\u00ea precisa ver em Wroc\u0142aw. \u2764\ufe0f<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Cidade_Velha_e_Rynek\"><\/span><span class=\"ez-toc-section\" id=\"1_Cidade_Velha_e_Rynek\"><\/span>1. Cidade Velha e Rynek<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Vamos come\u00e7ar bem no cora\u00e7\u00e3o da cidade \u2013 <strong>no centro hist\u00f3rico.<\/strong> A Cidade Velha \u00e9 cercada por um canal e <strong>antigamente havia muralhas, que infelizmente foram destru\u00eddas por Napole\u00e3o.<\/strong><br>A parte mais importante da Cidade Velha \u00e9, claro, o Rynek, uma das maiores pra\u00e7as da Europa.<br>Voc\u00ea ver\u00e1 edif\u00edcios g\u00f3ticos e barrocos, a hist\u00f3rica prefeitura e at\u00e9 uma &#8220;janela falsa&#8221;. O Rynek tamb\u00e9m est\u00e1 repleto de caf\u00e9s, restaurantes e lojinhas de arte onde voc\u00ea pode comprar souvenirs.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"467\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vratislav-4-700x467.jpg\" alt=\"Wroc\u0142aw\" class=\"wp-image-89643\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vratislav-4-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vratislav-4-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vratislav-4-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vratislav-4-696x464.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vratislav-4.jpg 1200w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\"><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Anoes_em_cada_esquina\"><\/span><span class=\"ez-toc-section\" id=\"2_Anoes_em_cada_esquina\"><\/span>2. An\u00f5es em cada esquina<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea est\u00e1 viajando com crian\u00e7as (ou mesmo sem elas), <strong>\u00e9 imposs\u00edvel n\u00e3o notar os ic\u00f4nicos an\u00f5es de Wroc\u0142aw.<\/strong> Essas pequenas est\u00e1tuas de bronze come\u00e7aram a surgir nos anos 80 como s\u00edmbolo de resist\u00eancia contra o regime comunista. Hoje, existem mais de 800 espalhadas pela cidade, cada uma com seu pr\u00f3prio nome e hist\u00f3ria.<\/p>\n\n<p><strong>Transforme-se em ca\u00e7ador de an\u00f5es com as crian\u00e7as e tente encontrar o m\u00e1ximo poss\u00edvel!<\/strong> Existem at\u00e9 mapas e aplicativos que ajudam a localiz\u00e1-los. \ud83d\ude0e<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-18.jpg\" alt=\"An\u00f5es em Wroc\u0142aw\" class=\"wp-image-89619\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-18.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-18-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-18-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-18-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-18-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Ostrow_Tumski_A_parte_mais_antiga_da_cidade\"><\/span><span class=\"ez-toc-section\" id=\"3_Ostrow_Tumski_A_parte_mais_antiga_da_cidade\"><\/span>3. Ostr\u00f3w Tumski: A parte mais antiga da cidade<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Ostr\u00f3w Tumski, ou Ilha da Catedral, <strong>\u00e9 a parte mais antiga de Wroc\u0142aw, mas aten\u00e7\u00e3o: n\u00e3o \u00e9 uma ilha de verdade. \ud83d\ude05<\/strong><\/p>\n\n<p>Embora os moradores a chamem de &#8220;ilha&#8221;, tecnicamente j\u00e1 n\u00e3o \u00e9 uma h\u00e1 muito tempo. Antigamente era cercada pelo rio Oder, mas altera\u00e7\u00f5es no curso do rio mudaram sua configura\u00e7\u00e3o.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Ponte_Tumski\"><\/span><span class=\"ez-toc-section\" id=\"4_Ponte_Tumski\"><\/span>4. Ponte Tumski<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong>Ao se dirigir at\u00e9 l\u00e1, voc\u00ea passar\u00e1 pela hist\u00f3rica Ponte Tumski<\/strong>, que \u00e9 um s\u00edmbolo do amor. Todo o corrim\u00e3o est\u00e1 coberto de cadeados deixados por casais apaixonados como s\u00edmbolo de devo\u00e7\u00e3o eterna.<\/p>\n\n<p>As chaves s\u00e3o jogadas no rio com um gesto rom\u00e2ntico. N\u00e3o \u00e9 muito ecol\u00f3gico, mas rom\u00e2ntico com certeza \u00e9.<\/p>\n\n<p>Na Ilha Tumski, h\u00e1 v\u00e1rias igrejas importantes cujas torres formam marcos visuais de toda a cidade.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/Ostrow-Tumski.jpg\" alt=\"Ostr\u00f3w Tumski, Wroc\u0142aw\" class=\"wp-image-89647\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/Ostrow-Tumski.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/Ostrow-Tumski-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/Ostrow-Tumski-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/Ostrow-Tumski-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/Ostrow-Tumski-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/figure>\n\n<p>A mais famosa \u00e9 a Catedral de S\u00e3o Jo\u00e3o Batista, facilmente reconhec\u00edvel por suas duas torres vis\u00edveis de grande parte da cidade. Este templo g\u00f3tico impressiona pela arquitetura majestosa e pelo interior deslumbrante.<\/p>\n\n<p>A ilha tamb\u00e9m tem um charme especial durante o Natal, quando fica lindamente decorada e funciona como o cora\u00e7\u00e3o espiritual da cidade.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Plac_Solny\"><\/span><span class=\"ez-toc-section\" id=\"5_Plac_Solny\"><\/span>5. Plac Solny<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Logo ao lado do Rynek, voc\u00ea encontrar\u00e1 a pra\u00e7a menor Plac Solny, onde h\u00e1 barracas de flores abertas 24 horas por dia, 7 dias por semana. A qualquer hora do dia ou da noite, voc\u00ea pode comprar lindas flores.<br>Al\u00e9m disso, h\u00e1 \u00f3timos restaurantes e a galeria <strong><a href=\"https:\/\/openheim.org\/en\/#all\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">OP ENHEIM<\/a><\/strong>, dedicada \u00e0 arte moderna.<\/p>\n\n<p>Na Pra\u00e7a do Sal tamb\u00e9m h\u00e1 v\u00e1rios caf\u00e9s aconchegantes onde voc\u00ea pode saborear um caf\u00e9 e observar o movimento da cidade.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-9.jpg\" alt=\"Plac Solny\" class=\"wp-image-89583\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-9.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-9-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-9-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-9-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-9-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Plac Solny<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_Jardim_Japones\"><\/span><span class=\"ez-toc-section\" id=\"6_Jardim_Japones\"><\/span>6. Jardim Japon\u00eas<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea procura um lugar para relaxar um pouco, v\u00e1 com certeza ao <strong>Jardim Japon\u00eas, que fica atr\u00e1s do Sal\u00e3o do Centen\u00e1rio (UNESCO).<\/strong><\/p>\n\n<p>Este espa\u00e7o foi criado no in\u00edcio do s\u00e9culo XX e hoje, da primavera ao outono, \u00e9 um lugar agrad\u00e1vel para descansar.<\/p>\n\n<p>Nas proximidades, voc\u00ea tamb\u00e9m encontrar\u00e1 a Fonte Multim\u00eddia, onde \u00e0 noite acontecem shows de luz e m\u00fasica.<\/p>\n\n<p>O pr\u00f3prio Sal\u00e3o do Centen\u00e1rio \u00e9 uma joia arquitet\u00f4nica, constru\u00edda em 1913, e uma das mais importantes obras modernistas da Pol\u00f4nia.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"x13nWqJTpX4\"><iframe loading=\"lazy\" title=\"Wroc\u0142aw Fontanna Multimedialna\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/x13nWqJTpX4?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_Wyspa_Slodowa_%E2%80%93_um_lugar_com_verdadeira_atmosfera_local\"><\/span><span class=\"ez-toc-section\" id=\"7_Wyspa_Slodowa_um_lugar_com_verdadeira_atmosfera_local\"><\/span>7. Wyspa S\u0142odowa \u2013 um lugar com verdadeira atmosfera local<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong>Se voc\u00ea quer vivenciar a verdadeira atmosfera de Wroc\u0142aw, v\u00e1 at\u00e9 a ilha Wyspa S\u0142odowa.<\/strong> Especialmente nos meses de ver\u00e3o, o lugar fica cheio de jovens que v\u00eam para tomar cerveja, conversar e curtir o sol.<br><\/p>\n\n<p><strong>\u00c9 o \u00fanico lugar em Wroc\u0142aw onde beber \u00e1lcool em p\u00fablico \u00e9 tolerado.<\/strong> Na ilha tamb\u00e9m acontecem frequentemente shows e eventos culturais que valem a pena conferir.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-11.jpg\" alt=\"Wyspa S\u0142odowa\" class=\"wp-image-89591\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-11.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-11-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-11-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-11-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-11-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_Panorama_Raclawicka\"><\/span><span class=\"ez-toc-section\" id=\"7_Panorama_Raclawicka\"><\/span>7. Panorama Rac\u0142awicka<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong>Uma parada quase obrigat\u00f3ria \u00e9 a enorme pintura Panorama Rac\u0142awicka<\/strong>, que retrata a Batalha de Rac\u0142awice. Esta pintura monumental tem dimens\u00f5es de 114 \u00d7 15 metros.<\/p>\n\n<p>Ao lado da Panorama Rac\u0142awicka, encontra-se tamb\u00e9m o Museu Nacional de Arte, onde voc\u00ea pode admirar outras obras de arte.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"YPT2DZVh_qw\"><iframe loading=\"lazy\" title=\"Panorama Rac\u0142awicka w nowej ods\u0142onie\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/YPT2DZVh_qw?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"8_Nadodrze\"><\/span><span class=\"ez-toc-section\" id=\"8_Nadodrze\"><\/span>8. Nadodrze<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea curte cultura alternativa e street art, <strong>v\u00e1 com certeza ao bairro Nadodrze.<\/strong><\/p>\n\n<p>Essa regi\u00e3o era antes bastante abandonada, mas hoje est\u00e1 cheia de vida, arte e pequenas galerias. <strong>\u00c9 mais ou menos como a Vila Madalena em S\u00e3o Paulo \u2013 quem lembra de quando era um bairro simples e sem gra\u00e7a? Pois \u00e9, mudou completamente.<\/strong> \ud83d\ude05<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-1.jpg\" alt=\"Street art em Wroc\u0142aw\" class=\"wp-image-89635\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-1.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-1-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-1-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-1-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-1-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Street art em Wroc\u0142aw<\/figcaption><\/figure>\n\n<p>Voc\u00ea pode descobrir antigas inscri\u00e7\u00f5es alem\u00e3s nos edif\u00edcios ou visitar a galeria Neon Side, onde h\u00e1 uma cole\u00e7\u00e3o de antigos letreiros de neon.<\/p>\n\n<p><strong>Nadodrze tamb\u00e9m \u00e9 conhecida por seus caf\u00e9s, padarias e mercados locais, onde voc\u00ea pode experimentar a aut\u00eantica culin\u00e1ria polonesa.<\/strong><\/p>\n\n<p><strong>Nadodrze, literalmente traduzido como &#8220;acima do Oder&#8221;<\/strong>, era antigamente uma \u00e1rea n\u00e3o muito segura, com muitos pr\u00e9dios residenciais do pr\u00e9-guerra em estado prec\u00e1rio.<\/p>\n\n<p>Nos edif\u00edcios ainda s\u00e3o vis\u00edveis antigas inscri\u00e7\u00f5es em alem\u00e3o, que foram pintadas por cima ap\u00f3s a guerra, mas com o tempo a tinta come\u00e7ou a descascar e o passado alem\u00e3o est\u00e1 reaparecendo.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"9_Vida_noturna_e_dicas_de_bares\"><\/span><span class=\"ez-toc-section\" id=\"9_Vida_noturna_e_dicas_de_bares\"><\/span>9. Vida noturna e dicas de bares<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Wroc\u0142aw \u00e9 uma cidade de estudantes e a vida noturna reflete isso. <strong>Voc\u00ea encontra in\u00fameros bares, pubs e casas noturnas que valem a visita.<\/strong><br><br>Recomendamos passar pelo <strong>Bu\u0142ka z Mas\u0142em ou Mleczarnia<\/strong>, onde voc\u00ea pode tanto tomar caf\u00e9 da manh\u00e3 quanto curtir drinks \u00e0 noite.<\/p>\n\n<p>Se voc\u00ea curte cervejas artesanais, v\u00e1 ao <strong>Alebrowar<\/strong> ou ao espa\u00e7o multifuncional <strong>Recepcja<\/strong>, onde tamb\u00e9m acontecem v\u00e1rios eventos culturais.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"630\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vanocni-trhy-wroclaw-1.jpg\" alt=\"Mercado de Natal em Wroc\u0142aw, Pol\u00f4nia\" class=\"wp-image-89446\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vanocni-trhy-wroclaw-1.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vanocni-trhy-wroclaw-1-300x158.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vanocni-trhy-wroclaw-1-700x368.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vanocni-trhy-wroclaw-1-768x403.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/vanocni-trhy-wroclaw-1-696x365.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Mercado de Natal em Wroc\u0142aw, Pol\u00f4nia<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"10_Mercado_de_Natal_encantador\"><\/span><span class=\"ez-toc-section\" id=\"10_Mercado_de_Natal_encantador\"><\/span>10. Mercado de Natal encantador<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea for a Wroc\u0142aw no inverno, <strong>n\u00e3o pode perder o <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/mercados-natal-wroclaw-polonia\/\" target=\"_blank\" data-type=\"post\" data-id=\"89419\" rel=\"noreferrer noopener\">mercado de Natal no Rynek<\/a><\/strong>. \u00c9 um dos mais bonitos da Europa e todo o centro da cidade se transforma em um mundo encantado cheio de luzes, barracas de comida e, claro, vinho quente.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"11_Universidade_de_Wroclaw_e_seus_interiores_deslumbrantes\"><\/span><span class=\"ez-toc-section\" id=\"11_Universidade_de_Wroclaw_e_seus_interiores_deslumbrantes\"><\/span>11. Universidade de Wroc\u0142aw e seus interiores deslumbrantes<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong>O edif\u00edcio da Universidade de Wroc\u0142aw \u00e9 uma das mais belas constru\u00e7\u00f5es barrocas da Pol\u00f4nia.<\/strong> No interior, voc\u00ea encontrar\u00e1 os magn\u00edficos sal\u00f5es Aula Leopoldina e Oratorium Marianum, ricamente decorados com afrescos e esculturas. Tamb\u00e9m \u00e9 poss\u00edvel subir \u00e0 Torre Matem\u00e1tica, de onde se tem uma bela vista de toda a cidade.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-19.jpg\" alt=\"Zool\u00f3gico de Wroc\u0142aw, Pol\u00f4nia\" class=\"wp-image-89623\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-19.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-19-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-19-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-19-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-19-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Zool\u00f3gico de Wroc\u0142aw, Pol\u00f4nia<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"12_Zoo_e_Afrykarium\"><\/span><span class=\"ez-toc-section\" id=\"12_Zoo_e_Afrykarium\"><\/span>12. Zoo e Afrykarium<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong>O Zool\u00f3gico de Wroc\u0142aw \u00e9 o mais antigo da Pol\u00f4nia<\/strong> e tamb\u00e9m um dos maiores. Uma das principais atra\u00e7\u00f5es \u00e9 o <strong>Afrykarium<\/strong> \u2013 <strong>um ocean\u00e1rio \u00fanico<\/strong> que leva voc\u00ea ao mundo submarino da \u00c1frica. L\u00e1 voc\u00ea encontra tubar\u00f5es, arraias e outros animais ex\u00f3ticos.<\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-20.jpg\" alt=\"Zool\u00f3gico de Wroc\u0142aw, Pol\u00f4nia\" class=\"wp-image-89627\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-20.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-20-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-20-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-20-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-20-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Zool\u00f3gico de Wroc\u0142aw, Pol\u00f4nia<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"13_Dzielnica_Czterech_Wyznan\"><\/span><span class=\"ez-toc-section\" id=\"13_Dzielnica_Czterech_Wyznan\"><\/span>13. Dzielnica Czterech Wyzna\u0144<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Em Wroc\u0142aw existe o \u00fanico <strong>Dzielnica Czterech Wyzna\u0144 (Bairro das Quatro Denomina\u00e7\u00f5es), onde ficam lado a lado uma igreja cat\u00f3lica, uma sinagoga, uma catedral ortodoxa e uma igreja evang\u00e9lica<\/strong>. Este bairro \u00e9 um s\u00edmbolo de toler\u00e2ncia religiosa e respeito m\u00fatuo.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"14_Salao_do_Centenario_UNESCO\"><\/span><span class=\"ez-toc-section\" id=\"14_Salao_do_Centenario_UNESCO\"><\/span>14. Sal\u00e3o do Centen\u00e1rio (UNESCO)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>J\u00e1 mencionamos o Sal\u00e3o do Centen\u00e1rio acima, agora vamos conhec\u00ea-lo melhor. <strong>Esta joia arquitet\u00f4nica, que est\u00e1 na lista da UNESCO, foi constru\u00edda em 1913<\/strong> e deveria ser apenas uma constru\u00e7\u00e3o tempor\u00e1ria. Mas fique tranquilo, mesmo depois de mais de 100 anos, ela continua firme! No edif\u00edcio acontecem diversas exposi\u00e7\u00f5es, shows e eventos, por isso vale a pena entrar.<\/p>\n\n\n<div class=\"lk-stays-module\">\n<style>\n\/* \u2500\u2500\u2500 RESET PRO GUTENBERG \u2500\u2500\u2500 *\/\n.lk-stays-module * { box-sizing: border-box; margin: 0; padding: 0; }\n\n\/* \u2500\u2500\u2500 WRAPPER \u2500\u2500\u2500 *\/\n.lk-stays-module {\n  font-family: 'DM Sans', Georgia, sans-serif;\n  max-width: 100%;\n  margin: 2.5rem auto;\n  background: linear-gradient(135deg, #fdfaf5 0%, #fcf8f0 100%);\n  border: 1px solid #e8dfd4;\n  border-radius: 16px;\n  overflow: hidden;\n  box-shadow: 0 16px 48px rgba(195, 159, 118, 0.25), 0 4px 12px rgba(0,0,0,0.08);\n}\n\n\/* \u2500\u2500\u2500 HEADER \u2500\u2500\u2500 *\/\n.lk-stays-header {\n  position: relative;\n  padding: 24px 36px 24px;\n  background: linear-gradient(135deg, #c39f76 0%, #d4b188 60%, #c39f76 100%);\n  border-bottom: 1px solid rgba(255,255,255,.15);\n  display: flex;\n  align-items: center;\n  gap: 18px;\n}\n.lk-stays-header::before {\n  content: '';\n  position: absolute;\n  inset: 0;\n  background: url(\"data:image\/svg+xml,%3Csvg width='60' height='60' viewBox='0 0 60 60' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cg fill='none' fill-rule='evenodd'%3E%3Cg fill='%23ffffff' fill-opacity='0.05'%3E%3Cpath d='M36 34v-4h-2v4h-4v2h4v4h2v-4h4v-2h-4zm0-30V0h-2v4h-4v2h4v4h2V6h4V4h-4zM6 34v-4H4v4H0v2h4v4h2v-4h4v-2H6zM6 4V0H4v4H0v2h4v4h2V6h4V4H6z'\/%3E%3C\/g%3E%3C\/g%3E%3C\/svg%3E\") repeat;\n  pointer-events: none;\n}\n.lk-stays-icon {\n  flex-shrink: 0;\n  width: 68px;\n  height: 68px;\n  border-radius: 14px;\n  background: linear-gradient(135deg, #fff 0%, #f9f6f0 100%);\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  font-size: 26px;\n  box-shadow: 0 4px 12px rgba(0,0,0,0.15);\n}\n.lk-stays-eyebrow {\n  font-size: 10px;\n  font-weight: 500;\n  letter-spacing: 2.5px;\n  text-transform: uppercase;\n  color: rgba(255,255,255,.85);\n  margin: 0 0 5px 0;\n}\n.lk-stays-title {\n  font-family: 'Playfair Display', Georgia, serif;\n  font-size: 24px;\n  font-weight: 700;\n  color: #fff;\n  line-height: 1.2;\n  text-shadow: 0 1px 2px rgba(0,0,0,0.1);\n  margin: 0;\n}\n.lk-stays-subtitle {\n  font-size: 13px;\n  color: rgba(255,255,255,.75);\n  margin: 4px 0 0 0;\n  font-weight: 300;\n}\n\n\/* \u2500\u2500\u2500 CARDS GRID \u2500\u2500\u2500 *\/\n.lk-stays-grid {\n  display: grid;\n  grid-template-columns: 1fr 1fr;\n  gap: 1px;\n  background: rgba(195, 159, 118, 0.12);\n}\n\n\/* \u2500\u2500\u2500 SINGLE CARD \u2500\u2500\u2500 *\/\n.lk-stay-card {\n  background: #ffffff;\n  padding: 26px;\n  display: flex;\n  flex-direction: column;\n  gap: 11px;\n  transition: all 0.3s ease;\n  text-decoration: none;\n  color: inherit;\n  position: relative;\n}\n.lk-stay-card:hover {\n  background: #fffbf5;\n  transform: translateY(-2px);\n  box-shadow: 0 8px 24px rgba(195, 159, 118, 0.18);\n  z-index: 1;\n}\n.lk-stay-card.featured {\n  background: linear-gradient(135deg, #fffdf9 0%, #fff9f0 100%);\n  box-shadow: 0 4px 16px rgba(195, 159, 118, 0.15), inset 0 1px 0 rgba(195, 159, 118, 0.1);\n}\n.lk-stay-card.featured:hover {\n  background: linear-gradient(135deg, #fffbf5 0%, #fff8ed 100%);\n  box-shadow: 0 8px 24px rgba(195, 159, 118, 0.25), inset 0 1px 0 rgba(195, 159, 118, 0.15);\n}\n\n.lk-stay-badge {\n  display: inline-flex;\n  align-items: center;\n  gap: 5px;\n  font-size: 10px;\n  font-weight: 500;\n  letter-spacing: 1.5px;\n  text-transform: uppercase;\n  padding: 5px 11px;\n  border-radius: 20px;\n  width: fit-content;\n}\n.badge-top     { background: linear-gradient(135deg, #c39f76 0%, #d4b188 100%); color: #fff; border: 1px solid #c39f76; font-weight: 600; box-shadow: 0 2px 8px rgba(195,159,118,0.3); }\n.badge-luxury  { background: rgba(195,159,118,.12); color: #c39f76; border: 1px solid rgba(195,159,118,.25); }\n.badge-boutique{ background: rgba(54,133,252,.08); color: #3685fc; border: 1px solid rgba(54,133,252,.2); }\n.badge-nature  { background: rgba(130,190,100,.1); color: #6b9c4a; border: 1px solid rgba(130,190,100,.2); }\n.badge-remote  { background: rgba(195,159,118,.12); color: #a67e50; border: 1px solid rgba(195,159,118,.25); }\n\n.lk-stay-name {\n  font-family: 'Playfair Display', Georgia, serif;\n  font-size: 18px;\n  font-weight: 700;\n  color: #111827;\n  line-height: 1.3;\n}\n.lk-stay-desc {\n  font-size: 13.5px;\n  color: #525252;\n  line-height: 1.65;\n  font-weight: 300;\n  flex: 1;\n}\n\n.lk-stay-meta {\n  display: flex;\n  align-items: center;\n  gap: 12px;\n  flex-wrap: wrap;\n  margin-top: 4px;\n}\n.lk-stay-price {\n  font-size: 13px;\n  color: #6b7280;\n}\n.lk-stay-price strong {\n  color: #c39f76;\n  font-weight: 500;\n}\n.lk-stay-stars {\n  color: #c39f76;\n  font-size: 11px;\n  letter-spacing: 1px;\n}\n\n\/* \u2500\u2500\u2500 CTA BUTTON \u2500\u2500\u2500 *\/\n.lk-stay-cta {\n  display: inline-flex;\n  align-items: center;\n  justify-content: center;\n  gap: 7px;\n  margin-top: 8px;\n  padding: 11px 20px;\n  border-radius: 8px;\n  background: linear-gradient(135deg, #3685fc 0%, #2a6fd9 100%);\n  color: #fff;\n  font-size: 13px;\n  font-weight: 500;\n  text-decoration: none;\n  letter-spacing: .3px;\n  transition: all .2s ease;\n  cursor: pointer;\n  border: none;\n  text-align: center;\n  box-shadow: 0 4px 12px rgba(54, 133, 252, 0.25);\n}\n.lk-stay-cta:hover {\n  background: linear-gradient(135deg, #2a6fd9 0%, #1e5bc4 100%);\n  transform: translateY(-1px);\n  box-shadow: 0 6px 16px rgba(54, 133, 252, 0.35);\n}\n.lk-stay-cta svg { flex-shrink: 0; }\n\n\/* \u2500\u2500\u2500 FOOTER \u2500\u2500\u2500 *\/\n.lk-stays-footer {\n  padding: 18px 36px;\n  background: linear-gradient(to bottom, #fdfaf5 0%, #f9f4ed 100%);\n  border-top: 1px solid rgba(195, 159, 118, 0.15);\n  display: flex;\n  align-items: center;\n  justify-content: space-between;\n  flex-wrap: wrap;\n  gap: 12px;\n}\n.lk-stays-footer-note {\n  font-size: 11.5px;\n  color: #6b7280;\n  font-weight: 300;\n  line-height: 1.5;\n}\n.lk-stays-footer-note a {\n  color: #c39f76;\n  text-decoration: none;\n  font-weight: 400;\n}\n.lk-stays-footer-note a:hover {\n  text-decoration: underline;\n}\n.lk-stays-all-btn {\n  display: inline-flex;\n  align-items: center;\n  gap: 6px;\n  font-size: 12.5px;\n  font-weight: 500;\n  color: #c39f76;\n  text-decoration: none;\n  border: 1px solid rgba(195, 159, 118, 0.35);\n  padding: 8px 18px;\n  border-radius: 8px;\n  transition: all .2s ease;\n}\n.lk-stays-all-btn:hover {\n  background: rgba(195, 159, 118, 0.08);\n  border-color: rgba(195, 159, 118, 0.5);\n}\n\n\/* \u2500\u2500\u2500 RESPONSIVE \u2500\u2500\u2500 *\/\n@media (max-width: 600px) {\n  .lk-stays-grid { grid-template-columns: 1fr; }\n  .lk-stays-header { padding: 24px 20px; }\n  .lk-stays-footer { padding: 16px 20px; }\n  .lk-stay-card { padding: 22px; }\n  .lk-stays-title { font-size: 20px; }\n}\n<\/style>\n\n  <!-- HEADER -->\n  <div class=\"lk-stays-header\">\n    <img decoding=\"async\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/02\/lukas-a-lucka.jpg\" alt=\"\" style=\"width: 75px; height: 75px; border-radius: 8px; flex-shrink: 0; object-fit: cover; display: block; margin: 4px 0;\" title=\"\">\n    <div class=\"lk-stays-header-text\">\n      <div class=\"lk-stays-eyebrow\">Luk\u00e1\u0161 and Lucie recommend<\/div>\n      <div class=\"lk-stays-title\">Onde se hospedar em Wroc\u0142aw<\/div>\n      <div class=\"lk-stays-subtitle\">3 acomoda\u00e7\u00f5es \u2014 hot\u00e9is e outras op\u00e7\u00f5es de hospedagem<\/div>\n    <\/div>\n  <\/div>\n\n  <!-- CARDS -->\n  <div class=\"lk-stays-grid\">\n\n    <a class=\"lk-stay-card featured\" href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&#038;campaign=loudavymkrokemcz&#038;campaign=vratislavpolsko&#038;address=Vratislav&#038;hotelname=Legnicka+Business+Apartments&#038;search=Legnicka+Business+Apartments&#038;category=accommodation\" target=\"_blank\" rel=\"nofollow noopener\">\n      <span class=\"lk-stay-badge badge-top\">\u2b50 MELHOR ESCOLHA<\/span>\n      <span class=\"lk-stay-badge badge-nature\">\ud83c\udfe8 Hotel<\/span>\n      <div class=\"lk-stay-name\">Legnicka Business Apartments<\/div>\n      <div class=\"lk-stay-desc\">Mais barato, mas ainda assim limpo e com estilo em Wroc\u0142aw.<\/div>\n      <div class=\"lk-stay-meta\">\n        <span class=\"lk-stay-stars\">\u2605\u2605\u2605\u2605<\/span>\n        <span class=\"lk-stay-price\">Verificar pre\u00e7os<\/span>\n      <\/div>\n      <span class=\"lk-stay-cta\">\n        <svg width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg>\n        Check availability\n      <\/span>\n    <\/a>\n\n    <a class=\"lk-stay-card\" href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&#038;campaign=loudavymkrokemcz&#038;campaign=vratislavpolsko&#038;address=Vratislav&#038;hotelname=Staycity+Apartments+Sukiennice+6&#038;search=Staycity+Apartments+Sukiennice+6&#038;category=accommodation\" target=\"_blank\" rel=\"nofollow noopener\">\n      <span class=\"lk-stay-badge badge-nature\">\ud83c\udfe8 Hotel<\/span>\n      <div class=\"lk-stay-name\">Staycity Apartments Sukiennice 6<\/div>\n      <div class=\"lk-stay-desc\">Apartamentos ainda mais baratos bem no centro da cidade. Estacionamento mais caro (\u20ac18 por dia), ent\u00e3o vale mais a pena ao viajar de \u00f4nibus.<\/div>\n      <div class=\"lk-stay-meta\">\n        <span class=\"lk-stay-stars\">\u2605\u2605\u2605\u2605<\/span>\n        <span class=\"lk-stay-price\">Verificar pre\u00e7os<\/span>\n      <\/div>\n      <span class=\"lk-stay-cta\">\n        <svg width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg>\n        Check availability\n      <\/span>\n    <\/a>\n\n    <a class=\"lk-stay-card\" href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&#038;campaign=loudavymkrokemcz&#038;campaign=vratislavpolsko&#038;address=vratislav\" target=\"_blank\" rel=\"nofollow noopener\">\n      <span class=\"lk-stay-badge badge-nature\">\ud83d\udd0d Buscar<\/span>\n      <div class=\"lk-stay-name\">Ver todas as acomoda\u00e7\u00f5es em Wroc\u0142aw<\/div>\n      <div class=\"lk-stay-desc\">Explore todas as op\u00e7\u00f5es de hospedagem dispon\u00edveis em Wroc\u0142aw e encontre a melhor de acordo com suas prefer\u00eancias e or\u00e7amento.<\/div>\n      <div class=\"lk-stay-meta\">\n        <span class=\"lk-stay-stars\">\u2605\u2605\u2605\u2605<\/span>\n        <span class=\"lk-stay-price\">Comparar pre\u00e7os<\/span>\n      <\/div>\n      <span class=\"lk-stay-cta\">\n        <svg width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg>\n        Check availability\n      <\/span>\n    <\/a>\n\n  <\/div>\n\n  \n<\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"15_Fonte_Multimidia\"><\/span><span class=\"ez-toc-section\" id=\"15_Fonte_Multimedia\"><\/span>15. Fonte Multim\u00eddia<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p><strong>Logo atr\u00e1s do Sal\u00e3o do Centen\u00e1rio fica a Fonte Multim\u00eddia<\/strong>, onde voc\u00ea pode assistir a um show de luzes de gra\u00e7a. A fonte \u00e9 a maior do tipo na Pol\u00f4nia e, durante a temporada de ver\u00e3o (de maio a outubro), h\u00e1 shows todos os dias \u2013 os espet\u00e1culos noturnos s\u00e3o espetaculares gra\u00e7as aos efeitos de luz.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"RoQ2pi6s1es\"><iframe loading=\"lazy\" title=\"Centennial Hall in Wroclaw - UNESCO World Heritage Site\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/RoQ2pi6s1es?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"16_Memorial_da_Passagem_Anonima\"><\/span><span class=\"ez-toc-section\" id=\"16_Memorial_da_Passagem_Anonima\"><\/span>16. Memorial da Passagem An\u00f4nima<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Este not\u00e1vel memorial fica em um cruzamento movimentado das ruas Pi\u0142sudskiego e \u015awidnicka, ao lado da passagem Arkady. <strong>Catorze figuras de bronze em tamanho real retratam pessoas comuns que &#8220;desaparecem&#8221; no subsolo de um lado da rua e reaparecem do outro.<\/strong><\/p>\n\n<p>O memorial \u00e9 uma lembran\u00e7a simb\u00f3lica da vida durante a lei marcial, <strong>declarada na Pol\u00f4nia em 13 de dezembro de 1981.<\/strong> O mundo &#8220;subterr\u00e2neo&#8221; oculto representava a resist\u00eancia e a luta de parte da sociedade polonesa contra o regime totalit\u00e1rio.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"W7ivv5quJ7o\"><iframe loading=\"lazy\" title=\"Anonymous Passerby in Wroc\u0142aw\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/W7ivv5quJ7o?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<p>O memorial foi inaugurado exatamente 24 anos ap\u00f3s a imposi\u00e7\u00e3o da lei marcial e faz refer\u00eancia \u00e0s a\u00e7\u00f5es brutais da pol\u00edcia secreta, que prendia pessoas \u00e0 noite e as levava para a pris\u00e3o. Na inaugura\u00e7\u00e3o, ecoou a voz do general Jaruzelski e sons de tiros, rememorando a atmosfera sombria daquela \u00e9poca.<\/p>\n\n<p>As esculturas foram projetadas por <strong>Jerzy Kalina, cujos prot\u00f3tipos em gesso foram criados j\u00e1 em 1977<\/strong>. Assim, este monumento se tornou n\u00e3o apenas uma obra de arte, mas tamb\u00e9m um forte s\u00edmbolo de coragem e resili\u00eancia durante a opress\u00e3o comunista.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"17_Teleferico_Polinka\"><\/span><span class=\"ez-toc-section\" id=\"17_Telef\u00e9rico_Polinka\"><\/span>17. Telef\u00e9rico Polinka<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Wroc\u0142aw \u00e9 uma cidade de pontes \u2013 s\u00e3o mais de cem \u2013, mas tamb\u00e9m tem um telef\u00e9rico. <strong>O telef\u00e9rico Polinka foi originalmente constru\u00eddo como uma solu\u00e7\u00e3o pr\u00e1tica para os estudantes que ficavam presos no tr\u00e2nsito na ponte Grunwaldzki<\/strong>, para que pudessem se deslocar facilmente entre duas faculdades da Universidade de Ci\u00eancia e Tecnologia de Wroc\u0142aw.<\/p>\n\n<p>Hoje, no entanto, o telef\u00e9rico se tornou tamb\u00e9m uma atra\u00e7\u00e3o tur\u00edstica que oferece uma vista \u00fanica do rio Oder.<\/p>\n\n<p><strong>Os bilhetes s\u00e3o muito acess\u00edveis (cerca de 1 euro) e com esse valor voc\u00ea pode curtir uma experi\u00eancia diferente e uma vista inusitada da cidade.<\/strong><\/p>\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-4.jpg\" alt=\"Vista de Wroc\u0142aw\" class=\"wp-image-89563\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-4.jpg 1200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-4-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-4-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-4-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-4-696x464.jpg 696w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"><figcaption class=\"wp-element-caption\">Vista de Wroc\u0142aw<\/figcaption><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"18_Tour_guiado_a_pe\"><\/span><span class=\"ez-toc-section\" id=\"18_Tour_guiado_a_pe\"><\/span>18. Tour guiado a p\u00e9<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Quer descobrir curiosidades sobre Wroc\u0142aw enquanto faz um passeio com outros viajantes? <strong>Fa\u00e7a um tour guiado a p\u00e9 \u2013 h\u00e1 op\u00e7\u00f5es em ingl\u00eas e espanhol.<\/strong> Esses passeios s\u00e3o uma \u00f3tima oportunidade de conhecer a cidade pela perspectiva de guias locais apaixonados, que apresentam Wroc\u0142aw do jeito que eles mesmos a amam.<\/p>\n\n<p>Normalmente, em nossas viagens, adoramos participar de tours guiados gratuitos. \u00c9 uma forma ideal de ter uma nova perspectiva sobre a cidade e aprender mais sobre ela. Temos certeza de que isso vai ajudar voc\u00ea tamb\u00e9m a descobrir as belezas de Wroc\u0142aw.<\/p>\n\n<p>Se voc\u00ea n\u00e3o tem amigos em Wroc\u0142aw que possam mostrar a cidade, participar de um tour guiado \u00e9 com certeza a escolha certa. Os passeios acontecem em v\u00e1rios idiomas, sendo os mais comuns polon\u00eas, ingl\u00eas, alem\u00e3o e espanhol.<\/p>\n\n<p>As datas e hor\u00e1rios dispon\u00edveis dos tours guiados podem ser reservados online \u2013 \u00e9 necess\u00e1rio, pois as vagas costumam ser limitadas.<\/p>\n\n<div class=\"gyg-iframe-container\" style=\"margin-bottom:1.5em\" class=\"wp-block-cgb-block-gyg-wp-plugin\"><iframe style=\"border:0;height:100%;width:100%\" title=\"GetYourGuide activities widget\" src=\"https:\/\/widget.getyourguide.com\/default\/activities.frame?widget=wp_activities&amp;currency=CSK&amp;locale_code=en-GB&amp;number_of_items=3&amp;partner_id=MKZ64IS&amp;q=walking%20tour%20wroclaw\"><\/iframe><\/div>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"19_Experimente_a_culinaria_polonesa_tradicional\"><\/span><span class=\"ez-toc-section\" id=\"19_Experimente_a_culinaria_polonesa_tradicional\"><\/span>19. Experimente a culin\u00e1ria polonesa tradicional<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Qual a melhor forma de conhecer a cultura local? Pela comida, \u00e9 claro! <strong>Vamos dar uma olhada na culin\u00e1ria tradicional polonesa.<\/strong><\/p>\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Pierogi\"><\/span><span class=\"ez-toc-section\" id=\"Pierogi\"><\/span>Pierogi<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n<p><strong>Pierogi s\u00e3o past\u00e9is cozidos recheados e s\u00e3o, sem d\u00favida, o s\u00edmbolo da culin\u00e1ria polonesa.<\/strong> E n\u00e3o \u00e9 \u00e0 toa \u2013 s\u00e3o simplesmente deliciosos!<\/p>\n\n<p><strong>A vers\u00e3o tradicional s\u00e3o os pierogi ruskie, recheados com batata e queijo cottage.<\/strong> E se voc\u00ea acha que <strong>&#8220;ruskie&#8221; significa que v\u00eam da R\u00fassia, est\u00e1 enganado.<\/strong><\/p>\n\n<p>Esses past\u00e9is s\u00e3o poloneses e, recentemente, o nome tem sido &#8220;neutralizado&#8221;, sem o adjetivo &#8220;ruskie&#8221;. Voc\u00ea pode experimentar pierogi em v\u00e1rios lugares, mas o nosso favorito \u00e9 o <strong>Bar Piero\u017cek na rua Ksi\u0119cia J\u00f3zefa Poniatowskiego 3<\/strong>.<\/p>\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sopas_tradicionais_polonesas\"><\/span><span class=\"ez-toc-section\" id=\"Sopas_tradicionais_polonesas\"><\/span>Sopas tradicionais polonesas<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n<p>Bem-vindo ao para\u00edso das sopas! Experimente a pomidorowa (sopa de tomate), barszcz czerwony (borscht vermelho), \u017curek (sopa \u00e0 base de centeio fermentado, tradicionalmente servida dentro do p\u00e3o), grzybowa (sopa de cogumelos), ros\u00f3\u0142 (caldo) e muitas outras.<\/p>\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Entradas_e_petiscos_para_acompanhar_cerveja\"><\/span><span class=\"ez-toc-section\" id=\"Entradas_e_petiscos_para_acompanhar_cerveja\"><\/span>Entradas e petiscos para acompanhar cerveja<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n<p>Al\u00e9m dos pratos principais, recomendamos experimentar as entradas polonesas. Uma das t\u00edpicas que voc\u00ea pode provar em Wroc\u0142aw \u00e9 o Gzik. \u00c9 origin\u00e1rio da Grande Pol\u00f4nia, mas se tornou parte da culin\u00e1ria local.<\/p>\n\n<p><strong>Gzik \u00e9 um queijo cottage tradicionalmente servido com batatas cozidas. Outras recomenda\u00e7\u00f5es s\u00e3o pepinos em conserva e arenque.<\/strong> Em quase todos os card\u00e1pios voc\u00ea tamb\u00e9m encontrar\u00e1 steak tartare.<\/p>\n\n<p>Dizem que todas essas del\u00edcias ficam ainda melhores com um shot de vodka gelada. N\u00f3s n\u00e3o somos muito de carne nem \u00e1lcool, ent\u00e3o voc\u00ea vai ter que testar por n\u00f3s. Bares muito populares s\u00e3o o Ambasada e o Przedwojenna.<\/p>\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Paczki\"><\/span><span class=\"ez-toc-section\" id=\"Paczki\"><\/span>P\u0105czki<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n<p>P\u0105czki s\u00e3o uma esp\u00e9cie de sonho ou berliner \u2013 se parecem com os nossos sonhos brasileiros, mas costumam ter uma variedade maior de recheios. Um lugar muito popular para experiment\u00e1-los \u00e9 a rede Dobra P\u0105czkarnia. Para uma vers\u00e3o mais tradicional, v\u00e1 \u00e0 Cukiernia \u0141om\u017canka.<\/p>\n\n<h4 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Food_tours_em_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"Food_tours_em_Wroclaw\"><\/span>Food tours em Wroc\u0142aw<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n\n<p>Em Wroc\u0142aw tamb\u00e9m s\u00e3o organizados tours gastron\u00f4micos, durante os quais voc\u00ea pode experimentar a culin\u00e1ria local \u2013 e geralmente inclui uma degusta\u00e7\u00e3o de vodka. A melhor forma de encontr\u00e1-los \u00e9 pelo <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"GetYourGuide\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/getyourguide\/\" data-shortcode=\"true\">GetYourGuide<\/a>.<\/strong> L\u00e1 voc\u00ea pode reservar com anteced\u00eancia (e, caso precise, cancelar online).<\/p>\n\n<div class=\"gyg-iframe-container\" style=\"margin-bottom:1.5em\" class=\"wp-block-cgb-block-gyg-wp-plugin\"><iframe style=\"border:0;height:100%;width:100%\" title=\"GetYourGuide activities widget\" src=\"https:\/\/widget.getyourguide.com\/default\/activities.frame?widget=wp_activities&amp;currency=CSK&amp;locale_code=en-GB&amp;number_of_items=3&amp;partner_id=MKZ64IS&amp;q=wroclaw%20food\"><\/iframe><\/div>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"20_Feiras_de_pulgas\"><\/span><span class=\"ez-toc-section\" id=\"20_Feiras_de_pulgas\"><\/span>20. Feiras de pulgas<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Dizem que nas feiras de pulgas o tempo parou e voc\u00ea pode vivenciar como Wroc\u0142aw era h\u00e1 20 anos. As feiras de pulgas mais populares s\u00e3o: Targowisko na \u015awiebodzkim e Targowisko M\u0141YN.<\/p>\n\n<p>Se voc\u00ea quer algo diferente das atra\u00e7\u00f5es tur\u00edsticas habituais, recomendamos visitar uma dessas feiras no domingo de manh\u00e3.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"21_Bar_do_Harry_Potter_%E2%80%93_Pod_Trzema_Miotlami\"><\/span><span class=\"ez-toc-section\" id=\"21_Bar_do_Harry_Potter_Pod_Trzema_Miotlami\"><\/span>21. Bar do Harry Potter \u2013 Pod Trzema Miot\u0142ami<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea \u00e9 f\u00e3 de Harry Potter, n\u00e3o deixe de visitar o encantador bar Pod Trzema Miot\u0142ami (Sob as Tr\u00eas Vassouras), <strong>onde voc\u00ea pode vivenciar a atmosfera do mundo bruxo<\/strong> e tomar a tradicional bebida potteriana \u2013 a cerveja amanteigada.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"22_Antigo_cemiterio_judaico\"><\/span><span class=\"ez-toc-section\" id=\"22_Antigo_cemiterio_judaico\"><\/span>22. Antigo cemit\u00e9rio judaico<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Um mundo esquecido de classicismo, art nouveau e s\u00edmbolos misteriosos. O antigo cemit\u00e9rio judaico \u00e9 literalmente uma galeria de arte a c\u00e9u aberto. Mais de 12.000 l\u00e1pides contam as hist\u00f3rias de m\u00e9dicos ilustres, artistas e pessoas comuns que morreram repentinamente em suas jornadas.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"23_Hydropolis\"><\/span><span class=\"ez-toc-section\" id=\"23_Hydropolis\"><\/span>23. Hydropolis<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>O que a ponte Grunwaldzki, as profundezas do mar e uma gota de chuva t\u00eam em comum? A resposta est\u00e1 no Hydropolis, o \u00fanico museu da \u00e1gua na Pol\u00f4nia. <strong>A exposi\u00e7\u00e3o interativa leva voc\u00ea do cosmos, passando pelos oceanos, at\u00e9 a torneira da sua cozinha.<\/strong> Quer brincar de deus e controlar uma &#8220;impressora de \u00e1gua&#8221;? Aqui voc\u00ea pode.<\/p>\n\n<p>B\u00f4nus: o pr\u00f3prio edif\u00edcio \u00e9 uma antiga esta\u00e7\u00e3o de tratamento de \u00e1gua, ent\u00e3o a hist\u00f3ria est\u00e1 em cada canto.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"rQmFC_4I9SI\"><iframe loading=\"lazy\" title=\"Film informacyjny o Hydropolis\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/rQmFC_4I9SI?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"24_Conjunto_habitacional_WuWa\"><\/span><span class=\"ez-toc-section\" id=\"24_Conjunto_habitacional_WuWa\"><\/span>24. <strong>Conjunto habitacional WuWa<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Um conjunto habitacional experimental de 1929, onde arquitetos testaram o futuro da moradia. Casas pr\u00e9-fabricadas, espa\u00e7os comuns e at\u00e9 uma creche em meio ao verde. \u00c9 um lugar ideal para um passeio para quem quer ver como era a &#8220;modernidade&#8221; h\u00e1 cem anos. E se cansar de explorar, pare no caf\u00e9 WuWa para tomar um caf\u00e9.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"25_Sky_Tower_%E2%80%93_o_edificio_mais_alto_de_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"25_Sky_Tower_o_edificio_mais_alto_de_Wroclaw\"><\/span>25. <strong>Sky Tower \u2013 o edif\u00edcio mais alto de Wroc\u0142aw<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Suba at\u00e9 o 49\u00ba andar do Sky Tower e aprecie a vista de toda a cidade e muito al\u00e9m. Este monstro de 206 metros de altura divide opini\u00f5es entre os moradores \u2013 uns amam, outros preferiam que fosse demolido. Mas uma coisa \u00e9 certa: a vista \u00e9 imbat\u00edvel. E j\u00e1 que estiver l\u00e1, pode aproveitar para fazer compras ou visitar a galeria dentro do edif\u00edcio.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"OPXgxzdI_us\"><iframe loading=\"lazy\" title=\"Wroclaw #11 - Sky Tower \/ Discover Your Roots\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/OPXgxzdI_us?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"26_Fosso_da_cidade\"><\/span><span class=\"ez-toc-section\" id=\"26_Fosso_da_cidade\"><\/span>26. <strong>Fosso da cidade<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>O fosso da cidade de Wroc\u0142aw \u00e9 um pitoresco remanescente das fortifica\u00e7\u00f5es urbanas do s\u00e9culo XIII. Originalmente servia como prote\u00e7\u00e3o contra inimigos; hoje \u00e9 um o\u00e1sis de tranquilidade no meio da cidade pulsante. A melhor forma de apreci\u00e1-lo \u00e9 passeando pelo Cal\u00e7ad\u00e3o da Cidade Velha, que o circunda.<\/p>\n\n<p><strong>O fosso foi preservado gra\u00e7as a Jer\u00f4nimo Bonaparte, irm\u00e3o de Napole\u00e3o, que ap\u00f3s a conquista de Wroc\u0142aw em 1807 ordenou a demoli\u00e7\u00e3o das muralhas e a entrega do espa\u00e7o aos moradores.<\/strong> Caminhar por aqui significa n\u00e3o apenas relaxar, mas tamb\u00e9m dar uma espiada na hist\u00f3ria da cidade. Nos meses mais quentes, voc\u00ea pode descansar sob as \u00e1rvores, enquanto no inverno a superf\u00edcie da \u00e1gua transforma a regi\u00e3o em um cen\u00e1rio de conto de fadas.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"27_Colina_dos_Partisanos\"><\/span><span class=\"ez-toc-section\" id=\"27_Colina_dos_Partisanos\"><\/span>27. <strong>Colina dos Partisanos<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>A Colina dos Partisanos, conhecida tamb\u00e9m como Wzg\u00f3rze Partyzant\u00f3w, \u00e9 um dos lugares mais rom\u00e2nticos de Wroc\u0142aw. Fica pr\u00f3xima ao fosso da cidade e \u00e9 um \u00f3timo lugar para quem busca tranquilidade, vistas bonitas e um toque de hist\u00f3ria. A colina, originalmente parte das fortifica\u00e7\u00f5es da cidade, se transformou em \u00e1rea de lazer no s\u00e9culo XIX, quando havia um restaurante com gazebo cercado de verde.<\/p>\n\n<p>Hoje, voc\u00ea encontra restos de uma colunata neocl\u00e1ssica e de um pavilh\u00e3o, que d\u00e3o ao lugar uma atmosfera nost\u00e1lgic<strong>a. \u00c9 o lugar ideal para um piquenique ou descanso ap\u00f3s um longo dia explorando a cidade.<\/strong> Do topo da colina, abre-se uma bela vista do centro hist\u00f3rico de Wroc\u0142aw, tornando-o um destino popular para passeios rom\u00e2nticos ou para contemplar o p\u00f4r do sol.<\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"youtube-embed\" data-video_id=\"Rh1BMSbOJlo\"><iframe loading=\"lazy\" title=\"Bastion Sakwowy - Wroc\u0142aw - Wzg\u00f3rze Partyzant\u00f3w\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/Rh1BMSbOJlo?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"28_Mirante_da_torre_da_Basilica_de_Santa_Isabel\"><\/span><span class=\"ez-toc-section\" id=\"28_Mirante_da_torre_da_Basilica_de_Santa_Isabel\"><\/span>28. Mirante da torre da <strong>Bas\u00edlica de Santa Isabel<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea quer ver Wroc\u0142aw de uma perspectiva totalmente diferente, suba a um dos mirantes da Cidade Velha. Um dos mais famosos \u00e9 a <strong>torre da Bas\u00edlica de Santa Isabel<\/strong>, que se ergue a 90 metros de altura. At\u00e9 o topo, voc\u00ea sobe por uma escada espiral estreita, mas a vista que espera l\u00e1 em cima vale cada gota de suor. Voc\u00ea ver\u00e1 os ic\u00f4nicos telhados vermelhos da Cidade Velha, o sinuoso rio Oder e o panorama da cidade que vai te deixar sem f\u00f4lego.<\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wroclaw_Mapa_com_pontos_de_interesse_para_o_celular\"><\/span><span class=\"ez-toc-section\" id=\"Wroclaw_Mapa_com_pontos_de_interesse_para_o_celular\"><\/span>Wroc\u0142aw: Mapa com pontos de interesse para o celular<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n<p><strong>Salve o mapa dos melhores lugares de Wroc\u0142aw direto no celular.<\/strong>&nbsp;Ap\u00f3s a compra, voc\u00ea receber\u00e1 um link para um Google Maps privado, que pode salvar clicando em &#8220;Seguir\/Follow&#8221;. Assim ele ser\u00e1 copiado para sua conta Google e aparecer\u00e1 em todos os dispositivos onde voc\u00ea usa o Google Maps.<\/p>\n\n\n<div style=\"gap: 20px;\" class=\"align-button-center ub-buttons orientation-button-row ub-flex-wrap wp-block-ub-button\" id=\"ub-button-ebbbcb4d-d9a3-4580-8fb5-83063885364c\"><div class=\"ub-button-container\">\n\t\t\t<a href=\"https:\/\/form.simpleshop.cz\/jDo4V\/\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"ub-button-block-main   ub-button-flex\" role=\"button\" style=\"--ub-button-background-color: #cf2e2e; --ub-button-color: #ffffff; --ub-button-border: none; --ub-button-hover-background-color: #313131; --ub-button-hover-color: #ffffff; --ub-button-hover-border: none; font-size: 25px; padding-top: 10px; padding-right: 10px; padding-bottom: 10px; padding-left: 10px; border-top-left-radius: 10px;; border-top-right-radius: 10px;; border-bottom-left-radius: 10px;; border-bottom-right-radius: 10px;; \">\n\t\t\t\t<div class=\"ub-button-content-holder\" style=\"flex-direction: row\">\n\t\t\t\t\t<span class=\"ub-button-block-btn\">Baixar o mapa dos melhores lugares de Wroc\u0142aw<br>(pre\u00e7o de um \u2615)<\/span>\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\t\t<\/div><\/div>\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"29_Mirante_da_Ponte_dos_Penitentes\"><\/span><span class=\"ez-toc-section\" id=\"29_Mirante_da_Ponte_dos_Penitentes\"><\/span>29. Mirante da Ponte dos Penitentes<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Para uma experi\u00eancia um pouco diferente, v\u00e1 at\u00e9 a <strong>Ponte dos Penitentes<\/strong>, que conecta as duas torres da Igreja de Santa Maria Madalena. Fica a 45 metros de altura e oferece uma vista fascinante da pra\u00e7a, dos edif\u00edcios hist\u00f3ricos e das ruelas abaixo. Segundo a lenda, almas de pecadoras arrependidas caminham por ali em busca de perd\u00e3o.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"30_Melhores_cafes_em_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"30_Melhores_cafes_em_Wroclaw\"><\/span>30. Melhores caf\u00e9s em Wroc\u0142aw<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Se voc\u00ea ama caf\u00e9 tanto quanto n\u00f3s, com certeza deveria visitar algum dos caf\u00e9s locais. Os que mais gostamos foram o <strong>Parrot Coffee<\/strong>, o <strong>Jolie \u2013 Brasserie Cafe<\/strong>, que tem brunches incr\u00edveis, e o <strong>Yerba Caf\u00e9<\/strong>, onde recomendamos pelo menos um caf\u00e9 da manh\u00e3.<\/p>\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"31_Melhores_restaurantes_em_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"31_Melhores_restaurantes_em_Wroclaw\"><\/span>31. Melhores restaurantes em Wroc\u0142aw<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n<p>Para quem ama comida indiana, tem o <strong>Indieflavours<\/strong>, que agrada praticamente todo mundo. Em Wroc\u0142aw tamb\u00e9m h\u00e1 o bom restaurante tcheco <strong>Bernard<\/strong>, e bem no Rynek fica o estiloso restaurante polon\u00eas <strong>Pierogarnia Rynek 26<\/strong>.<\/p>\n\n<p>Sempre tento incluir nos artigos dicas de restaurantes para vegetarianos e veganos, pois sei como \u00e0s vezes \u00e9 dif\u00edcil encontrar comida de verdade. Mas em Wroc\u0142aw voc\u00ea n\u00e3o ter\u00e1 esse problema \u2013 h\u00e1 um <strong>\u00f3timo restaurante vegano chamado &#8220;Bez Lukru&#8221; Kuchnia Ro\u015blinna.<\/strong><\/p>\n\n<p><em>Antes de sair por Wroc\u0142aw ca\u00e7ando an\u00f5es, experimentando pierogi e atravessando dezenas de pontes sobre o Oder, \u00e9 bom pensar tamb\u00e9m nas quest\u00f5es pr\u00e1ticas. Mesmo a Pol\u00f4nia fazendo parte da Uni\u00e3o Europeia, imprevistos acontecem em qualquer viagem. Desde mala extraviada at\u00e9 um problema de sa\u00fade no zool\u00f3gico. Por isso, vale a pena ter um bom seguro viagem contratado antes de embarcar. Brasileiros precisam de seguro viagem para entrar na \u00e1rea Schengen, ent\u00e3o n\u00e3o deixe de providenciar o seu. Assim, voc\u00ea pode explorar Wroc\u0142aw com tranquilidade e sem preocupa\u00e7\u00f5es desnecess\u00e1rias.<\/em><\/p>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Perguntas_frequentes\"><\/span><span class=\"ez-toc-section\" id=\"Perguntas_frequentes\"><\/span>Perguntas frequentes<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1731601425708\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"O_que_fazer_com_criancas_em_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"O_que_fazer_com_criancas_em_Wroclaw\"><\/span>O que fazer com crian\u00e7as em Wroc\u0142aw?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Com crian\u00e7as, v\u00e1 ao Zool\u00f3gico, colecione &#8220;an\u00f5es&#8221; pela cidade, ande de telef\u00e9rico e visite o museu da \u00e1gua \u2013 Hydropolis.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1731601479990\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"O_que_fazer_em_Wroclaw_quando_chove\"><\/span><span class=\"ez-toc-section\" id=\"O_que_fazer_em_Wroclaw_quando_chove\"><\/span>O que fazer em Wroc\u0142aw quando chove?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Visite o museu <strong><a href=\"https:\/\/openheim.org\/en\/#all\" target=\"_blank\" rel=\"noreferrer noopener\">OP ENHEIM<\/a><\/strong>, o museu nacional ou o bar tem\u00e1tico de Harry Potter.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1731601570895\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Quantos_dias_ficar_em_Wroclaw\"><\/span><span class=\"ez-toc-section\" id=\"Quantos_dias_ficar_em_Wroclaw\"><\/span>Quantos dias ficar em Wroc\u0142aw?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Na nossa opini\u00e3o, a cidade \u00e9 ideal para um feriad\u00e3o prolongado, ou seja, cerca de 3 dias.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Venha conhecer Wroc\u0142aw conosco e descubra que a Pol\u00f4nia tem muito a oferecer: monumentos deslumbrantes, um bar tem\u00e1tico de Harry Potter, an\u00f5es espalhados pela cidade e dicas de hot\u00e9is.<\/p>\n","protected":false},"author":3,"featured_media":89555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"Wroc\u0142aw Pol\u00f4nia: 31 Dicas do Que Ver e Fazer","rank_math_description":"Descubra Wroc\u0142aw, Pol\u00f4nia: 31 dicas imperd\u00edveis de pontos tur\u00edsticos, restaurantes, caf\u00e9s e hot\u00e9is. Planeje sua viagem agora!","rank_math_focus_keyword":"wroc\u0142aw pol\u00f4nia","rank_math_seo_score":""},"categories":[1121,1104,1145],"tags":[],"class_list":{"0":"post-143345","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europa","8":"category-nao-categorizado","9":"category-polonia"},"featured_image_src":"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2024\/11\/wroclaw-2-1.jpg","author_info":{"display_name":"Lucie Kone\u010dn\u00e1","author_link":"https:\/\/loudavymkrokem.cz\/pt-br\/author\/lucie-konecna\/"},"_links":{"self":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/comments?post=143345"}],"version-history":[{"count":1,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143345\/revisions"}],"predecessor-version":[{"id":146305,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143345\/revisions\/146305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/media\/89555"}],"wp:attachment":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/media?parent=143345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/categories?post=143345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/tags?post=143345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}