{"id":143130,"date":"2019-05-19T01:55:18","date_gmt":"2019-05-18T23:55:18","guid":{"rendered":"https:\/\/loudavymkrokem.cz\/?p=143130"},"modified":"2026-04-02T16:13:00","modified_gmt":"2026-04-02T14:13:00","slug":"ruinas-calakmul-mexico","status":"publish","type":"post","link":"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/","title":{"rendered":"Calakmul: Ru\u00ednas Maias na Selva do M\u00e9xico"},"content":{"rendered":"<p>Calakmul no M\u00e9xico \u00e9 uma antiga cidade maia situada no meio da selva impenetr\u00e1vel, no cora\u00e7\u00e3o da Pen\u00ednsula de Yucat\u00e1n. Apenas um punhado de turistas e aventureiros se aventura at\u00e9 l\u00e1, e isso torna a experi\u00eancia ainda mais inesquec\u00edvel.<\/p>\n<p>A cidade est\u00e1 localizada dentro de uma reserva da biosfera protegida pela UNESCO, e o pr\u00f3prio s\u00edtio arqueol\u00f3gico de Calakmul \u00e9 Patrim\u00f4nio Mundial da UNESCO.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Obsah \u010dl\u00e1nku<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Caminho_ate_as_ruinas_de_Calakmul\" >Caminho at\u00e9 as ru\u00ednas de Calakmul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#A_antiga_cidade_de_Calakmul\" >A antiga cidade de Calakmul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Historia_da_cidade_de_Calakmul\" >Hist\u00f3ria da cidade de Calakmul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#O_que_voce_vera_nas_ruinas_de_Calakmul\" >O que voc\u00ea ver\u00e1 nas ru\u00ednas de Calakmul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Onde_se_hospedar_perto_de_Calakmul\" >Onde se hospedar perto de Calakmul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Mapa_das_ruinas_de_Calakmul\" >Mapa das ru\u00ednas de Calakmul<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Dicas_para_viajar_pelo_Mexico\" >Dicas para viajar pelo M\u00e9xico<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#O_que_levar_na_mala\" >O que levar na mala<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Onde_encontrar_passagens_aereas\" >Onde encontrar passagens a\u00e9reas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Aluguel_de_carro\" >Aluguel de carro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Reserva_de_hospedagem\" >Reserva de hospedagem<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Nao_esqueca_do_seguro_viagem\" >N\u00e3o esque\u00e7a do seguro viagem<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Guia_que_recomendamos_Lonely_Planet_Yucatan\" >Guia que recomendamos: Lonely Planet Yucatan<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/ruinas-calakmul-mexico\/#Outros_artigos_sobre_Yucatan_que_voce_vai_gostar\" >Outros artigos sobre Yucat\u00e1n que voc\u00ea vai gostar<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Caminho_ate_as_ruinas_de_Calakmul\"><\/span><span class=\"ez-toc-section\" id=\"Caminho_ate_as_ruinas_de_Calakmul\"><\/span>Caminho at\u00e9 as ru\u00ednas de Calakmul<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Explorar essa cidade imensa n\u00e3o \u00e9 tarefa simples. As ru\u00ednas ficam a 60 quil\u00f4metros da estrada asfaltada mais pr\u00f3xima, e a partir da cidade mais pr\u00f3xima, Xpujil, a viagem leva mais de duas horas. O pr\u00f3prio Xpujil fica a seis horas ao sul do resort de Canc\u00fan, ent\u00e3o s\u00f3 chega at\u00e9 Calakmul quem decide percorrer toda a pen\u00ednsula. Para quem sai do Brasil, o mais comum \u00e9 voar at\u00e9 Canc\u00fan com conex\u00e3o na Cidade do M\u00e9xico ou nos Estados Unidos, e de l\u00e1 seguir de carro alugado pela regi\u00e3o.<\/p>\n<p>As ru\u00ednas ficam praticamente na fronteira entre o M\u00e9xico e a Guatemala.<\/p>\n<figure id=\"attachment_54894\" aria-describedby=\"caption-attachment-54894\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54894\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/cesta-skrze-dzungli.jpg\" alt=\"Trilha pela selva at\u00e9 as ru\u00ednas de Calakmul\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54894\" class=\"wp-caption-text\">\u00c9 por trilhas como essas que voc\u00ea caminha pela selva<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"A_antiga_cidade_de_Calakmul\"><\/span><span class=\"ez-toc-section\" id=\"A_antiga_cidade_de_Calakmul\"><\/span>A antiga cidade de Calakmul<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Estima-se que, no auge de sua gl\u00f3ria, essa cidade central de toda a regi\u00e3o abrigava at\u00e9 50 mil maias. Como pouqu\u00edssimos turistas visitam o local, praticamente n\u00e3o existem restri\u00e7\u00f5es dentro do complexo.<\/p>\n<p>Isso significa que voc\u00ea pode subir em todas as estruturas que encontrar, incluindo as duas pir\u00e2mides gigantescas. A maior delas tem 45 metros de altura e \u00e9 a segunda maior pir\u00e2mide maia j\u00e1 descoberta.<\/p>\n<p>Na \u00e1rea, existem 117 chamadas estelas \u2014 grandes blocos de pedra esculpidos em formato retangular, nos quais est\u00e3o representados eventos importantes e governantes. Algumas delas ainda conservam a pintura vermelha original!<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Historia_da_cidade_de_Calakmul\"><\/span><span class=\"ez-toc-section\" id=\"Historia_da_cidade_de_Calakmul\"><\/span>Hist\u00f3ria da cidade de Calakmul<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54891\" aria-describedby=\"caption-attachment-54891\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54891\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/struktura-1-calakmul.jpg\" alt=\"Estrutura n\u00ba 1, uma das duas pir\u00e2mides centrais de Calakmul\" width=\"1200\" height=\"900\" title=\"\"><figcaption id=\"caption-attachment-54891\" class=\"wp-caption-text\">Estrutura n\u00ba 1, at\u00e9 hoje a segunda maior pir\u00e2mide maia descoberta<\/figcaption><\/figure>\n<p>A cidade existiu ao longo de doze s\u00e9culos, de 500 a.C. at\u00e9 900 d.C. Fazia parte de uma coaliz\u00e3o de quatro cidades, sendo a mais importante delas. A coaliz\u00e3o vivia em constante guerra com seus vizinhos do sul, e os ataques mais frequentes vinham da cidade de Tikal.<\/p>\n<p>Em seu per\u00edodo de maior atividade, a cidade e seus arredores imediatos contavam com mais de 6.700 constru\u00e7\u00f5es, ocupando uma \u00e1rea de 70 quil\u00f4metros quadrados.<\/p>\n<p>O Reino de Calakmul (sob a influ\u00eancia do governante de Calakmul) englobava outros 20 centros urbanos, que juntos somavam cerca de 200 mil habitantes.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"O_que_voce_vera_nas_ruinas_de_Calakmul\"><\/span><span class=\"ez-toc-section\" id=\"O_que_voce_vera_nas_ruinas_de_Calakmul\"><\/span>O que voc\u00ea ver\u00e1 nas ru\u00ednas de Calakmul<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54892\" aria-describedby=\"caption-attachment-54892\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54892\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/struktura-2-calakmul.jpg\" alt=\"Estrutura n\u00ba 2, a segunda maior pir\u00e2mide maia j\u00e1 descoberta\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54892\" class=\"wp-caption-text\">Estrutura n\u00ba 1, uma das duas pir\u00e2mides centrais<\/figcaption><\/figure>\n<p>Essas ru\u00ednas s\u00e3o as mais extensas de toda a Pen\u00ednsula de Yucat\u00e1n, e voc\u00ea pode facilmente passar v\u00e1rias horas explorando o local.<\/p>\n<p><strong>No centro da cidade<\/strong>, que cobre aproximadamente dois quil\u00f4metros quadrados, encontramos restos de cerca de 1.000 estruturas diferentes. Essa \u00e9 a \u00fanica \u00e1rea aberta ao p\u00fablico. O restante ainda est\u00e1 coberto pela selva, embora as localiza\u00e7\u00f5es de todas as 6.200 estruturas estejam detalhadamente mapeadas.<\/p>\n<p>Os reservat\u00f3rios de \u00e1gua nos arredores de Calakmul s\u00e3o enormes. Aqui se encontra o maior reservat\u00f3rio artificial de \u00e1gua maia j\u00e1 descoberto. Ele mede 242 metros de largura e 212 metros de comprimento.<\/p>\n<p><strong>A Estrutura n\u00ba 1<\/strong>, como \u00e9 chamada sem muita criatividade a primeira das duas grandes pir\u00e2mides, foi constru\u00edda sobre uma colina suave. \u00c0 primeira vista, parece ser mais alta que a segunda pir\u00e2mide, embora n\u00e3o seja.<\/p>\n<p><strong>A Estrutura n\u00ba 2<\/strong> \u00e9, em volume, a maior pir\u00e2mide maia j\u00e1 descoberta. Sua base mede 120 metros quadrados e tem 45 metros de altura. Assim como outras pir\u00e2mides encontradas, ela come\u00e7ou como uma pir\u00e2mide pequena, que os governantes foram ampliando gradualmente at\u00e9 chegar \u00e0 forma atual.<\/p>\n<p>As estradas de pedra maias chamadas <strong>sacbes<\/strong> eram importantes vias de transporte, e nos arredores de Calakmul existem oito delas. Duas est\u00e3o mapeadas, tr\u00eas est\u00e3o parcialmente descobertas e as demais s\u00e3o conhecidas apenas por levantamentos a\u00e9reos. Essas estradas percorriam todo o reino e tamb\u00e9m conectavam Calakmul com seus inimigos. A estrada mais longa documentada, que ligava Calakmul a El Mirador e El Tintal, tem 68 quil\u00f4metros.<\/p>\n<p>Para uma descri\u00e7\u00e3o mais detalhada da hist\u00f3ria, recomendamos a fonte em ingl\u00eas <strong><a href=\"https:\/\/www.locogringo.com\/mexico\/ways-to-play\/mayan-ruins-archaeological-sites\/calakmul-ruins\/\" target=\"_blank\" rel=\"noopener noreferrer\">Loco Gringo<\/a><\/strong>.<\/p>\n<figure id=\"attachment_54893\" aria-describedby=\"caption-attachment-54893\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54893\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/struktury-v-ruinach-calakmul.jpg\" alt=\"Estruturas nas ru\u00ednas de Calakmul\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54893\" class=\"wp-caption-text\">Andar pelas pir\u00e2mides n\u00e3o \u00e9 f\u00e1cil \u2014 s\u00e3o estruturas realmente massivas<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"Onde_se_hospedar_perto_de_Calakmul\"><\/span><span class=\"ez-toc-section\" id=\"Onde_se_hospedar_perto_de_Calakmul\"><\/span><strong>Onde se hospedar perto de Calakmul<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>As ru\u00ednas ficam longe de tudo, ent\u00e3o recomendamos pernoitar na pacata cidadezinha de Xpujil e no dia seguinte visitar as ru\u00ednas de Becan, que ficam a apenas dez minutos dali.<\/p>\n<p>Percorremos a cidade de ponta a ponta e, com toda a tranquilidade, podemos recomendar apenas um hotelzinho. O <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"Hotel Villa Calakmul\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hotel-villa-calakmul\/\" data-shortcode=\"true\">Hotel Villa Calakmul<\/a><\/strong> custa cerca de 20 \u20ac por noite e o propriet\u00e1rio \u00e9 muito atencioso. Os quartos s\u00e3o limpos, h\u00e1 caf\u00e9 dispon\u00edvel na recep\u00e7\u00e3o e a internet funciona bem. Pelo que vimos, n\u00e3o d\u00e1 para dizer o mesmo dos outros alojamentos em Xpujil.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mapa_das_ruinas_de_Calakmul\"><\/span><span class=\"ez-toc-section\" id=\"Mapa_das_ruinas_de_Calakmul\"><\/span>Mapa das ru\u00ednas de Calakmul<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54898\" aria-describedby=\"caption-attachment-54898\" style=\"width: 740px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54898\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/calakmul-mapa.jpg\" alt=\"Mapa da cidade de Calakmul\" width=\"740\" height=\"504\" title=\"\"><figcaption id=\"caption-attachment-54898\" class=\"wp-caption-text\">Mapa da cidade de Calakmul<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"Dicas_para_viajar_pelo_Mexico\"><\/span><span class=\"ez-toc-section\" id=\"Dicas_para_viajar_pelo_Mexico\"><\/span>Dicas para viajar pelo M\u00e9xico<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table border=\"2\">\n<tbody>\n<tr>\n<td style=\"width: 865px;\">\n<h3><span class=\"ez-toc-section\" id=\"O_que_levar_na_mala\"><\/span><span style=\"font-size: 18pt;\"><strong>O que levar na mala<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Confira nosso <a href=\"https:\/\/loudavymkrokem.cz\/vybaveni-na-cesty\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>guia de bagagem para viagens<\/strong><\/a>, que vai ajudar voc\u00ea nos preparativos. Escolha a mochila certa, veja dicas de acess\u00f3rios \u00fateis e n\u00e3o esque\u00e7a nada importante em casa.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_encontrar_passagens_aereas\"><\/span><span style=\"font-size: 18pt;\"><strong>Onde encontrar passagens a\u00e9reas<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Procure passagens baratas no <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"Kiwi\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/kiwi\/\" data-shortcode=\"true\">Kiwi<\/a><\/strong>, que \u00e9 nosso buscador favorito. Do Brasil, voc\u00ea pode voar para Canc\u00fan com conex\u00e3o na Cidade do M\u00e9xico ou nos EUA. N\u00e3o deixe de ler nosso <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143120\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>guia de como encontrar passagens baratas<\/strong><\/a>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Aluguel_de_carro\"><\/span><span style=\"font-size: 18pt;\"><strong>Aluguel de carro<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Normalmente usamos o comparador <strong><a class=\"thirstylink\" title=\"RentalCars.com\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/rentalcars-com\/\" target=\"_blank\" rel=\"nofollow\" data-shortcode=\"true\">RentalCars.com<\/a><\/strong>, que nos ajuda a escolher a melhor op\u00e7\u00e3o. Em Playa del Carmen, tente entrar em contato pelo site <strong><a href=\"http:\/\/everythingplayadelcarmen.com\" target=\"_blank\" rel=\"noopener noreferrer\">everythingplayadelcarmen.org<\/a><\/strong> \u2014 o Sergio cuida de tudo para voc\u00ea.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Reserva_de_hospedagem\"><\/span><span style=\"font-size: 18pt;\"><strong>Reserva de hospedagem<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"Booking.com\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/booking-com\/\" data-shortcode=\"true\">Booking.com<\/a><\/strong> \u00e9 nosso buscador de hot\u00e9is favorito. Sempre comparamos os hot\u00e9is com as op\u00e7\u00f5es de apartamentos e quartos no <strong><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"AirBNB\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/airbnb\/\" data-shortcode=\"true\">Airbnb<\/a><\/strong>. Leia tamb\u00e9m nosso guia sobre <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143121\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>como encontrar hospedagem barata<\/strong><\/a>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Nao_esqueca_do_seguro_viagem\"><\/span><span style=\"font-size: 18pt;\"><strong>N\u00e3o esque\u00e7a do seguro viagem<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Seguro viagem<\/strong> \u00e9 absolutamente indispens\u00e1vel. Para viagens mais curtas, escolhemos a AXA (<a class=\"thirstylink\" title=\"Axa cestovn\u00ed poji\u0161t\u011bn\u00ed\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/axa-cestovni-pojisteni\/\" target=\"_blank\" rel=\"nofollow\" data-shortcode=\"true\"><strong>50% de desconto<\/strong><\/a>) e para viagens mais longas, a seguradora brit\u00e2nica <strong><a class=\"thirstylink\" title=\"True Traveller\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/true-traveller\/\" target=\"_blank\" rel=\"nofollow\" data-shortcode=\"true\">True Traveller<\/a><\/strong>. Confira nossa <strong><a href=\"https:\/\/loudavymkrokem.cz\/nejlepsi-cestovni-pojisteni\/\" target=\"_blank\" rel=\"noopener noreferrer\">compara\u00e7\u00e3o de seguradoras<\/a><\/strong> e escolha a que melhor atende suas necessidades.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Guia_que_recomendamos_Lonely_Planet_Yucatan\"><\/span><strong>Guia que recomendamos<\/strong>: <a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"Lonely Planet Yucatan\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/lonely-planet-yucatan\/\" data-shortcode=\"true\">Lonely Planet Yucatan<\/a><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2><\/h2>\n<h2 style=\"text-align: center;\"><span class=\"ez-toc-section\" id=\"Outros_artigos_sobre_Yucatan_que_voce_vai_gostar\"><\/span><span class=\"ez-toc-section\" id=\"Outros_artigos_sobre_Yucatan_que_voce_vai_gostar\"><\/span>Outros artigos sobre Yucat\u00e1n que voc\u00ea vai gostar<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143124\">Cob\u00e1: Descobrindo ru\u00ednas maias em Yucat\u00e1n<\/a><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/playa-del-carmen-mexico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Guia completo de Playa del Carmen<\/a><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143122\" target=\"_blank\" rel=\"noopener noreferrer\">O que fazer em Tulum? 12 coisas imperd\u00edveis<\/a><\/strong><\/span><\/p>\n<p class=\"entry-title\" style=\"text-align: center;\"><span style=\"font-size: 18pt;\"><strong><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143125\" rel=\"bookmark\">Chich\u00e9n Itz\u00e1: Ru\u00ednas maias e maravilha do mundo<\/a><\/strong><\/span><\/p>\n<p class=\"entry-title\" style=\"text-align: center;\"><strong><span style=\"font-size: 18pt;\"><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143126\" rel=\"bookmark\">Lagoa Bacalar: 8 coisas para fazer + onde comer<\/a><\/span><\/strong><\/p>\n<p class=\"entry-title page-title\" style=\"text-align: center;\"><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143128\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"font-size: 18pt;\">10 dicas do que fazer em San Francisco de Campeche<\/span><\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Calakmul \u00e9 uma antiga cidade maia escondida no cora\u00e7\u00e3o da selva da Pen\u00ednsula de Yucat\u00e1n, no M\u00e9xico. Poucos turistas chegam at\u00e9 l\u00e1, o que torna a experi\u00eancia ainda mais especial \u2014 com pir\u00e2mides gigantes, estelas esculpidas e uma atmosfera \u00fanica de aventura.<\/p>\n","protected":false},"author":2,"featured_media":54891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"Calakmul M\u00e9xico: Ru\u00ednas Maias na Selva de Yucat\u00e1n","rank_math_description":"Descubra Calakmul no M\u00e9xico: ru\u00ednas maias escondidas na selva de Yucat\u00e1n. Veja como chegar, o que visitar e onde se hospedar. Confira o guia completo!","rank_math_focus_keyword":"calakmul m\u00e9xico","rank_math_seo_score":""},"categories":[1125,1142],"tags":[],"class_list":{"0":"post-143130","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-america-do-norte","8":"category-mexico"},"featured_image_src":"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2019\/05\/struktura-1-calakmul.jpg","author_info":{"display_name":"Luk\u00e1\u0161 Kone\u010dn\u00fd","author_link":"https:\/\/loudavymkrokem.cz\/pt-br\/author\/lukas-konecny\/"},"_links":{"self":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/comments?post=143130"}],"version-history":[{"count":1,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143130\/revisions"}],"predecessor-version":[{"id":144736,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143130\/revisions\/144736"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/media\/54891"}],"wp:attachment":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/media?parent=143130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/categories?post=143130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/tags?post=143130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}