{"id":143111,"date":"2019-01-17T16:30:57","date_gmt":"2019-01-17T15:30:57","guid":{"rendered":"https:\/\/loudavymkrokem.cz\/?p=143111"},"modified":"2026-04-02T16:12:20","modified_gmt":"2026-04-02T14:12:20","slug":"roteiro-road-trip-islandia","status":"publish","type":"post","link":"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/","title":{"rendered":"Road trip pela Isl\u00e2ndia: roteiro de 14 dias + dicas de hospedagem"},"content":{"rendered":"<p>Quer saber como <b>aproveitar ao m\u00e1ximo 14-15 dias em um road trip pela Isl\u00e2ndia?<\/b> O que visitar e onde se hospedar? Preparamos para voc\u00ea um roteiro completo de road trip pela Isl\u00e2ndia de 14-15 dias, incluindo <b>mapa da rota e dicas de hospedagem.<\/b><\/p>\n<p>Lembre-se: <b>a Isl\u00e2ndia \u00e9 uma surpresa atr\u00e1s da outra e em 14 dias voc\u00ea n\u00e3o consegue ver tudo.<\/b> Al\u00e9m disso, o clima pode pregar pe\u00e7as \u2013 sim, pode nevar at\u00e9 no ver\u00e3o. Mesmo assim, tentamos incluir <b><a href=\"https:\/\/loudavymkrokem.cz\/20-nejhezcich-mist-na-islandu\/\">os lugares mais bonitos e interessantes<\/a>. Quanto gastamos no total, voc\u00ea encontra no nosso outro artigo <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143104\">neste link<\/a>.<\/b><\/p>\n<div class=\"youtube-embed\" data-video_id=\"CmKmfI2P3IM\"><iframe loading=\"lazy\" title=\"20 lugares mais bonitos da Isl\u00e2ndia | Loudav\u00fdm krokem\" width=\"696\" height=\"392\" src=\"https:\/\/www.youtube.com\/embed\/CmKmfI2P3IM?feature=oembed&#038;enablejsapi=1\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<h2><\/h2>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Obsah \u010dl\u00e1nku<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabela de conte\u00fado\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_1_Blue_Lagoon_dia_opcional\" >Dia 1) Blue Lagoon (dia opcional)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_2_Area_geotermal_Krysuvik_e_planicie_de_Thingvellir\" >Dia 2) \u00c1rea geotermal Kr\u00fdsuvik e plan\u00edcie de Thingvellir<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-2\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_3_Area_termal_Geysir\" >Dia 3) \u00c1rea termal Geysir<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-3\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_4_Dia_das_cachoeiras\" >Dia 4) Dia das cachoeiras<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-4\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_5_Lagoa_glacial_Jokullsarlon\" >Dia 5) Lagoa glacial J\u00f6kulls\u00e1rl\u00f3n<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-5\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_6_Fiordes_orientais\" >Dia 6) Fiordes orientais<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-6\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_7_Papagaios-do-mar_Snaefell\" >Dia 7) Papagaios-do-mar, Snaefell<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-7\" >Onde se hospedar:<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_8_Imponente_cachoeira_Detifoss\" >Dia 8) Imponente cachoeira Detifoss<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-8\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_9_Observacao_de_baleias_e_cachoeira_dos_deuses\" >Dia 9) Observa\u00e7\u00e3o de baleias e cachoeira dos deuses<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-9\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_10_Cidadezinhas_pitorescas_da_Islandia\" >Dia 10) Cidadezinhas pitorescas da Isl\u00e2ndia<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-10\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_11_Fiordes_ocidentais\" >Dia 11) Fiordes ocidentais<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-11\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_12_Cachoeira_encantada_Dynjandi\" >Dia 12) Cachoeira encantada Dynjandi<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-12\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_13_Isafjordur_e_a_terra_dos_Vikings\" >Dia 13) \u00cdsafj\u00f6r\u00f0ur e a terra dos Vikings<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-13\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_14_Peninsula_Snaefellsnes\" >Dia 14) Pen\u00ednsula Sn\u00e6fellsnes<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_se_hospedar-14\" >Onde se hospedar<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dia_15_Rio_quente_e_Reykjavik\" >Dia 15) Rio quente e Reykjav\u00edk<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Mapa_da_rota_pela_Islandia_para_download\" >Mapa da rota pela Isl\u00e2ndia para download<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Dicas_e_truques_para_viajar_pela_Islandia\" >Dicas e truques para viajar pela Isl\u00e2ndia<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#O_que_levar_na_mala\" >O que levar na mala<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Onde_encontrar_passagens_aereas\" >Onde encontrar passagens a\u00e9reas<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Aluguel_de_carro\" >Aluguel de carro<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-35\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Reserva_de_hospedagem\" >Reserva de hospedagem<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-36\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Nao_esqueca_o_seguro_viagem\" >N\u00e3o esque\u00e7a o seguro viagem<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-37\" href=\"https:\/\/loudavymkrokem.cz\/pt-br\/roteiro-road-trip-islandia\/#Outros_roteiros_para_a_Islandia\" >Outros roteiros para a Isl\u00e2ndia<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Dia_1_Blue_Lagoon_dia_opcional\"><\/span><span class=\"ez-toc-section\" id=\"Dia_1_Blue_Lagoon_dia_opcional\"><\/span>Dia 1) Blue Lagoon (dia opcional)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Blue Lagoon<\/strong><\/li>\n<\/ul>\n<p>Saindo de Keflav\u00edk, voc\u00ea pode ir direto <b>para as famosas termas turquesa da Blue Lagoon<\/b>. N\u00e3o esque\u00e7a: <b>os ingressos precisam ser reservados com anteced\u00eancia<\/b> \u2013 fora de temporada, pelo menos uma semana antes, e na alta temporada, de um a dois meses. Se achar o pre\u00e7o salgado, n\u00e3o se preocupe: <b>espalhadas por toda a Isl\u00e2ndia existem diversas piscinas termais que custam poucos euros ou s\u00e3o at\u00e9 gratuitas<\/b>. Confira as melhores <b><a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/fontes-termais-islandia\/\">neste artigo<\/a>.<\/b><\/p>\n<p><a href=\"https:\/\/www.instagram.com\/p\/Boug0BFlKOD\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.instagram.com\/p\/Boug0BFlKOD\/<\/a><\/p>\n<p><b>A Blue Lagoon fica a 20 km do aeroporto<\/b> e est\u00e1 localizada nos campos de lava perto da cidadezinha de Grindav\u00edk. Antes de se tornar uma grande atra\u00e7\u00e3o tur\u00edstica, <b>era usada principalmente para fins terap\u00eauticos.<\/b> A \u00e1gua \u00e9 rica em minerais como s\u00edlica e enxofre, sendo <b>indicada para pessoas com doen\u00e7as de pele, como psor\u00edase ou dermatite at\u00f3pica.<\/b><\/p>\n<blockquote>\n<p><em><b>Dica 1: Como economizar em hospedagem: <\/b>A Isl\u00e2ndia vive um boom tur\u00edstico que o pa\u00eds n\u00e3o consegue acompanhar (principalmente na constru\u00e7\u00e3o de hospedagens). Os pre\u00e7os s\u00e3o altos e o ideal \u00e9 reservar com anteced\u00eancia. <strong>Mesmo fora de temporada, pode ser dif\u00edcil encontrar hospedagem por menos de 40 \u20ac por pessoa.<\/strong> N\u00e3o espere por passagens baratas \u2013 os euros economizados nas passagens podem custar muito mais na hospedagem.<\/em><\/p>\n<\/blockquote>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): <strong><a title=\"Sunset H20\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/sunset-h20\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Sunset H20 Apartment or Room by Keflavik Airport<\/a> <\/strong>\/ <strong><a title=\"Anita\u00b4s Guest House\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/anitas-guest-house\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Anita\u00b4s Guest House<\/a> <\/strong>\/ <strong><a title=\"Guesthouse Anna\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/guesthouse-anna\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Guesthouse Anna<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o intermedi\u00e1ria<\/b> (at\u00e9 200 \u20ac): <strong><a title=\"Hotel Jazz\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hotel-jazz\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Hotel Jazz<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o de luxo<\/strong> (at\u00e9 320 \u20ac): <strong><a title=\"Geo H\u00f3tel Grindav\u00edk\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/geo-hotel-grindavik\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Geo H\u00f3tel Grindav\u00edk<\/a><\/strong> \/ <strong><a title=\"Northern Light Inn\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/northern-light-inn\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Northern Light Inn<\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_2_Area_geotermal_Krysuvik_e_planicie_de_Thingvellir\"><\/span><span class=\"ez-toc-section\" id=\"Dia_2_Area_geotermal_Krysuvik_e_planicie_de_Thingvellir\"><\/span>Dia 2) \u00c1rea geotermal Kr\u00fdsuvik e plan\u00edcie de <strong>Thingvellir<\/strong><span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Thingvellir, Kr\u00fdsuvik, Oxarafoss<\/strong><\/li>\n<\/ul>\n<p>Sa\u00edmos de Keflav\u00edk <b>em dire\u00e7\u00e3o a Kr\u00fdsuvik, o que leva aproximadamente 45 minutos.<\/b> Nessa \u00e1rea geotermal, passamos uma hora agrad\u00e1vel caminhando entre os lagos de lama borbulhante. <b>Depois, seguimos para a plan\u00edcie de Thingvellir, onde provavelmente surgiu o parlamento mais antigo do mundo.<\/b><\/p>\n<figure id=\"attachment_53884\" aria-describedby=\"caption-attachment-53884\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53884\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Oxarafoss_thingvellir.jpg\" alt=\"Road trip pela Isl\u00e2ndia: caminhada at\u00e9 as cachoeiras\" width=\"650\" height=\"975\" title=\"\"><figcaption id=\"caption-attachment-53884\" class=\"wp-caption-text\">Caminhada at\u00e9 as cachoeiras<\/figcaption><\/figure>\n<p>A viagem at\u00e9 Thingvellir leva cerca de 70 minutos. Em Thingvellir, caminhamos pelo c\u00e2nion <b>at\u00e9 a bel\u00edssima cachoeira Oxarafoss<\/b> e encerramos o dia na <b>cratera Kerid, que surgiu h\u00e1 cerca de 3 milh\u00f5es de anos<\/b>. Ela tem 70 m de profundidade e 70 m de largura, e voc\u00ea pode caminhar ao redor por uma pequena taxa. O passeio todo n\u00e3o leva mais que 20 minutos.<\/p>\n<blockquote>\n<p><em><b>Dica 2: Como economizar em hospedagem: <\/b><\/em><em>Se tem um lugar onde realmente vale a pena viajar em grupo, \u00e9 a Isl\u00e2ndia. Voc\u00eas podem ficar em hostels \u00f3timos, em quartos para quatro pessoas com cozinha dispon\u00edvel. <strong>Assim, o custo da hospedagem pode cair para<\/strong><b> 20-28 \u20ac por pessoa!<\/b><\/em><\/p>\n<\/blockquote>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-2\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 60 \u20ac): <strong><a title=\"Lj\u00f3safosssk\u00f3li Hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/ljosafossskoli-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Lj\u00f3safosssk\u00f3li Hostel<\/a><\/strong> \u2013 esse hostel \u00e9 uma antiga escola! Al\u00e9m disso, o caf\u00e9 da manh\u00e3 est\u00e1 inclu\u00eddo e \u00e9 servido no antigo refeit\u00f3rio escolar. O Luk\u00e1\u0161 se apaixonou totalmente por esse lugar.<\/li>\n<li><b>Op\u00e7\u00e3o intermedi\u00e1ria<\/b> (at\u00e9 160 \u20ac): <strong><a title=\"Guesthouse Nordheimar\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/guesthouse-nordheimar\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Guesthouse Nordheimar<\/a><\/strong> \/ <strong><a title=\"South Central Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/south-central-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">South Central Guesthouse<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o de luxo<\/strong> (at\u00e9 400 \u20ac): <strong><a title=\"Marta House\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/marta-house\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Marta House<\/a><\/strong> \/ <strong><a title=\"River Apartments\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/river-apartments\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">River Apartments<\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_3_Area_termal_Geysir\"><\/span><span class=\"ez-toc-section\" id=\"Dia_3_Area_termal_Geysir\"><\/span>Dia 3) \u00c1rea termal Geysir<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><b>Geysir, Brjarnafell, Gullfoss, Hrunalaug Hot Springs<\/b><\/li>\n<\/ul>\n<p>No terceiro dia, fomos at\u00e9 a \u00e1rea termal <b>Geysir, onde fica o g\u00eaiser de mesmo nome<\/b>. Se quiser ver o jato de \u00e1gua, reserve mais tempo. <b>Perto do Geysir, tamb\u00e9m subimos at\u00e9 o mirante no morro Bjarnalfell, mas honestamente n\u00e3o vale muito a pena<\/b> \u2013 al\u00e9m disso, durante a subida, todas as esta\u00e7\u00f5es do ano se alternaram: tivemos sol, vento absurdo, chuva e granizo. E o granizo nos pegou bem no topo.<\/p>\n<figure id=\"attachment_53862\" aria-describedby=\"caption-attachment-53862\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53862\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Geysir.jpg\" alt=\"Geysir\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53862\" class=\"wp-caption-text\">\u00c1rea termal Geysir<\/figcaption><\/figure>\n<p>Do Geysir, seguimos para as <b>imponentes cachoeiras Gullfoss<\/b>, e encerramos o dia nas <b>piscinas termais Hrunalaug Hot Springs<\/b>, a 30 km de dist\u00e2ncia.<\/p>\n<figure id=\"attachment_53869\" aria-describedby=\"caption-attachment-53869\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53869\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Hrunalaug_hot_springsr.jpg\" alt=\"Hrunalaug hot springs\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53869\" class=\"wp-caption-text\">Recomendamos viajar pela Isl\u00e2ndia em pelo menos 4 pessoas \u2013 isso reduz bastante os custos<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-3\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): <a title=\"Welcome Riverside Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/welcome-riverside-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><strong>Welcome Riverside Guesthouse<\/strong><\/a> \/ <strong><a title=\"Guesthouse Kaldakinn\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/guesthouse-kaldakinn\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Guesthouse Kaldakinn<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 140 \u20ac): <strong><a title=\"Voga Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/voga-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Voga Guesthouse<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 200 \u20ac): <strong><a title=\"Hekla Cabin 2 Volcano and Glacier View\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hekla-cabin-2-volcano-and-glacier-view\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Hekla Cabin 2 Volcano and Glacier View<\/a><\/strong> \/ <strong><a title=\"Hekla Cabin 1 Volcano and Glacier View\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hekla-cabin-1-volcano-and-glacier-view\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Hekla Cabin 1 Volcano and Glacier View<\/a><\/strong> \/ <strong><a title=\"Farmer&#039;s Guest House\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/farmers-guest-house\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Farmer&#8217;s Guest House<\/a><\/strong> \/ <strong><a title=\"Fagrabrekka Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/fagrabrekka-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Fagrabrekka Guesthouse<\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_4_Dia_das_cachoeiras\"><\/span><span class=\"ez-toc-section\" id=\"Dia_4_Dia_das_cachoeiras\"><\/span>Dia 4) Dia das cachoeiras<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53872\" aria-describedby=\"caption-attachment-53872\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53872\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Islandske_vodopady.jpg\" alt=\"Dia das cachoeiras\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53872\" class=\"wp-caption-text\">Dia das cachoeiras<\/figcaption><\/figure>\n<ul>\n<li><b>Gluggafoss, Seljalandsfoss, Gljufrafoss, Skogafoss, Dyrholaey<\/b><\/li>\n<\/ul>\n<p>De manh\u00e3, partimos para as cachoeiras <b>Gluggafoss, Seljalandsfoss, Gljufrafoss e Skogafoss<\/b>. Todas s\u00e3o deslumbrantes, e se voc\u00ea acha que vai enjoar de cachoeiras, pode ter certeza que n\u00e3o vai! <b>Depois das cachoeiras, fomos nos banhar na Seljavallalaug swimming pool.<\/b> Aten\u00e7\u00e3o: essa fotog\u00eanica piscina termal n\u00e3o \u00e9 t\u00e3o quente, e se voc\u00ea for fora de temporada, a \u00e1gua pode estar apenas morna. <b>O vesti\u00e1rio \u00e9 um tanto prec\u00e1rio.<\/b><\/p>\n<figure id=\"attachment_53886\" aria-describedby=\"caption-attachment-53886\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53886\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Seljavellir.jpg\" alt=\"Piscina termal todo dia: nosso lema na Isl\u00e2ndia\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53886\" class=\"wp-caption-text\">Piscina termal todo dia: nosso lema na Isl\u00e2ndia<\/figcaption><\/figure>\n<p>Encerramos o dia com a vista <b>do cabo Dyrholaey e a praia negra Reynisfjara, considerada a praia mais bonita da Isl\u00e2ndia.<\/b> Infelizmente, n\u00e3o conseguimos ver as forma\u00e7\u00f5es rochosas dos trolls Reynisdrangar com luz do dia. Mas talvez voc\u00ea tenha mais sorte!<\/p>\n<figure id=\"attachment_53883\" aria-describedby=\"caption-attachment-53883\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53883\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Mys_Dyrholay.jpg\" alt=\"Cabo Dyrholaey\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53883\" class=\"wp-caption-text\">Cabo Dyrholaey<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-4\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 80 \u20ac): <strong><a title=\"The Barn\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/the-barn\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">The Barn<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 240 \u20ac): <strong><a title=\"Guesthouse Galleri V\u00edk\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/guesthouse-galleri-vik\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Guesthouse Galleri V\u00edk<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 400 \u20ac): <strong><a title=\"Black Beach Suites\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/black-beach-suites\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Black Beach Suites<\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_5_Lagoa_glacial_Jokullsarlon\"><\/span><span class=\"ez-toc-section\" id=\"Dia_5_Lagoa_glacial_Jokulsarlon\"><\/span>Dia 5) Lagoa glacial J\u00f6kulls\u00e1rl\u00f3n<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53874\" aria-describedby=\"caption-attachment-53874\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53874\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Jakulsarlon_muz_sedici_na_brehu.jpg\" alt=\"Um dos lugares mais m\u00e1gicos da Isl\u00e2ndia\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53874\" class=\"wp-caption-text\">Um dos lugares mais m\u00e1gicos da Isl\u00e2ndia<\/figcaption><\/figure>\n<ul>\n<li><strong>J\u00f6kulls\u00e1rl\u00f3n, Hoffelsjokull, Eystrahorn, Djupivogur<\/strong><\/li>\n<\/ul>\n<p>Passamos a manh\u00e3 na lagoa glacial <b>J\u00f6kulls\u00e1rl\u00f3n<\/b>, considerada uma das paisagens mais impressionantes e belas da Isl\u00e2ndia. H\u00e1 apenas 60 anos, este lugar era coberto por um enorme glaciar, e infelizmente \u00e9 evidente que <b>em breve nem a lagoa existir\u00e1 mais.<\/b> Ficamos <b>cerca de duas horas ali e depois seguimos at\u00e9 o glaciar Hoffelsjokull<\/b>, onde voc\u00ea tamb\u00e9m encontra \u00f3timas piscinas termais, as <strong>Hoffel hot tubs<\/strong>. Uma das montanhas mais bonitas da Isl\u00e2ndia <b>\u00e9 sem d\u00favida a Eystrahorn, que voc\u00ea avista no caminho para <em>Berufj\u00f6r\u00f0ur<\/em>, onde decidimos pernoitar.<\/b><\/p>\n<blockquote>\n<p><em><strong>Dica 3 \u2013 Como economizar em hospedagem:<\/strong> <a href=\"https:\/\/loudavymkrokem.cz\/jak-usetrit-kartou-pri-cestovani\/\">Aproveite programas de cashback!<\/a> N\u00f3s economizamos assim pagando todas as hospedagens com cart\u00f5es que oferecem cashback. Voc\u00ea pode economizar de 5 a 13%.<\/em><\/p>\n<\/blockquote>\n<figure id=\"attachment_53861\" aria-describedby=\"caption-attachment-53861\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53861\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Eystrahorn.jpg\" alt=\"A fotog\u00eanica montanha Eystrahorn\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53861\" class=\"wp-caption-text\">A fotog\u00eanica montanha Eystrahorn<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-5\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): <strong><a title=\"Havar\u00ed hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/havari-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Havar\u00ed hostel<\/a><\/strong> \/ <strong><a title=\"Klif Hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/klif-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Klif Hostel<\/a><\/strong> \/ <strong><a title=\"Berunes HI Hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/berunes-hi-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Berunes HI Hostel<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 160 \u20ac): <strong><a title=\"Hotel Blafell\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hotel-blafell\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Hotel Blafell<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 240 \u20ac): <strong><a title=\"Starm\u00fdri 2a\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/starmyri-2a\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Starm\u00fdri 2a<\/a><\/strong> \/ <strong><a title=\"Kr\u00e1khamar Apartments\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/krakhamar-apartments\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Kr\u00e1khamar Apartments<\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_6_Fiordes_orientais\"><\/span><span class=\"ez-toc-section\" id=\"Dia_6_Fiordes_orientais\"><\/span>Dia 6) Fiordes orientais<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><b>Rey\u00f0arfj\u00f6r\u00f0ur, Neskaupsta\u00f0ur, Paskahellir, Egilssta\u00f0ir, Sey\u00f0isfj\u00f6r\u00f0ur<\/b><\/li>\n<\/ul>\n<p>De manh\u00e3, continuamos dirigindo pelos fiordes. <b>Nossa pr\u00f3xima parada foi Rey\u00f0arfj\u00f6r\u00f0ur, onde voc\u00ea pode fazer uma curta caminhada de subida (cerca de 2 horas) at\u00e9 Graenefell.<\/b> Seguimos para o ponto mais oriental <b>da Isl\u00e2ndia, Neskaupsta\u00f0ur<\/b>. Visitamos as <b>cavernas da P\u00e1scoa, Paskahellir<\/b>, onde voc\u00ea pode encontrar cristais nas pedras (com um pouco de paci\u00eancia).<\/p>\n<figure id=\"attachment_53864\" aria-describedby=\"caption-attachment-53864\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53864\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Graenefell.jpg\" alt=\"Curta subida at\u00e9 Graenefell\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53864\" class=\"wp-caption-text\">Curta subida at\u00e9 Graenefell<\/figcaption><\/figure>\n<p>Sinceramente, esper\u00e1vamos mais das cavernas, e se voc\u00ea precisar pular alguma parada, eu cortaria essa. <strong>Conseguimos hospedagem<\/strong> <b>em Egilssta\u00f0ir, mas como ainda t\u00ednhamos tempo de sobra, fomos at\u00e9 o popular Sey\u00f0isfj\u00f6r\u00f0ur<\/b> (30 minutos de carro), famoso pelas fotos da igrejinha com a cal\u00e7ada arco-\u00edris.<\/p>\n<figure id=\"attachment_53887\" aria-describedby=\"caption-attachment-53887\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53887\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Seydisfjordur.jpg\" alt=\"Sey\u00f0isfj\u00f6r\u00f0ur\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53887\" class=\"wp-caption-text\">Sey\u00f0isfj\u00f6r\u00f0ur<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-6\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): <strong><a title=\"Vallnaholt Apartments and Rooms\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/vallnaholt-apartments-and-rooms\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Vallnaholt Apartments and Rooms<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 160 \u20ac): <strong><a title=\"Vinland Guesthouse \" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/vinland-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Vinland Guesthouse<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 200 \u20ac): <strong><a title=\"Kald\u00e1 Lyngholt Holiday Homes\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/kalda-lyngholt-holiday-homes\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Kald\u00e1 Lyngholt Holiday Homes<\/span><\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_7_Papagaios-do-mar_Snaefell\"><\/span><span class=\"ez-toc-section\" id=\"Dia_7_Papagaios_do_mar_Snaefell\"><\/span>Dia 7) Papagaios-do-mar, Snaefell<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53878\" aria-describedby=\"caption-attachment-53878\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53878\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/kone_na_islandu.jpg\" alt=\"O que mais amamos na Isl\u00e2ndia foram os cavalos islandeses\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53878\" class=\"wp-caption-text\">O que mais amamos na Isl\u00e2ndia foram os cavalos islandeses<\/figcaption><\/figure>\n<ul>\n<li><strong>Papagaios-do-mar, Laugarfell, Snaefell, Hengifoss<\/strong><\/li>\n<\/ul>\n<p>Come\u00e7amos o dia em <b>Borgarfj\u00f6r\u00f0ur (uma hora de Egilssta\u00f0ir)<\/b>, onde na temporada \u00e9 poss\u00edvel ver os puffins (papagaios-do-mar). Fora de temporada, n\u00e3o recomendamos ir, pois n\u00e3o h\u00e1 nada para ver. Depois, fomos novamente para piscinas termais \u2013 desta vez escolhemos as luxuosas piscinas de Laugarfell. N\u00e3o se preocupe, o pre\u00e7o n\u00e3o \u00e9 nada exorbitante. <b>No caminho, voc\u00ea pode avistar a famosa montanha Snaefell, e se tiver tempo suficiente, passe nas cachoeiras Hengifoss, que s\u00e3o as terceiras mais altas da Isl\u00e2ndia<\/b>. A caminhada at\u00e9 as cachoeiras leva cerca de 30 minutos.<\/p>\n<figure id=\"attachment_53882\" aria-describedby=\"caption-attachment-53882\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53882\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Laugarfell.jpg\" alt=\"Laugarfell\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53882\" class=\"wp-caption-text\">O que seria de um dia na Isl\u00e2ndia sem hot pots!<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-7\"><\/span><strong>Onde se hospedar:<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Mesma hospedagem do dia anterior!<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Dia_8_Imponente_cachoeira_Detifoss\"><\/span><span class=\"ez-toc-section\" id=\"Dia_8_Imponente_cachoeira_Detifoss\"><\/span>Dia 8) Imponente cachoeira Detifoss<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53859\" aria-describedby=\"caption-attachment-53859\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53859\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Detifoss.jpg\" alt=\"Detifoss\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53859\" class=\"wp-caption-text\">Detifoss<\/figcaption><\/figure>\n<ul>\n<li><b>Detifoss, Selfoss, Husav\u00edk<\/b><\/li>\n<\/ul>\n<p>De manh\u00e3, partimos para a <b>imponente cachoeira Detifoss \u2013 a estrada costuma estar fechada e n\u00e3o \u00e9 adequada para carros pequenos<\/b>. Confira nosso outro artigo, onde damos dicas de como se preparar para a Isl\u00e2ndia. <b>Se o tempo estiver bom, voc\u00ea pode caminhar de Detifoss at\u00e9 Selfoss.<\/b> N\u00f3s tivemos que pular Selfoss por causa do mau tempo e seguimos direto para nosso destino do dia \u2013 <b>a linda cidadezinha portu\u00e1ria de Husav\u00edk.<\/b><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-8\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 120 \u20ac): <strong><a title=\"Berg Hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/berg-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Berg Hostel<\/span><\/a><\/strong><\/li>\n<li><strong>Nossa op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 240 \u20ac): <strong><a title=\"Saltv\u00edk Farm Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/saltvik-farm-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Saltv\u00edk Farm Guesthouse<\/a><\/strong> \/ <strong><a title=\"\u00c1rb\u00f3l Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/arbol-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">\u00c1rb\u00f3l Guesthouse<\/span><\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 400 \u20ac): <strong><a title=\"Bjarnab\u00fa\u00f0\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/bjarnabud\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Bjarnab\u00fa\u00f0<\/span><\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_9_Observacao_de_baleias_e_cachoeira_dos_deuses\"><\/span><span class=\"ez-toc-section\" id=\"Dia_9_Observacao_de_baleias_e_cachoeira_dos_deuses\"><\/span>Dia 9) Observa\u00e7\u00e3o de baleias e cachoeira dos deuses<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>O porto de Husav\u00edk \u00e9 famoso principalmente porque <b>daqui voc\u00ea pode embarcar em passeios de observa\u00e7\u00e3o de baleias<\/b>. Como j\u00e1 t\u00ednhamos visto baleias em outras viagens, decidimos pular esse passeio e passamos a manh\u00e3 explorando a cidadezinha.<\/p>\n<figure id=\"attachment_53870\" aria-describedby=\"caption-attachment-53870\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53870\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Husavik.jpg\" alt=\"Husav\u00edk, cidade das baleias\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53870\" class=\"wp-caption-text\">Husav\u00edk, cidade das baleias<\/figcaption><\/figure>\n<p><b>Se voc\u00ea nunca fez um passeio de observa\u00e7\u00e3o de baleias, considere seriamente investir \u2013 \u00e9 um dos passeios mais populares da Isl\u00e2ndia, custa entre 80-100 \u20ac por pessoa e dura de 3 a 4 horas.<\/b> Perfeito para uma manh\u00e3 ou tarde agrad\u00e1vel. Durante a alta temporada (1\u00ba de julho a 19 de agosto), os passeios saem \u00e0s 10h, 14h30 e 18h30. A temporada vai de maio a setembro. Reserve a observa\u00e7\u00e3o de baleias com anteced\u00eancia, os hor\u00e1rios lotam r\u00e1pido na temporada (<em>link para <strong><a href=\"https:\/\/www.northsailing.is\/whale-watching\/timetable\/\" target=\"_blank\" rel=\"noopener\">reserva<\/a><\/strong><\/em>).<\/p>\n<p><b>\u00c0 tarde, seguimos para M\u00fdvatn (cerca de uma hora de carro de Husav\u00edk), destino famoso pela observa\u00e7\u00e3o de aves.<\/b> Mesmo que p\u00e1ssaros n\u00e3o sejam sua praia, a paisagem \u00e9 deslumbrante por si s\u00f3. <b>\u00c9 exatamente assim que imagino Marte.<\/b> A caminhada ao redor das crateras <b>levou cerca de uma hora e meia<\/b>, e depois seguimos <b>at\u00e9 a cratera Viti e o vulc\u00e3o Krafla. Encerramos o dia com o p\u00f4r do sol na cachoeira Godafoss.<\/b><\/p>\n<figure id=\"attachment_53863\" aria-describedby=\"caption-attachment-53863\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53863\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Godafoss.jpg\" alt=\"Godafoss\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53863\" class=\"wp-caption-text\">Godafoss<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-9\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): Infelizmente reservamos tarde e tudo de bom j\u00e1 estava esgotado, ent\u00e3o acabamos ficando no <strong><a title=\"Amma Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/amma-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Amma Guesthouse<\/a><\/strong>. Tente o futurista <strong><a title=\"Hafnarstr\u00e6ti Hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hafnarstraeti-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Hafnarstr\u00e6ti Hostel<\/a><\/strong> ou o <strong><a title=\"Akureyri H.I. Hostel\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/akureyri-h-i-hostel\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Akureyri H.I. Hostel<\/a><\/strong> \u2013 ambos t\u00eam \u00f3timas avalia\u00e7\u00f5es.<\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 160 \u20ac): <strong><a title=\"Guesthouse Baegisa\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/guesthouse-baegisa\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Guesthouse Baegisa<\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_10_Cidadezinhas_pitorescas_da_Islandia\"><\/span><span class=\"ez-toc-section\" id=\"Dia_10_Cidadezinhas_pitorescas_da_Islandia\"><\/span>Dia 10) Cidadezinhas pitorescas da Isl\u00e2ndia<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53888\" aria-describedby=\"caption-attachment-53888\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53888\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Sigufjordur.jpg\" alt=\"Siglufj\u00f6r\u00f0ur\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53888\" class=\"wp-caption-text\">Siglufj\u00f6r\u00f0ur<\/figcaption><\/figure>\n<ul>\n<li><strong>Akureyri, Siglufj\u00f6r\u00f0ur, Hofs\u00f3s, Grettislaug<\/strong><\/li>\n<\/ul>\n<p>De manh\u00e3, fomos ver as <b>tradicionais casas de turfa em Eyjafj\u00f6r\u00f0ur<\/b>. <b>A 40 km do C\u00edrculo Polar \u00c1rtico fica o pitoresco porto de Siglufj\u00f6r\u00f0ur, onde paramos para uma breve caminhada.<\/b> Se voc\u00ea gosta de cidadezinhas charmosas, pare tamb\u00e9m em Hofs\u00f3s. Como de costume, encerramos nosso d\u00e9cimo dia na <b>piscina termal Grettislaug.<\/b><\/p>\n<figure id=\"attachment_53865\" aria-describedby=\"caption-attachment-53865\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53865\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Grettislaug.jpg\" alt=\"Vista de Grettislaug\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53865\" class=\"wp-caption-text\">Vista de Grettislaug<\/figcaption><\/figure>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-10\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 120 \u20ac): <strong><a title=\"H\u00fanaver\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hunaver\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">H\u00fanaver<\/a><\/strong> \/ <strong><a title=\"Hotel H\u00fani\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hotel-huni\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Hotel H\u00fani<\/a><\/strong> \/ <strong><a title=\"B\u00f3lsta\u00f0arhl\u00ed\u00f0 Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/bolstadarhlid-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">B\u00f3lsta\u00f0arhl\u00ed\u00f0 Guesthouse<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 240 \u20ac): <strong><a title=\"Hestasport Cottages\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/hestasport-cottages\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Hestasport Cottages<\/span><\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_11_Fiordes_ocidentais\"><\/span><span class=\"ez-toc-section\" id=\"Dia_11_Fiordes_ocidentais\"><\/span>Dia 11) Fiordes ocidentais<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53885\" aria-describedby=\"caption-attachment-53885\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53885\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Polarni_zare_Island.jpg\" alt=\"Aurora boreal na Isl\u00e2ndia\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53885\" class=\"wp-caption-text\">Aurora boreal na Isl\u00e2ndia<\/figcaption><\/figure>\n<ul>\n<li><b>A paisagem selvagem dos fiordes ocidentais<\/b><\/li>\n<\/ul>\n<p>No d\u00e9cimo primeiro dia, nos esperava um <b>longo trajeto pela costa sul dos fiordes ocidentais.<\/b> Mas n\u00e3o se preocupe: <b>a estrada \u00e9 verdadeiramente encantadora, aut\u00eantica, e \u00e9 a parte menos visitada da Isl\u00e2ndia.<\/b> Acho que para esse tipo de paisagem costumam usar a express\u00e3o &#8220;crua&#8221;. Talvez at\u00e9 um pouco selvagem. Mas t\u00e9dio aqui \u00e9 imposs\u00edvel. <b>Na verdade, tome cuidado para conseguir chegar ao destino \u2013 a cada quil\u00f4metro a paisagem pede uma parada. E claro, para n\u00f3s com c\u00e2meras, pede fotos.<\/b> \u00c0 noite, nos hospedamos em um chal\u00e9 lindo, de onde observamos a aurora boreal. O que mais se pode querer!<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-11\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): <span class=\"sr-hotel__name \" data-et-click=\" \"><strong><a title=\"Rau\u00f0sdalur\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/raudsdalur\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Rau\u00f0sdalur<\/a><\/strong> \/ <\/span><strong><a title=\"Bjarkarholt Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/bjarkarholt-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Bjarkarholt Guesthouse<\/span><\/a><\/strong><\/li>\n<li><strong>Nossa op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 200 \u20ac): <strong><a title=\"Road 62 Hagi 2\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/road-62-hagi-2\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Road 62 Hagi 2<\/a><\/strong> (pequeno, mas adequado at\u00e9 para 4 pessoas)<\/li>\n<li><b>Para grupos maiores<\/b> (at\u00e9 400 \u20ac): <strong><a title=\"Fer\u00f0a\u00fej\u00f3nustan Bar\u00f0astr\u00f6nd\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/ferdathjonustan-bardastrond\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Fer\u00f0a\u00fej\u00f3nustan Bar\u00f0astr\u00f6nd<\/span><\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_12_Cachoeira_encantada_Dynjandi\"><\/span><span class=\"ez-toc-section\" id=\"Dia_12_Cachoeira_encantada_Dynjandi\"><\/span>Dia 12) Cachoeira encantada Dynjandi<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53860\" aria-describedby=\"caption-attachment-53860\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53860\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Dynjandi.jpg\" alt=\"Dynjandi\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53860\" class=\"wp-caption-text\">Dynjandi<\/figcaption><\/figure>\n<ul>\n<li><strong>Dynjandi, Pollurin, Arnarfj\u00f6r\u00f0ur, B\u00edldudalur<\/strong><\/li>\n<\/ul>\n<p>Come\u00e7amos o dia com um banho <b>nas piscinas termais Pollurin<\/b> e, uma hora depois, j\u00e1 est\u00e1vamos de volta \u00e0 estrada desbravando os fiordes ocidentais. <b>A estrada \u00e9 cheia de adrenalina, longa, e leva mais tempo do que o Google indica.<\/b> Voc\u00ea passa por cima do lindo Arnarfj\u00f6r\u00f0ur e pelo porto de B\u00edldudalur. Encerramos o dia na encantada <b>cachoeira Dynjandi<\/b>, onde passamos pelo menos uma hora e meia. Alguns dizem que \u00e9 a cachoeira mais bonita da Isl\u00e2ndia. <b>Tenho a sensa\u00e7\u00e3o de que gostaria de dizer isso de cada uma delas! \u00c0 noite, chegamos a \u00cdsafj\u00f6r\u00f0ur, onde nos hospedamos.<\/b><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-12\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 120 \u20ac): <span class=\"sr-hotel__name \" data-et-click=\" \"><strong><a title=\"GentleSpace Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/gentlespace-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">GentleSpace Guesthouse<\/a><\/strong> \/ op\u00e7\u00e3o mais barata por\u00e9m mais simples: <\/span><strong><a title=\"M\u00e1nagisting Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/managisting-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">M\u00e1nagisting Guesthouse<\/span><\/a><\/strong><\/li>\n<li><strong>Nossa op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 160 \u20ac): <strong><a title=\"Central Apartment with Mountain view\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/central-apartment-with-mountain-view\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Central Apartment with Mountain view<\/a><\/strong><\/li>\n<li><b>Op\u00e7\u00e3o de luxo<\/b> (at\u00e9 240 \u20ac): <strong><a title=\"Tangs\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/tangs\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Tangs<\/a><\/strong> (avalia\u00e7\u00e3o 9,9 no Booking \u2013 fazia tempo que n\u00e3o via nota t\u00e3o alta!)<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_13_Isafjordur_e_a_terra_dos_Vikings\"><\/span><span class=\"ez-toc-section\" id=\"Dia_13_Isafjordur_e_a_terra_dos_Vikings\"><\/span>Dia 13) \u00cdsafj\u00f6r\u00f0ur e a terra dos Vikings<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><b>\u00cdsafj\u00f6r\u00f0ur, Litlib\u00e6r, H\u00f3lmav\u00edk, B\u00fa\u00f0ardalur<\/b><\/li>\n<\/ul>\n<p>\u00cdsafj\u00f6r\u00f0ur \u00e9 famosa <b>por suas vistas dram\u00e1ticas e casinhas de madeira dos s\u00e9culos XVIII e XIX da antiga vila de pescadores.<\/b> Se a hist\u00f3ria local te interessa, vale visitar o museu. N\u00f3s preferimos seguir viagem pela costa norte dos fiordes ocidentais. O clima no in\u00edcio de outubro estava bem gelado. Quem estiver na Isl\u00e2ndia durante a temporada (que termina em meados de setembro) pode tomar um caf\u00e9 na casinha de turfa Litlib\u00e6r. Infelizmente, viajar fora de temporada tem seus pontos negativos. Por outro lado, economizamos com o caf\u00e9 island\u00eas absurdamente caro.<\/p>\n<figure id=\"attachment_53880\" aria-describedby=\"caption-attachment-53880\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53880\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/krajina-vikingu.jpg\" alt=\"A terra dos Vikings, imposs\u00edvel n\u00e3o se apaixonar\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53880\" class=\"wp-caption-text\">A terra dos Vikings, imposs\u00edvel n\u00e3o se apaixonar<\/figcaption><\/figure>\n<p>Ent\u00e3o seguimos viagem pela <b>terra dos Vikings<\/b>, admirando vistas de tirar o f\u00f4lego, quase ficamos presos em uma nevasca, mas no fim conseguimos <b>passar por H\u00f3lmav\u00edk e chegar \u00e0 hospedagem em B\u00fa\u00f0ardalur.<\/b><\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-13\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 120 \u20ac): <strong><a title=\"The Castle\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/the-castle\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">The Castle<\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 160 \u20ac): <strong><a title=\"Saudafell Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/saudafell-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Saudafell Guesthouse<\/span><\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_14_Peninsula_Snaefellsnes\"><\/span><span class=\"ez-toc-section\" id=\"Dia_14_Peninsula_Snaefellsnes\"><\/span>Dia 14) Pen\u00ednsula Sn\u00e6fellsnes<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_53877\" aria-describedby=\"caption-attachment-53877\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53877\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Kirkjufell.jpg\" alt=\"Kirkjufell nos decepcionou um pouco\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53877\" class=\"wp-caption-text\">Kirkjufell nos decepcionou um pouco<\/figcaption><\/figure>\n<ul>\n<li><b>Sn\u00e6fellsnes, Kirkjufellfoss, Akranes<\/b><\/li>\n<\/ul>\n<p>Nossa viagem estava chegando ao fim. No pen\u00faltimo dia, dedicamos o tempo \u00e0 <b>pen\u00ednsula Sn\u00e6fellsnes, onde nossa primeira parada foi Stykkish\u00f3lmur.<\/b> Um dos nossos objetivos era a cachoeira <b>Kirkjufellfoss<\/b>, que <b>\u00e9 a cachoeira mais fotografada da Isl\u00e2ndia.<\/b> Infelizmente, nos decepcionou um pouco, pois parecia que todos os turistas da Isl\u00e2ndia estavam ali, e aquela vista m\u00e1gica s\u00f3 funciona de um \u00e2ngulo bem espec\u00edfico. De qualquer outro \u00e2ngulo, parece completamente comum.<\/p>\n<figure id=\"attachment_53879\" aria-describedby=\"caption-attachment-53879\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53879\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/konicky_island.jpg\" alt=\"Se mor\u00e1ssemos na Isl\u00e2ndia, eu com certeza precisaria de um cavalo\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53879\" class=\"wp-caption-text\">Se mor\u00e1ssemos na Isl\u00e2ndia, eu com certeza precisaria de um cavalo<\/figcaption><\/figure>\n<p><b>Nos compensamos na rom\u00e2ntica vilazinha de Arnarstapi, onde vale a pena parar por mais tempo e caminhar.<\/b> H\u00e1 forma\u00e7\u00f5es rochosas incr\u00edveis no mar e, ao fundo, montanhas cobertas de neve.<\/p>\n<p>Nossa \u00faltima parada <b>foi Sn\u00e6fellsj\u00f6kull, um estratovulc\u00e3o de 700 mil anos de idade, cujo pico \u00e9 coberto por uma geleira.<\/b> Nos hospedamos na cidadezinha de <b>Akranes, pertinho de Reykjav\u00edk<\/b>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_se_hospedar-14\"><\/span><strong>Onde se hospedar<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<ul>\n<li><b>Nossa op\u00e7\u00e3o econ\u00f4mica<\/b> (at\u00e9 100 \u20ac): <strong><a title=\"Gallery Guesthouse - StayWest\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/gallery-guesthouse-staywest\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Gallery Guesthouse &#8211; StayWest<\/a><\/strong> \/ <strong><a title=\"M\u00f3ar Guesthouse\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/moar-guesthouse\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">M\u00f3ar Guesthouse<\/a><\/strong> \/ <strong><a title=\"Akranes Rooms\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/akranes-rooms\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">Akranes Rooms<\/span><\/a><\/strong><\/li>\n<li><strong>Op\u00e7\u00e3o intermedi\u00e1ria:<\/strong> (at\u00e9 160 \u20ac): <span class=\"sr-hotel__name \" data-et-click=\" \"><strong><a title=\"M\u00f3ar Cottage\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/moar-cottage\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">M\u00f3ar Cottage<\/a><\/strong> \/ <\/span><strong><a title=\"J\u00f6rfagrund 19 \" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/jorfagrund-19\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\"><span class=\"sr-hotel__name \" data-et-click=\" \">J\u00f6rfagrund 19 <\/span><\/a><\/strong><\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Dia_15_Rio_quente_e_Reykjavik\"><\/span><span class=\"ez-toc-section\" id=\"Dia_15_Rio_quente_e_Reykjavik\"><\/span>Dia 15) Rio quente e Reykjav\u00edk<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Reykjadalur,<\/strong> <strong>Hallgr\u00edmskirkja, The Sun Voyager, Harpa<\/strong><\/li>\n<\/ul>\n<p>Como nosso voo era s\u00f3 \u00e0 noite, <b>no \u00faltimo dia de manh\u00e3 decidimos ir at\u00e9 o rio quente Reykjadalur<\/b>. \u00c9 uma caminhada de 45 minutos at\u00e9 um rio termal. Sim, uma subida at\u00e9 um rio quente de verdade! Mas aten\u00e7\u00e3o: se estiver frio e com vento gelado, talvez seja melhor pular essa parada. <b>Voc\u00ea precisa se trocar ao ar livre.<\/b><\/p>\n<figure id=\"attachment_53868\" aria-describedby=\"caption-attachment-53868\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53868\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/horka_reka.jpg\" alt=\"Rio quente na Isl\u00e2ndia\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53868\" class=\"wp-caption-text\">Rio quente na Isl\u00e2ndia<\/figcaption><\/figure>\n<p>Por isso, s\u00f3 chegamos a Reykjav\u00edk \u00e0 tarde. O tempo n\u00e3o colaborou, mas sinceramente j\u00e1 n\u00e3o importava. Depois de duas semanas na Isl\u00e2ndia, est\u00e1vamos cheios de impress\u00f5es, de frio e de alca\u00e7uz, a ponto de simplesmente tomar um caf\u00e9 island\u00eas (caro!) e curtir os \u00faltimos momentos nessa terra de gelo no calor de um caf\u00e9.<\/p>\n<p>Em Reykjav\u00edk, <b>voc\u00ea pode visitar a Hallgr\u00edmskirkja<\/b>, uma igreja de visual inusitado que me lembrou mais uma nave espacial. Com bom tempo, voc\u00ea pode at\u00e9 subir na torre da igreja por cerca de 8 \u20ac. <b>Confira a futurista sala de concertos Harpa<\/b> e, claro, n\u00e3o deixe de ver <strong>o The Sun Voyager, escultura moderna de um barco na orla \u2013 provavelmente a atra\u00e7\u00e3o mais popular de Reykjav\u00edk<\/strong>.<\/p>\n<figure id=\"attachment_53871\" aria-describedby=\"caption-attachment-53871\" style=\"width: 650px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-53871\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/island_krajina.jpg\" alt=\"A Isl\u00e2ndia \u00e9 uma surpresa atr\u00e1s da outra e com certeza vale a visita\" width=\"650\" height=\"433\" title=\"\"><figcaption id=\"caption-attachment-53871\" class=\"wp-caption-text\">A Isl\u00e2ndia \u00e9 uma surpresa atr\u00e1s da outra e com certeza vale a visita<\/figcaption><\/figure>\n<p><strong>Quer saber quanto gastamos no total? O or\u00e7amento detalhado est\u00e1 no <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143104\">nosso outro artigo<\/a><\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mapa_da_rota_pela_Islandia_para_download\"><\/span><span class=\"ez-toc-section\" id=\"Mapa_da_rota_pela_Islandia_para_download\"><\/span>Mapa da rota pela Isl\u00e2ndia para download<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n[mailerlite_form form_id=6]\n[amp-optin id=55426]\n<h2><span class=\"ez-toc-section\" id=\"Dicas_e_truques_para_viajar_pela_Islandia\"><\/span><span class=\"ez-toc-section\" id=\"Dicas_e_truques_para_viajar_pela_Islandia\"><\/span>Dicas e truques para viajar pela Isl\u00e2ndia<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table border=\"2\">\n<tbody>\n<tr>\n<td style=\"width: 865px;\">\n<h3><span class=\"ez-toc-section\" id=\"O_que_levar_na_mala\"><\/span><span style=\"font-size: 18pt;\"><strong>O que levar na mala<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Confira nosso <a href=\"https:\/\/loudavymkrokem.cz\/vybaveni-na-cesty\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>guia para fazer as malas<\/strong><\/a>, que vai te ajudar na prepara\u00e7\u00e3o. Escolha a mochila certa, veja <a href=\"https:\/\/www.zapakuj.cz\/kempovani\/\" target=\"_blank\" rel=\"noopener\">acess\u00f3rios \u00fateis para viagem<\/a> e n\u00e3o esque\u00e7a nada importante em casa.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Onde_encontrar_passagens_aereas\"><\/span><span style=\"font-size: 18pt;\"><strong>Onde encontrar passagens a\u00e9reas<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Procure passagens baratas no <strong><a title=\"Kiwi\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/kiwi\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Kiwi<\/a><\/strong>, nosso buscador favorito. Saindo do Brasil, a Icelandair opera voos com conex\u00e3o a partir de cidades norte-americanas, e companhias como LATAM ou Azul oferecem boas conex\u00f5es at\u00e9 a Europa, de onde \u00e9 f\u00e1cil chegar a Reykjav\u00edk. Confira nosso <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143120\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>guia de como encontrar passagens baratas<\/strong><\/a>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Aluguel_de_carro\"><\/span><span style=\"font-size: 18pt;\"><strong>Aluguel de carro<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Normalmente usamos o comparador <strong><a class=\"thirstylink\" title=\"RentalCars.com\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/rentalcars-com\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\" data-shortcode=\"true\">RentalCars.com<\/a><\/strong>, que nos ajuda a escolher a melhor locadora de ve\u00edculos.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Reserva_de_hospedagem\"><\/span><span style=\"font-size: 18pt;\"><strong>Reserva de hospedagem<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong><a title=\"Booking.com\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/booking-com\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">Booking.com<\/a><\/strong> \u00e9 nosso buscador de hot\u00e9is favorito. Sempre comparamos os hot\u00e9is com ofertas de apartamentos e quartos no Airbnb (<strong><a title=\"AirBNB\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/airbnb\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\">confira os descontos<\/a><\/strong>). Leia como <a href=\"https:\/\/loudavymkrokem.cz\/pt-br\/?p=143121\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>n\u00f3s encontramos hospedagem barata<\/strong><\/a>.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Nao_esqueca_o_seguro_viagem\"><\/span><span style=\"font-size: 18pt;\"><strong>N\u00e3o esque\u00e7a o seguro viagem<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>Seguro viagem<\/strong> \u00e9 absolutamente essencial. Para viagens mais curtas, escolhemos a AXA (<a class=\"thirstylink\" title=\"Axa cestovn\u00ed poji\u0161t\u011bn\u00ed\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/axa-cestovni-pojisteni\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\" data-shortcode=\"true\"><strong>50% de desconto<\/strong><\/a>) e para viagens mais longas, a seguradora brit\u00e2nica <strong><a class=\"thirstylink\" title=\"True Traveller\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/true-traveller\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored\" data-shortcode=\"true\">True Traveller<\/a><\/strong>. Confira nossa <strong><a href=\"https:\/\/loudavymkrokem.cz\/nejlepsi-cestovni-pojisteni\/\" target=\"_blank\" rel=\"noopener noreferrer\">compara\u00e7\u00e3o de seguradoras<\/a><\/strong> e escolha a que melhor se encaixa para voc\u00ea.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Outros_roteiros_para_a_Islandia\"><\/span><b>Outros roteiros para a Isl\u00e2ndia<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div>Roteiros bem elaborados e testados na pr\u00e1tica para a Isl\u00e2ndia <strong><a href=\"http:\/\/retkee.com\/cs\/destinace\/island\/#itinerare\" target=\"_blank\" rel=\"noopener\"><u>voc\u00ea tamb\u00e9m encontra na plataforma Retkee<\/u><\/a><\/strong>. Eles descrevem, por exemplo, o circuito completo da Ring Road e uma expedi\u00e7\u00e3o de inverno cheia de aventura.<\/div>\n<div><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Quer saber como aproveitar ao m\u00e1ximo 14-15 dias na Isl\u00e2ndia? Preparamos um roteiro completo de road trip pela Isl\u00e2ndia com mapa da rota e dicas de hospedagem. Lembre-se: a Isl\u00e2ndia \u00e9 uma surpresa atr\u00e1s da outra e em 14 dias voc\u00ea n\u00e3o consegue ver tudo!<\/p>\n","protected":false},"author":3,"featured_media":53885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"Road Trip pela Isl\u00e2ndia: Roteiro de 14 Dias + Dicas","rank_math_description":"Planeje seu road trip pela Isl\u00e2ndia com nosso roteiro de 14 dias, mapa da rota e dicas de hospedagem. Descubra os melhores lugares para visitar!","rank_math_focus_keyword":"road trip pela Isl\u00e2ndia","rank_math_seo_score":""},"categories":[1121,1136],"tags":[],"class_list":{"0":"post-143111","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-europa","8":"category-islandia"},"featured_image_src":"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2019\/01\/Polarni_zare_Island.jpg","author_info":{"display_name":"Lucie Kone\u010dn\u00e1","author_link":"https:\/\/loudavymkrokem.cz\/pt-br\/author\/lucie-konecna\/"},"_links":{"self":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/comments?post=143111"}],"version-history":[{"count":1,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143111\/revisions"}],"predecessor-version":[{"id":144327,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/posts\/143111\/revisions\/144327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/media\/53885"}],"wp:attachment":[{"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/media?parent=143111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/categories?post=143111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/pt-br\/wp-json\/wp\/v2\/tags?post=143111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}