{"id":125815,"date":"2019-06-10T19:31:26","date_gmt":"2019-06-10T17:31:26","guid":{"rendered":"https:\/\/loudavymkrokem.cz\/yucatan-mayske-ruiny\/"},"modified":"2025-12-19T14:42:50","modified_gmt":"2025-12-19T13:42:50","slug":"yucatan-messico-rovine-maya","status":"publish","type":"post","link":"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/","title":{"rendered":"Yucat\u00e1n, Messico: Le migliori rovine Maya da visitare"},"content":{"rendered":"<p>Le rovine delle citt\u00e0 dell&#8217;antica civilt\u00e0 Maya si trovano in tutto lo Yucat\u00e1n e sono la cosa pi\u00f9 interessante che puoi vivere nella penisola messicana. Vieni con noi sulle orme dei Maya. <\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenuto dell&#039;articolo<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#La_civilta_Maya_nella_penisola_dello_Yucatan\" >La civilt\u00e0 Maya nella penisola dello Yucat\u00e1n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Chichen_Itza_%E2%80%93_nuova_meraviglia_del_mondo\" >Chichen Itza &#8211; nuova meraviglia del mondo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Tulum_%E2%80%93_citta_portuale_con_spiaggia\" >Tulum &#8211; citt\u00e0 portuale con spiaggia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Coba_%E2%80%93_rovine_accessibili_senza_turisti\" >Coba &#8211; rovine accessibili senza turisti<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Uxmal_%E2%80%93_rovine_uniche_vicino_a_Merida\" >Uxmal &#8211; rovine uniche vicino a M\u00e9rida<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Calakmul_%E2%80%93_gioiello_nel_cuore_della_giungla\" >Calakmul &#8211; gioiello nel cuore della giungla<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Becan_%E2%80%93_rovine_direttamente_sulla_strada\" >Becan &#8211; rovine direttamente sulla strada<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Kohunlich\" >Kohunlich<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Mappa_della_posizione_delle_rovine_Maya_nello_Yucatan\" >Mappa della posizione delle rovine Maya nello Yucat\u00e1n<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Consigli_e_trucchi_per_viaggiare_in_Messico\" >Consigli e trucchi per viaggiare in Messico<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Cosa_mettere_in_valigia\" >Cosa mettere in valigia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Dove_trovare_i_biglietti_aerei\" >Dove trovare i biglietti aerei<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Noleggio_auto\" >Noleggio auto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Prenotazione_alloggi\" >Prenotazione alloggi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Non_dimenticare_lassicurazione\" >Non dimenticare l&#8217;assicurazione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/loudavymkrokem.cz\/it\/yucatan-messico-rovine-maya\/#Guida_che_consigliamo_Lonely_Planet_Yucatan\" >Guida che consigliamo: Lonely Planet Yucatan<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"La_civilta_Maya_nella_penisola_dello_Yucatan\"><\/span><strong>La civilt\u00e0 Maya nella penisola dello Yucat\u00e1n<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>La civilt\u00e0 Maya fu una delle culture pi\u00f9 avanzate dell&#8217;emisfero occidentale, almeno fino a quando gli Europei non scoprirono il Nord America.<\/p>\n<p><strong>I Maya conobbero il loro massimo splendore tra il 300 e il 900 d.C. e il loro impero si estendeva sul territorio dell&#8217;attuale Messico meridionale, Guatemala, Honduras e Belize settentrionale.<\/strong> In totale si trattava di pi\u00f9 di 40 citt\u00e0-stato e quelle che si sono conservate sotto gli strati della giungla sono oggi designate come patrimonio mondiale.<\/p>\n<p><strong>Le citt\u00e0 Maya sono piene di templi in pietra, piramidi, campi da gioco e quartieri residenziali.<\/strong> Le citt\u00e0 servivano principalmente come dimora per i leader locali, i re e per le attivit\u00e0 religiose.<\/p>\n<p>I Maya sono noti soprattutto per le loro eccellenti conoscenze di matematica e astronomia. Queste scienze erano strettamente legate al culto degli dei Maya. <\/p>\n<p><strong>Diamo un&#8217;occhiata insieme a sette vaste citt\u00e0 Maya che si sono conservate fino ad oggi e possono essere visitate.<\/strong> Se ti stai preparando per lo Yucat\u00e1n e hai intenzione di seguire le orme dei Maya, ti consigliamo di prenotare almeno 14 giorni.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Chichen_Itza_%E2%80%93_nuova_meraviglia_del_mondo\"><\/span><strong>Chichen Itza &#8211; nuova meraviglia del mondo<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54818\" aria-describedby=\"caption-attachment-54818\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54818\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/el-castillo.jpg\" alt=\"Piramide di El Castillo nella citt\u00e0 Maya di Chichen Itza\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54818\" class=\"wp-caption-text\">Piramide El Castillo<\/figcaption><\/figure>\n<p><strong><a href=\"https:\/\/loudavymkrokem.cz\/it\/chichen-itza-messico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Chichen Itza<\/a> sono le rovine pi\u00f9 visitate e allo stesso tempo pi\u00f9 costose di tutto lo Yucat\u00e1n, ma c&#8217;\u00e8 un motivo.<\/strong> Qui si trovano in totale 18 edifici restaurati, di cui il pi\u00f9 famoso \u00e8 la piramide di Kukulcan.<\/p>\n<p>Nei giorni degli equinozi (21 marzo e 21 settembre) il sole al tramonto crea un&#8217;ombra perfetta che forma la sagoma di un serpente che scende sulle scale della piramide. Sotto la piramide si trova anche una grotta con un lago sotterraneo, ma purtroppo non potrai visitarla. <\/p>\n<p><strong>Nel complesso urbano troverai uno dei luoghi meglio conservati, dove si giocava il famoso gioco della palla religioso Tlachtli.<\/strong> A quanto pare, dopo la partita, o il capitano o un&#8217;intera squadra venivano sacrificati agli dei nel vicino cenote.<\/p>\n<p>Un&#8217;altra struttura interessante \u00e8 il cosiddetto <em>Osservatorio<\/em>, il cui tetto ha una forma a cupola e non \u00e8 completamente chiuso. Molto probabilmente serviva agli astrologi Maya per l&#8217;osservazione delle stelle. <\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Chichen Itza<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 480 pesos \/ 577 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Valladolid, Playa del Carmen, Canc\u00fan<\/li>\n<li><strong>Orario di apertura: <\/strong>9:00 &#8211; 17:00, spettacolo notturno dalle 19:00 o 20:00 a seconda della stagione<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/www.inah.gob.mx\/zonas\/146-zona-arqueologica-de-chichen-itza\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica de Chich\u00e9n Itz\u00e1<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Tulum_%E2%80%93_citta_portuale_con_spiaggia\"><\/span><strong>Tulum &#8211; citt\u00e0 portuale con spiaggia<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54666\" aria-describedby=\"caption-attachment-54666\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54666\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Tulum_ruins.jpg\" alt=\"Rovine di Tulum\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54666\" class=\"wp-caption-text\">Rovine di Tulum<\/figcaption><\/figure>\n<p>La citt\u00e0 Maya sul sito dell&#8217;attuale <a href=\"https:\/\/loudavymkrokem.cz\/tulum\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tulum<\/a> (130 chilometri a sud di Canc\u00fan) era un porto marittimo con la sua ampia spiaggia e una cinta muraria difensiva che circonda la citt\u00e0 su tre lati.<\/p>\n<p>Gli edifici qui sono molto ben conservati, ma a differenza delle citt\u00e0 meno visitate, non si trovano nella giungla. Per questo ti consigliamo di partire per la visita la mattina presto, prima che arrivi il caldo intenso. <\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Tulum<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 70 pesos \/ 84 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Tulum, Playa del Carmen, Canc\u00fan<\/li>\n<li><strong>Orario di apertura: <\/strong>8:00 &#8211; 17:00, possibilit\u00e0 di visita serale\/notturna<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/www.inah.gob.mx\/zonas\/99-zona-arqueologica-de-tulum\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica de Tulum<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Coba_%E2%80%93_rovine_accessibili_senza_turisti\"><\/span><strong>Coba &#8211; rovine accessibili senza turisti<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54880\" aria-describedby=\"caption-attachment-54880\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54880\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/mala-pyramida-coba-2.jpg\" alt=\"piccola piramide nelle rovine Maya di Coba\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54880\" class=\"wp-caption-text\">Si consiglia di noleggiare una bicicletta, risparmierai molto tempo<\/figcaption><\/figure>\n<p><strong>Gli archeologi ritengono che la <a href=\"https:\/\/loudavymkrokem.cz\/ruiny-coba\/\" target=\"_blank\" rel=\"noopener noreferrer\">citt\u00e0 di Coba<\/a> fosse estremamente importante per i Maya, ma non \u00e8 ancora diventata una meta troppo turistica.<\/strong> Per questo \u00e8 possibile salire sulla piramide pi\u00f9 alta e godersi molte strutture in solitudine.<\/p>\n<p>Oltre all&#8217;iconica piramide di Ixmoja, che misura 42 metri, qui troverai diversi campi da gioco ben conservati e strutture pi\u00f9 piccole. La maggior parte della citt\u00e0 \u00e8 ancora inaccessibile e coperta da una fitta giungla. <\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Coba<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 75 pesos \/ 100 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Tulum, Playa del Carmen, Valladolid<\/li>\n<li><strong>Orario di apertura: <\/strong>8:00 &#8211; 17:00<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/inah.gob.mx\/zonas\/515-zona-arqueologica-de-coba\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica de Coba<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Uxmal_%E2%80%93_rovine_uniche_vicino_a_Merida\"><\/span><strong>Uxmal &#8211; rovine uniche vicino a M\u00e9rida<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54805\" aria-describedby=\"caption-attachment-54805\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54805\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/Uxmal.jpg\" alt=\"{%ALT_TEXT%}\" width=\"1200\" height=\"900\" title=\"\"><figcaption id=\"caption-attachment-54805\" class=\"wp-caption-text\">{%CAPTION%}<\/figcaption><\/figure>\n<p>La citt\u00e0 di Uxmal (pronunciata Oshmal) fu una delle pi\u00f9 importanti citt\u00e0 Maya. Fu costruita tra il quinto e il sesto secolo, ma gli scavi dimostrano che il luogo era abitato gi\u00e0 dall&#8217;ottavo secolo a.C. <\/p>\n<p>\u00c8 interessante notare che la citt\u00e0 fu costruita esclusivamente nello stile Maya Puuc. Questo \u00e8 strano, perch\u00e9 le citt\u00e0 pi\u00f9 piccole nei dintorni mostrano segni di diversi stili, poich\u00e9 le culture locali si influenzavano a vicenda. <\/p>\n<p><strong>La struttura pi\u00f9 significativa \u00e8 la Piramide del Mago, che ha un totale di quattro annessi.<\/strong><\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Uxmal<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 470 pesos \/ 570 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Campeche, M\u00e9rida<\/li>\n<li><strong>Orario di apertura: <\/strong>8:00 &#8211; 17:00<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/www.inah.gob.mx\/zonas\/110-zona-arqueologica-de-uxmal\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica de Uxmal<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Calakmul_%E2%80%93_gioiello_nel_cuore_della_giungla\"><\/span><strong>Calakmul &#8211; gioiello nel cuore della giungla<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54891\" aria-describedby=\"caption-attachment-54891\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54891\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/struktura-1-calakmul.jpg\" alt=\"Struttura n. 1, una delle due piramidi centrali\" width=\"1200\" height=\"900\" title=\"\"><figcaption id=\"caption-attachment-54891\" class=\"wp-caption-text\">Struttura n. 1, una delle due piramidi centrali<\/figcaption><\/figure>\n<p><strong><a href=\"https:\/\/loudavymkrokem.cz\/ruiny-calakmul\/\" target=\"_blank\" rel=\"noopener noreferrer\">Calakmul<\/a> \u00e8 uno dei complessi urbani che sono davvero difficilmente accessibili per il turista comune.<\/strong> Si trova a 60 km dalla strada asfaltata pi\u00f9 vicina e a tre ore di auto dalle grandi citt\u00e0 pi\u00f9 vicine. Tanto pi\u00f9 ha conservato l&#8217;atmosfera antica. <\/p>\n<p><strong>Questa citt\u00e0 Maya \u00e8 enorme, e per questo ti consigliamo di dedicare un&#8217;intera giornata a questa escursione.<\/strong> Nella giungla qui troverai, oltre a innumerevoli edifici pi\u00f9 piccoli, anche due piramidi gigantesche, una delle quali \u00e8 la seconda piramide Maya pi\u00f9 grande mai scoperta. Misura 55 metri di altezza e, naturalmente, puoi scalarla. <\/p>\n<p>Durante la nostra visita abbiamo condiviso l&#8217;intero complesso solo con trenta turisti e ci siamo goduti la maggior parte dei panorami completamente da soli. Ci hanno fatto compagnia solo due famiglie di scimmie urlatrici (scimmie estremamente rumorose). <\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Calakmul<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 75 pesos \/ 90 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Xpujil, Campeche<\/li>\n<li><strong>Orario di apertura: <\/strong>8:00 &#8211; 17:00<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/www.inah.gob.mx\/zonas\/62-zona-arqueologica-de-calakmul\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica de Calakmul<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Becan_%E2%80%93_rovine_direttamente_sulla_strada\"><\/span><strong>Becan &#8211; rovine direttamente sulla strada<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54896\" aria-describedby=\"caption-attachment-54896\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54896\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/ruiny-becan.jpg\" alt=\"\" width=\"1200\" height=\"900\" title=\"\"><figcaption id=\"caption-attachment-54896\" class=\"wp-caption-text\">Vista delle rovine di Becan vicino alla cittadina di Xpujil<\/figcaption><\/figure>\n<p>La citt\u00e0 di Becan fu scoperta solo nel 1934 e la maggior parte degli edifici giace ancora in profondit\u00e0 sotto secoli di depositi di terra. Anche se vedi la piramide principale direttamente dalla strada trafficata, pochi si fermano qui. <\/p>\n<p><strong>Tra pi\u00f9 di 20 edifici e piramidi scoperti, abbiamo camminato completamente da soli, \u00e8 apparso solo un anziano messicano che ci ha preso sotto la sua ala e ci ha guidato attraverso l&#8217;intera citt\u00e0 in spagnolo.<\/strong><\/p>\n<p>Becan \u00e8 costruita nello stile R\u00edo Bec (fiume Bec) e un tempo era la capitale politica, economica, militare e religiosa dell&#8217;intera provincia di R\u00edo Bec.<\/p>\n<p>La citt\u00e0 \u00e8 unica per il suo fossato che circonda il centro della citt\u00e0, dove si ergono diverse piramidi e importanti edifici.<\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Becan<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 60 pesos \/ 70 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Xpujil, Campeche<\/li>\n<li><strong>Orario di apertura: <\/strong>8:00 &#8211; 17:00<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/www.inah.gob.mx\/zonas\/61-zona-arqueologica-de-becan\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica de Bec\u00e1n<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Kohunlich\"><\/span><strong>Kohunlich<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<figure id=\"attachment_54751\" aria-describedby=\"caption-attachment-54751\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-54751\" src=\"https:\/\/www.loudavymkrokem.cz\/wp-content\/uploads\/2023\/05\/kohunlich-mayske-ruiny.jpg\" alt=\"Rovine Maya di Kohunlich\" width=\"1200\" height=\"800\" title=\"\"><figcaption id=\"caption-attachment-54751\" class=\"wp-caption-text\">Scale per l&#8217;edificio pi\u00f9 alto delle rovine Maya di Kohunlich<\/figcaption><\/figure>\n<p>Le ultime rovine che abbiamo visitato e che meritano sicuramente una visita, si trovano di nuovo nel cuore della giungla nel sud della provincia messicana di Quintana Roo e distano solo 9 km dalla strada asfaltata pi\u00f9 vicina.<\/p>\n<p>La citt\u00e0 di Kohunlich fu fondata probabilmente intorno al 200 a.C., ma la maggior parte degli edifici importanti fu costruita tra il terzo e il sesto secolo.<\/p>\n<p><strong>Sul posto troverai un totale di 8 grandi gruppi di edifici, che servivano come centri amministrativi, luoghi spirituali, palazzi e aree residenziali.<\/strong><\/p>\n<p>Il fatto che l&#8217;intera citt\u00e0 sia nel profondo della giungla invita direttamente all&#8217;esplorazione dei dintorni. L&#8217;ombra per tutto il giorno permette di trascorrere lunghe ore tra le rovine. <\/p>\n<div class=\"su-box su-box-style-soft\" id=\"\" style=\"border-color:318912;border-radius:0px;max-width:none\"><div class=\"su-box-title\" style=\"background-color:318912;color:#000000;border-top-left-radius:0px;border-top-right-radius:0px\">Informazioni su Kohunlich<\/div><div class=\"su-box-content su-u-clearfix su-u-trim\" style=\"border-bottom-left-radius:0px;border-bottom-right-radius:0px\">\n<ul>\n<li><strong>Ingresso:<\/strong> 70 pesos \/ 80 K\u010d<\/li>\n<li><strong>Citt\u00e0 pi\u00f9 vicina:<\/strong> Xpujil, Bacalar<\/li>\n<li><strong>Orario di apertura: <\/strong>8:00 &#8211; 17:00<\/li>\n<li><strong>Sito web<\/strong>: <strong><a href=\"https:\/\/www.inah.gob.mx\/zonas\/103-zona-arqueologica-kohunlich\" target=\"_blank\" rel=\"noopener noreferrer\">Zona Arqueol\u00f3gica Kohunlich<\/a><\/strong><\/li>\n<\/ul>\n<\/div><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Mappa_della_posizione_delle_rovine_Maya_nello_Yucatan\"><\/span>Mappa della posizione delle rovine Maya nello Yucat\u00e1n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<div class=\"map-responsive\"><iframe loading=\"lazy\" src=\"https:\/\/www.google.com\/maps\/d\/embed?mid=1iNI19SOF5UZME5B53rInai-rTW2UXZSw\" width=\"600\" height=\"480\" align=\"center\" data-mce-fragment=\"1\"><span data-mce-type=\"bookmark\" style=\"display: inline-block; width: 0px; overflow: hidden; line-height: 0;\" class=\"mce_SELRES_start\"><\/span><\/iframe><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Consigli_e_trucchi_per_viaggiare_in_Messico\"><\/span>Consigli e trucchi per viaggiare in Messico<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<table border=\"2\">\n<tbody>\n<tr>\n<td style=\"width: 865px;\">\n<h3><span class=\"ez-toc-section\" id=\"Cosa_mettere_in_valigia\"><\/span><span style=\"font-size: 18pt;\"><strong>Cosa mettere in valigia<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Dai un&#8217;occhiata alla nostra <a href=\"https:\/\/loudavymkrokem.cz\/vybaveni-na-cesty\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>guida per preparare la valigia<\/strong><\/a>, che ti aiuter\u00e0 con i preparativi. Scegli lo zaino da viaggio giusto, dai un&#8217;occhiata ai gadget da viaggio e non dimenticare nulla di importante a casa. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Dove_trovare_i_biglietti_aerei\"><\/span><span style=\"font-size: 18pt;\"><strong>Dove trovare i biglietti aerei<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Cerca voli economici su <strong><a title=\"Kiwi\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/kiwi\/\" target=\"_blank\" rel=\"noopener noreferrer\">Kiwi<\/a><\/strong>, \u00e8 il nostro portale preferito. Assicurati di leggere la nostra <a href=\"https:\/\/loudavymkrokem.cz\/jak-na-letenky\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>guida<\/strong> <strong>su come trovare voli economici<\/strong><\/a>. <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Noleggio_auto\"><\/span><span style=\"font-size: 18pt;\"><strong>Noleggio auto<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Di solito usiamo il comparatore <strong><a class=\"thirstylink\" title=\"RentalCars.com\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/rentalcars-com\/\" target=\"_blank\" rel=\"noopener noreferrer\">RentalCars.com<\/a><\/strong>, che ci aiuta a scegliere un fornitore di auto.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Prenotazione_alloggi\"><\/span><span style=\"font-size: 18pt;\"><strong>Prenotazione alloggi<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong><a title=\"Booking.com\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/booking-com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Booking.com<\/a><\/strong> \u00e8 il nostro motore di ricerca di hotel preferito. Confrontiamo sempre gli hotel con l&#8217;offerta di appartamenti e camere locali su Airbnb (<g id=\"gid_2\"><g id=\"gid_3\">725 K\u010d di sconto<\/g><\/g>). Leggi <a href=\"https:\/\/loudavymkrokem.cz\/levne-ubytovani\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>come cerchiamo noi alloggi economici<\/strong><\/a>.  <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Non_dimenticare_lassicurazione\"><\/span><span style=\"font-size: 18pt;\"><strong>Non dimenticare l&#8217;assicurazione<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><strong>L&#8217;assicurazione di viaggio<\/strong> \u00e8 un must assoluto. Per i viaggi pi\u00f9 brevi scegliamo AXA (<g id=\"gid_1\"><g id=\"gid_2\">50% di sconto<\/g><\/g>) e per i viaggi pi\u00f9 lunghi la compagnia assicurativa britannica <g id=\"gid_3\"><g id=\"gid_4\"><a class=\"thirstylink\" rel=\"nofollow\" target=\"_blank\" title=\"True Traveller\" href=\"https:\/\/loudavymkrokem.cz\/it\/doporucujeme\/true-traveller\/\" data-shortcode=\"true\">True Traveller<\/a><\/g><\/g>. Dai un&#8217;occhiata al <strong><a href=\"https:\/\/loudavymkrokem.cz\/nejlepsi-cestovni-pojisteni\/\" target=\"_blank\" rel=\"noopener noreferrer\">confronto di tutte le compagnie assicurative<\/a><\/strong> e scegli quella pi\u00f9 adatta a te.  <\/p>\n<h3><span class=\"ez-toc-section\" id=\"Guida_che_consigliamo_Lonely_Planet_Yucatan\"><\/span><strong>Guida che consigliamo<\/strong>: <a title=\"Lonely Planet Yucatan\" href=\"https:\/\/loudavymkrokem.cz\/doporucujeme\/lonely-planet-yucatan\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lonely Planet Yucatan<\/a><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le rovine delle citt\u00e0 dell&#8217;antica civilt\u00e0 Maya si trovano in tutto lo Yucat\u00e1n e sono la cosa pi\u00f9 interessante che puoi vivere nella penisola messicana. Vieni con noi sulle orme dei Maya. La civilt\u00e0 Maya nella penisola dello Yucat\u00e1n La civilt\u00e0 Maya fu una delle culture pi\u00f9 avanzate dell&#8217;emisfero occidentale, almeno fino a quando gli [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":125822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","rank_math_title":"Rovine Maya: Il meglio dello Yucat\u00e1n messicano | Loudav\u00fdm krokem","rank_math_description":"Le rovine Maya sono le destinazioni turistiche pi\u00f9 popolari nello Yucat\u00e1n. Ti mostreremo tutte le localit\u00e0 delle rovine che meritano una visita. ","rank_math_focus_keyword":"","rank_math_seo_score":""},"categories":[635,569],"tags":[],"class_list":{"0":"post-125815","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-messico","8":"category-nord-america"},"featured_image_src":"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2019\/04\/Uxmal.jpg","author_info":{"display_name":"Luk\u00e1\u0161 Kone\u010dn\u00fd","author_link":"https:\/\/loudavymkrokem.cz\/it\/author\/lukas-konecny\/"},"_links":{"self":[{"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/posts\/125815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/comments?post=125815"}],"version-history":[{"count":1,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/posts\/125815\/revisions"}],"predecessor-version":[{"id":127151,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/posts\/125815\/revisions\/127151"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/media\/125822"}],"wp:attachment":[{"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/media?parent=125815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/categories?post=125815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/it\/wp-json\/wp\/v2\/tags?post=125815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}