{"id":161308,"date":"2026-05-14T14:24:03","date_gmt":"2026-05-14T12:24:03","guid":{"rendered":"https:\/\/loudavymkrokem.cz\/?p=161308"},"modified":"2026-07-13T01:48:51","modified_gmt":"2026-07-12T23:48:51","slug":"emily-in-paris-drehorte","status":"publish","type":"post","link":"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/","title":{"rendered":"Emily in Paris: 15 Drehorte in Paris, die du besuchen kannst (Location-Guide)"},"content":{"rendered":"<p>Wenn Luk\u00e1\u0161 und ich abends auf der Couch sitzen, nachdem unser Kleiner eingeschlafen ist, suchen wir bei Netflix oft nach etwas Entspannendem \u2013 und genau so sind wir auf die Serie Emily in Paris gesto\u00dfen. <strong>Klar, es ist ein riesiges Klischee, alles ist ziemlich \u00fcbertrieben und Paris sieht aus wie durch einen perfekten Instagram-Filter, aber ich muss zugeben: Uns hat es beide gepackt und wir haben dabei wunderbar abgeschaltet. Man kann sich einfach nicht dagegen wehren, dass einen die romantische Atmosph\u00e4re und die wundersch\u00f6nen Gassen in den Bann ziehen \u2013 und pl\u00f6tzlich will man alle Emily in Paris Drehorte selbst besuchen.<\/strong><\/p>\n\n\n\n<p>Wir waren erst k\u00fcrzlich mit unserem Kleinkind in Paris Frankreich, deshalb muss ich ehrlich gestehen: Das Abklappern von Seriendrehorten lie\u00df sich mit Kinderwagen und Baby-Rhythmus nicht wirklich vereinbaren. Wir sind nicht von Caf\u00e9 zu Caf\u00e9 gerannt und haben uns nicht vor der B\u00e4ckerei fotografiert, weil wir schlicht andere Priorit\u00e4ten hatten. Aber das Thema hat mich so fasziniert, dass ich mir dachte: H\u00e4tten wir mehr Zeit und freie H\u00e4nde gehabt, h\u00e4tten wir uns diese Orte liebend gern angeschaut. Also habe ich gr\u00fcndlich recherchiert, alle wundersch\u00f6nen Drehorte der Serie ausfindig gemacht und daraus diesen Guide zusammengestellt.<\/p>\n\n\n\n<p>In diesem Artikel findest du 15 Drehorte von Emily in Paris \u2013 von Emilys ber\u00fchmter Wohnung \u00fcber die duftende B\u00e4ckerei und Gabriels Restaurant bis hin zu ikonischen Caf\u00e9s und historischen Br\u00fccken \u00fcber der Seine. Ich zeige dir nicht nur, wo genau diese Orte liegen und in welchen Folgen sie vorkommen, sondern auch, was dort ein Kaffee oder ein Essen kostet, damit du vor Ort nicht unangenehm \u00fcberrascht wirst. Paris kann n\u00e4mlich ganz sch\u00f6n teuer sein, und manche Leute nehmen die Serie gerade wegen ihrer Unrealistik nicht ganz ernst. Wenn du das Ganze aber mit einem Augenzwinkern angehst, erwartet dich ein zauberhafter Ausflug auf den Spuren von Emily.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-obsazeni.jpg\" alt=\"Hauptbesetzung der Serie Emily in Paris\" class=\"wp-image-159191\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-obsazeni.jpg 1280w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-obsazeni-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-obsazeni-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-obsazeni-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-obsazeni-696x392.jpg 696w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Hauptbesetzung der Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Artikelinhalt<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Zusammenfassung\" >Zusammenfassung<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Auf_den_Spuren_von_Emily_in_Paris_so_gehts_wann_wie_viele_Staffeln_Route_Anreise\" >Auf den Spuren von Emily in Paris: so geht&#8217;s (wann, wie viele Staffeln, Route, Anreise)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Wo_uebernachten_damit_die_Drehorte_um_die_Ecke_liegen\" >Wo \u00fcbernachten, damit die Drehorte um die Ecke liegen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#5_Arrondissement_Emilys_Nachbarschaft_das_Herzstueck_aller_Drehorte\" >5. Arrondissement: Emilys Nachbarschaft (das Herzst\u00fcck aller Drehorte)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#1_Emilys_Haus_am_Place_de_lEstrapade\" >1. Emilys Haus am Place de l&#8217;Estrapade<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#2_Boulangerie_Moderne_%E2%80%94_Emilys_Baeckerei\" >2. Boulangerie Moderne \u2014 Emilys B\u00e4ckerei<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#3_Terra_Nera_%E2%80%94_Gabriels_Restaurant\" >3. Terra Nera \u2014 Gabriels Restaurant<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#4_Pantheon\" >4. Panth\u00e9on<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#5_Jardin_du_Luxembourg_Luxemburggarten\" >5. Jardin du Luxembourg (Luxemburggarten)<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#1_Arrondissement_wo_Emily_arbeitet_Savoir_und_Palais_Royal\" >1. Arrondissement: wo Emily arbeitet (Savoir und Palais Royal)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#6_Place_de_Valois_%E2%80%94_Agentur_Savoir_Agence_Grateau\" >6. Place de Valois \u2014 Agentur Savoir \/ Agence Grateau<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#7_Jardin_du_Palais_Royal_%E2%80%94_die_gestreiften_Saeulen\" >7. Jardin du Palais Royal \u2014 die gestreiften S\u00e4ulen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#8_Le_Grand_Vefour_%E2%80%94_das_Restaurant_in_das_Emily_vergeblich_will\" >8. Le Grand V\u00e9four \u2014 das Restaurant, in das Emily vergeblich will<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Saint-Germain_beruehmte_und_ziemlich_teure_Cafes\" >Saint-Germain: ber\u00fchmte (und ziemlich teure) Caf\u00e9s<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#9_Cafe_de_Flore\" >9. Caf\u00e9 de Flore<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#10_Les_Deux_Magots\" >10. Les Deux Magots<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Montmartre_die_fotogensten_Szenen_der_Serie\" >Montmartre: die fotogensten Szenen der Serie<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#11_La_Maison_Rose\" >11. La Maison Rose<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#12_Le_Mur_des_Je_taime_die_Liebeswand\" >12. Le Mur des Je t&#8217;aime (die Liebeswand)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#13_Sacre-Coeur\" >13. Sacr\u00e9-C\u0153ur<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Bruecken_und_grosse_Szenen_Parfuem_Strassenmusik_und_Seine\" >Br\u00fccken und gro\u00dfe Szenen: Parf\u00fcm, Stra\u00dfenmusik und Seine<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#14_Pont_Alexandre_III\" >14. Pont Alexandre III<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-23\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#15_Pont_des_Arts\" >15. Pont des Arts<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-24\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Wo_essen_auf_Emilys_Spuren_ohne_zweite_Hypothek\" >Wo essen auf Emilys Spuren (ohne zweite Hypothek)<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-25\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Bevor_du_losgehst_sei_ruecksichtsvoll_gegenueber_den_Anwohnern\" >Bevor du losgehst: sei r\u00fccksichtsvoll gegen\u00fcber den Anwohnern<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-26\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Weiterlesen\" >Weiterlesen<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-27\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Haeufig_gestellte_Fragen_FAQ\" >H\u00e4ufig gestellte Fragen (FAQ)<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-28\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Wo_wurde_die_Wohnung_aus_Emily_in_Paris_gedreht\" >Wo wurde die Wohnung aus Emily in Paris gedreht?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-29\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Kann_man_Emilys_Wohnung_von_innen_besichtigen\" >Kann man Emilys Wohnung von innen besichtigen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-30\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Welches_Restaurant_ist_Gabriels_Restaurant\" >Welches Restaurant ist Gabriels Restaurant?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-31\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Kann_man_alle_Drehorte_an_einem_Tag_zu_Fuss_ablaufen\" >Kann man alle Drehorte an einem Tag zu Fu\u00df ablaufen?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-32\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Gibt_es_gefuehrte_Touren_zu_den_Emily_in_Paris_Drehorten\" >Gibt es gef\u00fchrte Touren zu den Emily in Paris Drehorten?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-33\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Wo_ist_die_Baeckerei_aus_Emily_in_Paris\" >Wo ist die B\u00e4ckerei aus Emily in Paris?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-34\" href=\"https:\/\/loudavymkrokem.cz\/de\/emily-in-paris-drehorte\/#Wurde_die_5_Staffel_in_Paris_gedreht\" >Wurde die 5. Staffel in Paris gedreht?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Zusammenfassung\"><\/span><span class=\"ez-toc-section\" id=\"Zusammenfassung\"><\/span>Zusammenfassung<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Das Herzst\u00fcck der Serie und die bekanntesten Drehorte findest du im 5. Pariser Arrondissement (Quartier Latin), wo alles nur wenige Schritte voneinander entfernt liegt.<\/li>\n\n\n\n<li>Der Grundrundgang auf Emilys Spuren im Zentrum l\u00e4sst sich bequem in zwei bis drei Stunden zu Fu\u00df absolvieren \u2013 komplizierte Logistik ist nicht n\u00f6tig.<\/li>\n\n\n\n<li>Die Wohnung, in der Emily lebt, ist ein ganz normales privates Wohnhaus und kann nur von au\u00dfen besichtigt werden \u2013 hinein kommt man leider nicht.<\/li>\n\n\n\n<li>Ber\u00fchmte Serien-Caf\u00e9s wie das Caf\u00e9 de Flore oder Les Deux Magots sind legend\u00e4r, aber auch entsprechend teuer \u2013 rechne damit, dass du f\u00fcr Atmosph\u00e4re und Geschichte ordentlich draufzahlst.<\/li>\n\n\n\n<li>Die Anwohner in der Umgebung der Drehorte sind oft genervt von den Touristenmassen \u2013 bitte sei r\u00fccksichtsvoll, fotografiere niemandem in die Fenster und verhalte dich auf den kleinen Pl\u00e4tzen leise.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Auf_den_Spuren_von_Emily_in_Paris_so_gehts_wann_wie_viele_Staffeln_Route_Anreise\"><\/span><span class=\"ez-toc-section\" id=\"Auf_den_Spuren_von_Emily_in_Paris_so_gehts_wann_wie_viele_Staffeln_Route_Anreise\"><\/span>Auf den Spuren von Emily in Paris: so geht&#8217;s (wann, wie viele Staffeln, Route, Anreise)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-emily-mindy-prochazka.jpg\" alt=\"Emily und Mindy beim Spaziergang durch eine Pariser Gasse in der Serie Emily in Paris\" class=\"wp-image-159192\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-emily-mindy-prochazka.jpg 1280w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-emily-mindy-prochazka-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-emily-mindy-prochazka-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-emily-mindy-prochazka-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-emily-mindy-prochazka-696x392.jpg 696w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Emily und Mindy beim Spaziergang durch eine Pariser Gasse in der Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Bevor du dich in die franz\u00f6sische Metropole aufmachst, um bekannte Gassen und Restaurants zu suchen, solltest du ein paar organisatorische Dinge kl\u00e4ren, damit du dich in der Stadt zurechtfindest und wei\u00dft, was dich an den Seriendrehorten erwartet. Emily in Paris hat aktuell f\u00fcnf ausgestrahlte Staffeln, wobei die f\u00fcnfte am 18. Dezember 2025 erschien \u2013 und eine sechste Staffel ist bereits offiziell best\u00e4tigt. Wichtig zu wissen: Ab der f\u00fcnften Staffel verlagert sich die Handlung deutlich ins italienische Rom. Unser Guide konzentriert sich daher haupts\u00e4chlich auf die klassischen Locations der ersten vier Staffeln, die im Herzen von Frankreich spielen.<\/p>\n\n\n\n<p>Falls du dich fragst, ob alle Hauptdrehorte an einem einzigen Tag machbar sind \u2013 ja, das geht problemlos! Die zentralen Locations lassen sich in etwa zwei bis drei Stunden zu Fu\u00df ablaufen. Ich empfehle dir, die Route am kleinen Platz Place de l&#8217;Estrapade zu starten. Von dort geht es weiter zum nahegelegenen Panth\u00e9on, anschlie\u00dfend spazierst du durch den ruhigen Jardin du Luxembourg, \u00fcberquerst die Seine \u00fcber die Pont des Arts, h\u00e4ltst am Louvre an und beendest den Rundgang am Place de Valois und in den G\u00e4rten des Palais Royal. Einen separaten Ausflug solltest du f\u00fcr das romantische Montmartre einplanen \u2013 dorthin musst du mit der Metro fahren, aber es erwarten dich dort einige weitere wundersch\u00f6ne Stationen, die sich absolut lohnen.<\/p>\n\n\n\n<p>Was die Fortbewegung in Paris betrifft: Am einfachsten besorgst du dir eine Navigo-Easy-Karte und l\u00e4dst die praktische App Bonjour RATP aufs Handy, die dir die Suche nach Metro- und Busverbindungen erheblich erleichtert. Die Anreise von Deutschland nach Paris ist heutzutage ziemlich erschwinglich \u2013 mit Billigfliegern wie Eurowings bekommst du Hin- und R\u00fcckfl\u00fcge von Berlin oder M\u00fcnchen schon ab etwa 50 bis 100 \u20ac, w\u00e4hrend es bei Airlines wie Lufthansa je nach Buchungszeitpunkt meist zwischen 140 und 250 \u20ac kostet. Alternativ ist der TGV oder Thalys ab Frankfurt, K\u00f6ln oder Stuttgart eine bequeme Option. Du kannst auch organisierte \u201eEmily&#8220;-Touren ausprobieren, die beispielsweise \u00fcber Websites wie <a href=\"https:\/\/www.cometoparis.com\" target=\"_blank\" rel=\"nofollow noopener\">Come to Paris<\/a> ab etwa 14,50 \u20ac angeboten werden \u2013 aber mit ein bisschen Planung schaffst du alles problemlos auf eigene Faust in deinem Tempo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wo_uebernachten_damit_die_Drehorte_um_die_Ecke_liegen\"><\/span><span class=\"ez-toc-section\" id=\"Wo_uebernachten_damit_die_Drehorte_um_die_Ecke_liegen\"><\/span>Wo \u00fcbernachten, damit die Drehorte um die Ecke liegen<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029.jpg\" alt=\"Lucie mit Kleinkind vor dem Eiffelturm am Trocad\u00e9ro\" class=\"wp-image-158706\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029.jpg 2000w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-1536x1024.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-696x464.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-1392x928.jpg 1392w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-5029-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\"><figcaption class=\"wp-element-caption\">Lucie mit Kleinkind vor dem Eiffelturm am Trocad\u00e9ro<\/figcaption><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&amp;campaign=loudavymkrokemcz-nakupyvparizi&amp;product=allez&amp;habl=false&amp;isinc=false&amp;sid22=eyOhfbUVRdp25NRC&amp;conmeth=normal&amp;plng=cs-CZ&amp;pageCategory=travel&amp;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize&amp;source=direct&amp;medium=hyperlink&amp;address=Paris%2C+France&amp;search=V%C3%BDb%C4%9Br+%C4%8Dtvrti&amp;version=surface-the-opportunities%7C7%7C1.2.0&amp;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi\" rel=\"noreferrer noopener\" target=\"_blank\">Die Wahl des Viertels<\/a>&nbsp;beeinflusst dein gesamtes Paris-Erlebnis und dein Budget massiv. Paris ist in zwanzig Arrondissements unterteilt, die sich vom historischen Zentrum am Louvre spiralf\u00f6rmig im Uhrzeigersinn ausbreiten.&nbsp;<strong><a href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&amp;campaign=loudavymkrokemcz-nakupyvparizi&amp;product=allez&amp;habl=false&amp;isinc=false&amp;sid22=eyOhfbUVRdp25NRC&amp;conmeth=normal&amp;plng=cs-CZ&amp;pageCategory=travel&amp;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize-loudavymkrokemcz-parizzdarma&amp;source=direct&amp;medium=hyperlink&amp;address=Paris%2C+France&amp;search=levn%C3%A9+ubytov%C3%A1n%C3%AD+v+centru&amp;version=surface-the-opportunities%7C7%7C1.2.0&amp;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi\" rel=\"noreferrer noopener\" target=\"_blank\">Eine g\u00fcnstige Unterkunft im Zentrum<\/a>&nbsp;zu finden ist fast unm\u00f6glich, aber wenn du wei\u00dft, wo du suchen musst, findest du einen tollen Kompromiss aus Preis, Sicherheit und Erreichbarkeit.<\/strong><\/p>\n\n\n\n<p>Mit Kinderwagen und unserem Kleinen solltet ihr einen gro\u00dfen Bogen um die&nbsp;<a href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&amp;campaign=loudavymkrokemcz-nakupyvparizi&amp;product=allez&amp;habl=false&amp;isinc=false&amp;sid22=eyOhfbUVRdp25NRC&amp;conmeth=normal&amp;plng=cs-CZ&amp;pageCategory=travel&amp;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize-loudavymkrokemcz-parizzdarma&amp;source=direct&amp;medium=hyperlink&amp;address=Gare+du+Nord%2C+10th+arrondissement%2C+Paris%2C+France&amp;search=severn%C3%AD+%C4%8D%C3%A1sti+10.+obvodu+kolem+n%C3%A1dra%C5%BE%C3%AD+Gare+du+Nord&amp;version=surface-the-opportunities%7C7%7C1.2.0&amp;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi\" rel=\"noreferrer noopener\" target=\"_blank\">n\u00f6rdliche Gegend des 10. Arrondissements rund um den Gare du Nord<\/a>&nbsp;und&nbsp;<a href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&amp;campaign=loudavymkrokemcz-nakupyvparizi&amp;product=allez&amp;habl=false&amp;isinc=false&amp;sid22=eyOhfbUVRdp25NRC&amp;conmeth=normal&amp;plng=cs-CZ&amp;pageCategory=travel&amp;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize-loudavymkrokemcz-parizzdarma&amp;source=direct&amp;medium=hyperlink&amp;address=Pigalle%2C+18th+arrondissement%2C+Paris%2C+France&amp;search=no%C4%8Dn%C3%ADmu+Pigalle+v+18.+obvodu&amp;version=surface-the-opportunities%7C7%7C1.2.0&amp;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi\" rel=\"noreferrer noopener\" target=\"_blank\">das n\u00e4chtliche Pigalle im 18. Arrondissement<\/a> machen. Einmal haben wir uns dort mit einem Freund um zwei Uhr nachts verlaufen \u2013 das m\u00f6chte man mit einem Zweij\u00e4hrigen definitiv nicht wiederholen. \ud83d\ude05&nbsp;<\/p>\n\n\n\n<p>Nach langer Suche haben wir uns f\u00fcr das&nbsp;<strong><a href=\"https:\/\/booking.stay22.com\/lukaskonecny\/AxKJ70l2yy?aid=lukaskonecny&amp;campaign=loudavymkrokemcz-nakupyvparizi&amp;product=allez&amp;habl=false&amp;isinc=false&amp;sid22=eyOhfbUVRdp25NRC&amp;conmeth=normal&amp;plng=cs-CZ&amp;pageCategory=travel&amp;address=Paris%2C+France&amp;source=direct&amp;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi&amp;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize-loudavymkrokemcz-parizzdarma\" target=\"_blank\" rel=\"noreferrer noopener\">H\u00f4bou<\/a><\/strong> entschieden, ein authentisches franz\u00f6sisches Boutique-Hotel in&nbsp;<a href=\"https:\/\/www.hobou.com\/en\/\" target=\"_blank\" rel=\"noreferrer noopener\">Boulogne-Billancourt<\/a>&nbsp;(buchen kannst du es&nbsp;<a href=\"https:\/\/booking.stay22.com\/lukaskonecny\/AxKJ70l2yy?aid=lukaskonecny&amp;campaign=loudavymkrokemcz-nakupyvparizi&amp;product=allez&amp;habl=false&amp;isinc=false&amp;sid22=eyOhfbUVRdp25NRC&amp;conmeth=normal&amp;plng=cs-CZ&amp;pageCategory=travel&amp;address=Paris%2C+France&amp;source=direct&amp;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi&amp;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize-loudavymkrokemcz-parizzdarma\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a>), das auf den ersten Blick eher unscheinbar wirkt, aber innerhalb der ersten Stunden hat man es ins Herz geschlossen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Arrondissement_Emilys_Nachbarschaft_das_Herzstueck_aller_Drehorte\"><\/span><span class=\"ez-toc-section\" id=\"5_Arrondissement_Emilys_Nachbarschaft_das_Herzstueck_aller_Drehorte\"><\/span>5. Arrondissement: Emilys Nachbarschaft (das Herzst\u00fcck aller Drehorte)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka.jpg\" alt=\"Emily und Mindy vor dem Tor eines Pariser Hauses in der Serie Emily in Paris\" class=\"wp-image-159193\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka.jpg 1280w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka-696x392.jpg 696w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Emily und Mindy vor dem Tor eines Pariser Hauses in der Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Wenn du das Gef\u00fchl haben m\u00f6chtest, direkt in die Serie hineinzuspazieren, sollten deine ersten Schritte garantiert ins 5. Arrondissement f\u00fchren. Dieses Viertel bildet das Herz der gesamten Handlung, und alle wichtigen Orte liegen hier fu\u00dfl\u00e4ufig innerhalb von f\u00fcnf Minuten beieinander. Am einfachsten kommst du hierher mit der Metro zur Station Cardinal Lemoine oder mit dem RER-Zug bis zur Station Luxembourg \u2013 von dort ist es nur noch ein kurzer, sch\u00f6ner Spaziergang zu Emilys kleinem Platz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Emilys_Haus_am_Place_de_lEstrapade\"><\/span><span class=\"ez-toc-section\" id=\"1_Emilys_Haus_am_Place_de_lEstrapade\"><\/span>1. Emilys Haus am Place de l&#8217;Estrapade<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1018\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade.jpg\" alt=\"Der Platz Place de l&#039;Estrapade im 5. Pariser Arrondissement, wo Emily in der Serie wohnt\" class=\"wp-image-159197\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade.jpg 1600w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade-300x191.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade-700x445.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade-768x489.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade-1536x977.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade-696x443.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-place-de-lestrapade-1392x886.jpg 1392w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\"><figcaption class=\"wp-element-caption\">Der Platz Place de l&#8217;Estrapade im 5. Pariser Arrondissement, wo Emily in der Serie wohnt<\/figcaption><\/figure>\n\n\n\n<p>Deine erste Station ist die Adresse 1 Place de l&#8217;Estrapade \u2013 jener bezaubernde kleine Platz mit Baum und B\u00e4nken, an dem Emily in der Serie ihre winzige Dachwohnung im f\u00fcnften Stock ohne Aufzug bewohnt. In Wirklichkeit handelt es sich um ein ganz normales privates Wohnhaus, sodass ein Besuch nur von au\u00dfen m\u00f6glich ist \u2013 hinein kommt man nicht. Au\u00dferdem befinden sich Restaurant und B\u00e4ckerei nicht direkt unter dem Haus wie in der Serie, sondern ein St\u00fcckchen weiter in der angrenzenden Stra\u00dfe. Ich empfehle, sehr fr\u00fch morgens herzukommen, denn tags\u00fcber bilden sich lange Schlangen von Touristen, die auf ein Foto vor der Eingangst\u00fcr warten \u2013 was verst\u00e4ndlicherweise die Geduld der Anwohner ziemlich strapaziert, die hier einfach nur normal leben m\u00f6chten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"2_Boulangerie_Moderne_%E2%80%94_Emilys_Baeckerei\"><\/span><span class=\"ez-toc-section\" id=\"2_Boulangerie_Moderne_Emilys_Baeckerei\"><\/span>2. Boulangerie Moderne \u2014 Emilys B\u00e4ckerei<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1137\" height=\"1166\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-boulangerie-moderne.jpg\" alt=\"Die B\u00e4ckerei Boulangerie Moderne in Paris, bekannt aus der Serie Emily in Paris\" class=\"wp-image-159198\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-boulangerie-moderne.jpg 1137w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-boulangerie-moderne-293x300.jpg 293w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-boulangerie-moderne-700x718.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-boulangerie-moderne-768x788.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-boulangerie-moderne-696x714.jpg 696w\" sizes=\"auto, (max-width: 1137px) 100vw, 1137px\"><figcaption class=\"wp-element-caption\">Die B\u00e4ckerei Boulangerie Moderne in Paris, bekannt aus der Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Gleich um die Ecke an der Adresse 16 Rue des Foss\u00e9s Saint-Jacques liegt die Boulangerie Moderne \u2013 jene ber\u00fchmte B\u00e4ckerei, in der sich Emily morgens ihr hei\u00dfgeliebtes Pain au Chocolat holt. Das Tolle daran: Es ist eine echte, voll funktionsf\u00e4hige Handwerksb\u00e4ckerei mit einer wundersch\u00f6nen historischen Schaufensterfront. Ein normaler Croissant kostet hier etwa 1,50 \u20ac, und f\u00fcr ein traditionelles knuspriges Baguette zahlst du rund 1 \u20ac \u2013 f\u00fcr das Pariser Zentrum absolut faire Preise. Ge\u00f6ffnet ist in der Regel montags bis freitags zwischen 7:00 und 20:00 Uhr, aber Vorsicht: Im August und montags ist meistens geschlossen \u2013 damit du nicht vor heruntergelassenen Rolll\u00e4den stehst. Obwohl die B\u00e4ckerei mittlerweile ein riesiger Touristen-Magnet ist, bleibt sie eine ausgezeichnete Viertelb\u00e4ckerei, die Bio-Mehl verwendet und 2023 sogar die Silbermedaille f\u00fcr den besten Croissant beim Pariser Stadtwettbewerb gewonnen hat. Im Mai 2025 belegte sie au\u00dferdem den vierten Platz im Ranking der Pariser B\u00e4ckerinnung.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"3_Terra_Nera_%E2%80%94_Gabriels_Restaurant\"><\/span><span class=\"ez-toc-section\" id=\"3_Terra_Nera_Gabriels_Restaurant\"><\/span>3. Terra Nera \u2014 Gabriels Restaurant<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1363\" height=\"912\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-terra-nera-restaurace.jpg\" alt=\"Restaurant Terra Nera mit roter Fassade, Gabriels Restaurant aus der Serie Emily in Paris\" class=\"wp-image-159199\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-terra-nera-restaurace.jpg 1363w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-terra-nera-restaurace-300x201.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-terra-nera-restaurace-700x468.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-terra-nera-restaurace-768x514.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-terra-nera-restaurace-696x466.jpg 696w\" sizes=\"auto, (max-width: 1363px) 100vw, 1363px\"><figcaption class=\"wp-element-caption\">Restaurant Terra Nera mit roter Fassade, Gabriels Restaurant aus der Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Direkt gegen\u00fcber von Emilys Haus findest du an der Adresse 18 Rue des Foss\u00e9s Saint-Jacques ein Restaurant mit auff\u00e4llig roter Fassade, das in der Serie als Lokal des gutaussehenden K\u00fcchenchefs Gabriel dient und im Laufe der Staffeln seinen Namen wechselt \u2013 von Les Deux Comp\u00e8res \u00fcber Chez Lavaux bis hin zu L&#8217;Esprit de Gigi. Hier erwartet dich eine gro\u00dfe \u00dcberraschung: Terra Nera ist in Wirklichkeit ein italienisches Restaurant und kein franz\u00f6sisches Bistro. Statt Cassoulet findest du auf der Speisekarte eher Pasta mit Muscheln, Mail\u00e4nder Kalbsschnitzel und hervorragende Pizza. Die Hauptgerichte kosten zwischen 18 und 25 \u20ac, und es gibt sogar ein spezielles \u201eEmily in Paris&#8220;-Men\u00fc f\u00fcr 39 \u20ac, wenn du das volle Erlebnis m\u00f6chtest. Unbedingt vorher anrufen und reservieren, denn das Restaurant ist oft hoffnungslos ausgebucht \u2013 und vor der T\u00fcr steht fast st\u00e4ndig eine Traube fotografierender Serienfans.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"4_Pantheon\"><\/span><span class=\"ez-toc-section\" id=\"4_Pantheon\"><\/span>4. Panth\u00e9on<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon.jpg\" alt=\"Das Pariser Panth\u00e9on am Place du Panth\u00e9on im Quartier Latin\" class=\"wp-image-159200\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon.jpg 1600w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-300x225.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-700x525.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-768x576.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-1536x1152.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-80x60.jpg 80w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-160x120.jpg 160w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-696x522.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pantheon-1392x1044.jpg 1392w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\"><figcaption class=\"wp-element-caption\">Das Pariser Panth\u00e9on am Place du Panth\u00e9on im Quartier Latin<\/figcaption><\/figure>\n\n\n\n<p>Von Emilys Wohnung sind es nur wenige Gehminuten zum riesigen Place du Panth\u00e9on mit dem beeindruckenden Panth\u00e9on-Geb\u00e4ude, das in der Serie vor allem in der ersten Staffel als Teil der wundersch\u00f6nen Zwischenschnitte des Lebens im 5. Arrondissement auftaucht. Es handelt sich um einen prachtvollen Bau, in dem bedeutende Franzosen wie Victor Hugo oder Marie Curie beigesetzt sind \u2013 ein logischer und sch\u00f6ner Halt auf deiner Route. Der Eintritt ins Innere, das meist von 10:00 bis 18:30 Uhr ge\u00f6ffnet ist, kostet 11 bis 13 \u20ac. Aktuelle Informationen findest du auf der offiziellen Website des <a href=\"https:\/\/www.paris-pantheon.fr\" target=\"_blank\" rel=\"nofollow noopener\">Panth\u00e9on<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"5_Jardin_du_Luxembourg_Luxemburggarten\"><\/span><span class=\"ez-toc-section\" id=\"5_Jardin_du_Luxembourg_Luxemburggarten\"><\/span>5. Jardin du Luxembourg (Luxemburggarten)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"2000\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794.jpg\" alt=\"Der Jardin du Luxembourg im 6. Pariser Arrondissement, wo Emily in der Serie joggen geht\" class=\"wp-image-158727\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794.jpg 1333w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794-200x300.jpg 200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794-700x1050.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794-768x1152.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794-1024x1536.jpg 1024w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4794-696x1044.jpg 696w\" sizes=\"auto, (max-width: 1333px) 100vw, 1333px\"><figcaption class=\"wp-element-caption\">Der Jardin du Luxembourg im 6. Pariser Arrondissement, wo Emily in der Serie joggen geht<\/figcaption><\/figure>\n\n\n\n<p>Gleich ein St\u00fcckchen weiter im benachbarten 6. Arrondissement erwartet dich der Jardin du Luxembourg \u2013 der wundersch\u00f6ne und weitl\u00e4ufige Luxemburggarten, in dem Emily in der zweiten Folge der ersten Staffel morgens joggen geht. Der Eintritt ist f\u00fcr alle kostenlos, und es ist der perfekte Ort f\u00fcr eine kleine Pause w\u00e4hrend deines Spaziergangs. Du kannst dich auf die ikonischen gr\u00fcnen St\u00fchle rund um den gro\u00dfen Brunnen setzen oder die Kinder mit den Holzbooten spielen lassen. Luk\u00e1\u0161 und ich lieben diesen Garten, und wenn du mit kleineren Kindern nach Paris f\u00e4hrst \u2013 so wie wir mit unserem Kleinkind \u2013, wirst du die herrliche Ruhe und den gro\u00dfz\u00fcgigen Platz zum Toben und Entspannen zu sch\u00e4tzen wissen.<\/p>\n\n\n<p><!-- GYG:Pa\u0159\u00ed\u017e --><\/p>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"1_Arrondissement_wo_Emily_arbeitet_Savoir_und_Palais_Royal\"><\/span><span class=\"ez-toc-section\" id=\"1_Arrondissement_wo_Emily_arbeitet_Savoir_und_Palais_Royal\"><\/span>1. Arrondissement: wo Emily arbeitet (Savoir und Palais Royal)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-agentura-savoir.jpg\" alt=\"Emily im B\u00fcro der Marketingagentur Savoir aus der Serie Emily in Paris\" class=\"wp-image-159194\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-agentura-savoir.jpg 1280w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-agentura-savoir-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-agentura-savoir-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-agentura-savoir-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-agentura-savoir-696x392.jpg 696w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Emily im B\u00fcro der Marketingagentur Savoir aus der Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Wenn du Emilys Nachbarschaft gr\u00fcndlich erkundet hast, wird es Zeit, ins 1. Arrondissement weiterzuziehen \u2013 genau dorthin, wo die Hauptfigur jeden Morgen zur Arbeit pendelt und wo dich eine etwas luxuri\u00f6sere Atmosph\u00e4re des alten Paris empf\u00e4ngt. Am besten nimmst du die Metro und steigst an der Station Palais Royal\u2013Mus\u00e9e du Louvre aus \u2013 von dort sind es nur ein paar malerische G\u00e4sschen bis zur Serienwerbeagentur.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"6_Place_de_Valois_%E2%80%94_Agentur_Savoir_Agence_Grateau\"><\/span><span class=\"ez-toc-section\" id=\"6_Place_de_Valois_Agentur_Savoir_Agence_Grateau\"><\/span>6. Place de Valois \u2014 Agentur Savoir \/ Agence Grateau<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v.jpg\" alt=\"Traditionelles Pariser Caf\u00e9 in der Rue Valois in der N\u00e4he der Agentur Savoir\" class=\"wp-image-158797\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v.jpg 2000w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-1536x1024.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-696x464.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-1392x928.jpg 1392w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-07-tradicni-pariska-kavarna-palais-royal-se-vinove-cervenou-markyzou-na-ulici-rue-v-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\"><figcaption class=\"wp-element-caption\">Traditionelles Pariser Caf\u00e9 in der Rue Valois in der N\u00e4he der Agentur Savoir<\/figcaption><\/figure>\n\n\n\n<p>Der erste Ort, nach dem du Ausschau halten wirst, ist der versteckte kleine Platz Place de Valois an der Adresse 6 Place de Valois nahe der Rue des Bons Enfants. Hier befindet sich die Marketingagentur Savoir, die sp\u00e4ter zur Agence Grateau wird. Der Innenhof, in den Emily praktisch in jeder Folge kommt und wo die meisten Au\u00dfengespr\u00e4che mit Chefin Sylvie stattfinden, ist frei und kostenlos zug\u00e4nglich \u2013 du kannst dich dort in aller Ruhe umsehen und dir vorstellen, mit dem Morgenkaffee direkt ins Meeting zu marschieren. Erreichbar ist der Platz ganz einfach \u00fcber einen Durchgang vom nahegelegenen Palais Royal, und es ist hier meist angenehm ruhig, da er etwas abseits der gro\u00dfen Touristenstr\u00f6me liegt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"7_Jardin_du_Palais_Royal_%E2%80%94_die_gestreiften_Saeulen\"><\/span><span class=\"ez-toc-section\" id=\"7_Jardin_du_Palais_Royal_die_gestreiften_Saeulen\"><\/span>7. Jardin du Palais Royal \u2014 die gestreiften S\u00e4ulen<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1333\" height=\"2000\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567.jpg\" alt=\"Die gestreiften S\u00e4ulen Colonnes de Buren im Hof des Palais Royal in Paris\" class=\"wp-image-158737\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567.jpg 1333w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567-200x300.jpg 200w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567-700x1050.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567-768x1152.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567-1024x1536.jpg 1024w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/paris-4567-696x1044.jpg 696w\" sizes=\"auto, (max-width: 1333px) 100vw, 1333px\"><figcaption class=\"wp-element-caption\">Die gestreiften S\u00e4ulen Colonnes de Buren im Hof des Palais Royal in Paris<\/figcaption><\/figure>\n\n\n\n<p>Nur wenige Meter weiter an der Adresse 8 Rue de Montpensier st\u00f6\u00dft du auf den Jardin du Palais Royal \u2013 ein Ort mit freiem Eintritt, der in der Serie eine ziemlich wichtige Rolle spielt. Genau hier setzt sich Emily zum ersten Mal auf eine Bank am Brunnen, isst zu Mittag und lernt ihre k\u00fcnftige beste Freundin Mindy kennen. Neben den wundersch\u00f6nen G\u00e4rten mit B\u00e4nken findest du hier auch einen der beliebtesten Pariser Instagram-Spots: die ikonischen schwarz-wei\u00df gestreiften S\u00e4ulen verschiedener H\u00f6he, bekannt als Colonnes de Buren. Es ist ein wunderbar angenehmer Ort, an dem du dem Gro\u00dfstadttrubel entfliehen kannst \u2013 und obendrein deutlich weniger \u00fcberlaufen als die nahegelegenen Parks rund um den Louvre.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"8_Le_Grand_Vefour_%E2%80%94_das_Restaurant_in_das_Emily_vergeblich_will\"><\/span><span class=\"ez-toc-section\" id=\"8_Le_Grand_Vefour_das_Restaurant_in_das_Emily_vergeblich_will\"><\/span>8. Le Grand V\u00e9four \u2014 das Restaurant, in das Emily vergeblich will<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Direkt am Rand dieser G\u00e4rten an der Adresse 17 Rue de Beaujolais befindet sich Le Grand V\u00e9four \u2013 ein luxuri\u00f6ses, pr\u00e4chtiges historisches Restaurant, in das Emily in der ersten Staffel selbstbewusst mit Kunden und Kollegen gehen m\u00f6chte, nur um am Eingang besch\u00e4mt festzustellen, dass sie das Reservierungsdatum verwechselt hat. Es handelt sich um ein echtes legend\u00e4res Restaurant, das jahrelang Michelin-Sterne hielt. Auch heute ist es ein \u00e4u\u00dferst exklusives und teures Erlebnis, bei dem die Preise pro Person leicht 60 bis 150 \u20ac und mehr betragen k\u00f6nnen. Reservierungen m\u00fcssen weit im Voraus get\u00e4tigt werden \u2013 wenn du also nicht gerade das Budget amerikanischer Manager hast, empfehle ich dir, dieses wundersch\u00f6ne historische Juwel lieber nur von au\u00dfen durch das prachtvoll verzierte Fenster zu bewundern.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Saint-Germain_beruehmte_und_ziemlich_teure_Cafes\"><\/span><span class=\"ez-toc-section\" id=\"Saint-Germain_beruehmte_und_ziemlich_teure_Cafes\"><\/span>Saint-Germain: ber\u00fchmte (und ziemlich teure) Caf\u00e9s<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-kavarna-beret.jpg\" alt=\"Emily mit roter Baskenm\u00fctze in einem Pariser Caf\u00e9, Szene aus Emily in Paris\" class=\"wp-image-159195\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-kavarna-beret.jpg 1280w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-kavarna-beret-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-kavarna-beret-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-kavarna-beret-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-kavarna-beret-696x392.jpg 696w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Emily mit roter Baskenm\u00fctze in einem Pariser Caf\u00e9, Szene aus Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Wenn du vom Zentrum aus \u00fcber die Seine zur\u00fcck ins 6. Arrondissement zum Boulevard Saint-Germain wechselst, landest du in der Welt der ber\u00fchmten Pariser Caf\u00e9s, in denen sich im 20. Jahrhundert bedeutende Schriftsteller, Philosophen und K\u00fcnstler trafen \u2013 und die nat\u00fcrlich auch bei den Dreharbeiten unserer Serie nicht fehlen durften. Es sind Orte mit enormer Geschichte und unverwechselbarem Charme, aber gleich vorweg die Warnung: Sie sind schlicht und einfach richtig teuer, und du zahlst weniger f\u00fcr einen herausragenden Kaffee als vielmehr daf\u00fcr, auf demselben Stuhl zu sitzen, auf dem einst Jean-Paul Sartre Platz genommen hat.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"9_Cafe_de_Flore\"><\/span><span class=\"ez-toc-section\" id=\"9_Cafe_de_Flore\"><\/span>9. Caf\u00e9 de Flore<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore.jpg\" alt=\"Das ber\u00fchmte Caf\u00e9 de Flore am Boulevard Saint-Germain in Paris\" class=\"wp-image-159201\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore.jpg 1080w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore-300x300.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore-700x700.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore-150x150.jpg 150w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore-768x768.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-cafe-de-flore-696x696.jpg 696w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\"><figcaption class=\"wp-element-caption\">Das ber\u00fchmte Caf\u00e9 de Flore am Boulevard Saint-Germain in Paris<\/figcaption><\/figure>\n\n\n\n<p>An der legend\u00e4ren Adresse 172 Boulevard Saint-Germain steht das Ecklokal Caf\u00e9 de Flore mit seiner un\u00fcbersehbaren Blumendekoration und dem gr\u00fcnen Schriftzug. Hier trifft Emily in der sechsten Episode der ersten Staffel auf den snobistischen Semiotik-Professor Thomas. Die Preise entsprechen nicht denen normaler Caf\u00e9s: F\u00fcr einen einfachen kleinen Espresso zahlst du rund 5 \u20ac, eine s\u00e4mige hei\u00dfe Schokolade kostet 10 bis 12 \u20ac, und f\u00fcr ein leichtes Gericht wie Omelett oder Sandwich legst du zwischen 10 und 20 \u20ac hin. Ehrlich gesagt ist es heute eigentlich eine wundersch\u00f6ne Touristenfalle, aber mit Kultstatus \u2013 man sollte es schlicht als historisches Erlebnis betrachten, bei dem das Preis-Leistungs-Verh\u00e4ltnis keine Rolle spielt. Ge\u00f6ffnet ist t\u00e4glich von 7:30 Uhr morgens bis 1:30 Uhr nachts, und ich empfehle dir dringend, entweder ganz fr\u00fch am Morgen oder sp\u00e4ter am Abend zu kommen \u2013 sonst kannst du in der Schlange auf den perfekten Au\u00dfentisch mit Blick auf die Stra\u00dfe locker eine halbe Stunde warten. Mehr Infos auf der Website des <a href=\"https:\/\/cafedeflore.fr\" target=\"_blank\" rel=\"nofollow noopener\">Caf\u00e9 de Flore<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"10_Les_Deux_Magots\"><\/span><span class=\"ez-toc-section\" id=\"10_Les_Deux_Magots\"><\/span>10. Les Deux Magots<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots.jpg\" alt=\"Das historische Caf\u00e9 Les Deux Magots im Pariser Viertel Saint-Germain\" class=\"wp-image-159202\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots.jpg 1600w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots-1536x864.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots-696x392.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-les-deux-magots-1392x783.jpg 1392w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\"><figcaption class=\"wp-element-caption\">Das historische Caf\u00e9 Les Deux Magots im Pariser Viertel Saint-Germain<\/figcaption><\/figure>\n\n\n\n<p>Direkt neben dem Caf\u00e9 de Flore am Platz 6 Place Saint-Germain-des-Pr\u00e9s befindet sich sein historisch gr\u00f6\u00dfter Rivale: das Caf\u00e9 Les Deux Magots. Es spielt in der Serie zwar keine ganz so prominente Rolle, geh\u00f6rt aber in dieselbe Liga bewunderter und \u00e4u\u00dferst teurer Lokale \u2013 und die Kameras konnten es bei den Aufnahmen des Viertels nat\u00fcrlich nicht ignorieren. Die Atmosph\u00e4re ist der beim Nachbarn sehr \u00e4hnlich: F\u00fcr einen Cappuccino zahlst du rund 9,50 \u20ac und kannst hier bequem einen Nachmittag damit verbringen, stilvolle Pariser zu beobachten. Im M\u00e4rz 2025 wurde das Caf\u00e9 nach einer l\u00e4ngeren Renovierung wiederer\u00f6ffnet und erstrahlt nun in einem aufgefrischten, polierten Interieur. Alle Neuigkeiten findest du direkt auf der Website von <a href=\"https:\/\/lesdeuxmagots.fr\" target=\"_blank\" rel=\"nofollow noopener\">Les Deux Magots<\/a>.<\/p>\n\n\n\n<!-- LKM_GYG_CARD start q=\"paris\" lang=\"de\" rendered=\"2026-06-03T07:31:37+00:00\" v=\"1\" -->\n<style id=\"lk-gyg-styles\">\n@import url(\"https:\/\/fonts.googleapis.com\/css2?family=Playfair+Display:wght@700&family=DM+Sans:wght@300;400;500;600&display=swap\");\n\/* === LK GYG karty \u2014 CRO redesign 2026-05 (namespace .lkx-) ===\n   C\u00edl: vy\u0161\u0161\u00ed CTR (hero + v\u00fdrazn\u00fd social proof + ak\u010dn\u00ed CTA, m\u00e9n\u011b \"reklamn\u00ed\").\n   Injektuje se inline do prvn\u00edho markeru postu (refresh_cards.py --inline-css). *\/\n.lkx-module, .lkx-module *{box-sizing:border-box;margin:0;padding:0}\n.lkx-module{\n  font-family:'DM Sans',-apple-system,Segoe UI,Roboto,Georgia,sans-serif;\n  max-width:860px;margin:2.5rem auto;color:#1f2328;\n}\n\n\/* HEADER \u2014 lehk\u00fd editorsk\u00fd, \u017e\u00e1dn\u00fd bannerov\u00fd blok; nadpis + popisek pod n\u00edm *\/\n.lkx-head{margin-bottom:16px}\n.lkx-head-main{display:flex;align-items:center;gap:10px}\n.lkx-head-accent{width:26px;height:3px;border-radius:2px;background:#c39f76;flex-shrink:0}\n.lkx-head-title{font-family:'Playfair Display',Georgia,serif;font-size:21px;font-weight:700;color:#1a1a1a;line-height:1.25}\n.lkx-head-meta{display:block;font-size:11px;letter-spacing:.3px;color:#9aa0a6;margin-top:4px;margin-left:36px}\n\n\/* HERO *\/\n.lkx-hero{display:grid;grid-template-columns:300px 1fr;background:#fff;border:1px solid #ece7df;border-radius:14px;overflow:hidden;text-decoration:none!important;color:inherit;box-shadow:0 6px 20px rgba(0,0,0,.06);transition:box-shadow .2s,transform .2s;margin-bottom:14px}\n.lkx-hero:hover{box-shadow:0 12px 30px rgba(0,0,0,.12);transform:translateY(-2px)}\n.lkx-hero-img{position:relative;min-height:230px;background-size:cover;background-position:center;background-color:#eee}\n.lkx-hero-body{padding:22px 24px;display:flex;flex-direction:column}\n.lkx-pick{position:absolute;top:12px;left:12px;background:#1a1a1a;color:#fff;font-size:11px;font-weight:700;letter-spacing:.5px;padding:5px 11px;border-radius:20px}\n\n\/* TITLE *\/\n.lkx-title{font-size:19px;font-weight:700;color:#161616;line-height:1.3}\n.lkx-title-sm{font-size:14.5px;line-height:1.35;display:-webkit-box;-webkit-line-clamp:2;-webkit-box-orient:vertical;overflow:hidden}\n\n\/* SOCIAL PROOF \u2014 v\u00fdrazn\u011b, naho\u0159e *\/\n.lkx-proof{display:flex;align-items:center;gap:7px;margin-top:12px;font-size:15px;color:#3a3a3a}\n.lkx-proof b{font-size:16px;color:#161616}\n.lkx-stars{color:#f5a623;letter-spacing:1px}\n.lkx-proof-sm{font-size:12.5px;margin-top:8px;gap:5px}\n.lkx-proof-sm b{font-size:13px}\n.lkx-proof-new{color:#3685fc;font-weight:600}\n\n\/* PRICE \u2014 n\u00edzk\u00e1 kotva *\/\n.lkx-price{font-size:14px;color:#6b7280}\n.lkx-price b{font-size:20px;color:#161616;font-weight:700}\n.lkx-price-sm b{font-size:15px}\n\n\/* CTA \u2014 tepl\u00e9 ak\u010dn\u00ed tla\u010d\u00edtko *\/\n.lkx-cta{display:inline-flex;align-items:center;justify-content:center;text-decoration:none!important;font-weight:700;color:#fff!important;background:linear-gradient(135deg,#f6743f,#e8552a);border-radius:10px;box-shadow:0 6px 16px rgba(232,85,42,.32);transition:box-shadow .2s}\n.lkx-cta-hero{font-size:15px;padding:13px 22px}\n.lkx-hero:hover .lkx-cta-hero{box-shadow:0 8px 22px rgba(232,85,42,.45)}\n.lkx-cta-sm{font-size:12.5px;padding:9px 14px;width:100%;margin-top:2px}\n.lkx-hero-bottom{margin-top:auto;padding-top:18px;display:flex;align-items:center;justify-content:space-between;gap:14px;flex-wrap:wrap}\n\n\/* BADGE \u2014 jeden v\u00fdrazn\u00fd na fotce *\/\n.lkx-badge{position:absolute;top:12px;right:12px;font-size:10.5px;font-weight:700;letter-spacing:.3px;padding:5px 10px;border-radius:16px;color:#fff}\n.lkx-badge.badge-urgency{background:rgba(214,40,40,.92)}\n.lkx-badge.badge-new{background:rgba(54,133,252,.92)}\n.lkx-badge.badge-top{background:rgba(195,159,118,.95)}\n.lkx-badge.badge-info{background:rgba(40,40,40,.78)}\n\n\/* SECONDARY GRID *\/\n.lkx-grid{display:grid;grid-template-columns:1fr 1fr;gap:14px}\n.lkx-card{background:#fff;border:1px solid #ece7df;border-radius:14px;overflow:hidden;text-decoration:none!important;color:inherit;box-shadow:0 4px 14px rgba(0,0,0,.05);display:flex;flex-direction:column;transition:box-shadow .2s,transform .2s}\n.lkx-card:hover{box-shadow:0 10px 24px rgba(0,0,0,.1);transform:translateY(-2px)}\n.lkx-card-img{position:relative;aspect-ratio:16\/10;background-size:cover;background-position:center;background-color:#eee}\n.lkx-card-body{padding:14px 16px 16px;display:flex;flex-direction:column;gap:7px;flex:1}\n.lkx-card-bottom{margin-top:auto;padding-top:10px;display:flex;align-items:center;justify-content:space-between;gap:8px}\n\n\/* DISCLOSURE \u2014 drobn\u00e1, kv\u016fli d\u016fv\u011b\u0159e\/z\u00e1konu *\/\n.lkx-disclosure{font-size:11px;color:#a7adb3;text-align:center;margin-top:14px;line-height:1.6}\n.lkx-disclosure a{color:#c39f76;text-decoration:none}\n\n@media(max-width:680px){\n  .lkx-hero{grid-template-columns:1fr}\n  .lkx-hero-img{min-height:180px}\n  .lkx-grid{grid-template-columns:1fr}\n  .lkx-head-meta{margin-left:0;width:100%}\n  .lkx-head-title{font-size:19px}\n}\n\n<\/style>\n<div class=\"lkx-module\" data-query=\"paris\">\n  <div class=\"lkx-head\">\n    <div class=\"lkx-head-main\">\n      <span class=\"lkx-head-accent\"><\/span>\n      <span class=\"lkx-head-title\">Erlebnisse &amp; Tickets<\/span>\n    <\/div>\n    <span class=\"lkx-head-meta\">von Reisenden bewertet \u00b7 GetYourGuide<\/span>\n  <\/div><a class=\"lkx-hero\" href=\"https:\/\/www.getyourguide.com\/de-de\/paris-l16\/paris-bateaux-mouches-abendliche-bootsfahrt-souvenir-postkarte-t1282311\/?partner_id=MKZ64IS&amp;utm_medium=online_publisher&amp;cmp=emily-in-paris-drehorte\" target=\"_blank\" rel=\"sponsored noopener nofollow\">\n    <div class=\"lkx-hero-img\" style=\"background-image:url('https:\/\/cdn.getyourguide.com\/img\/tour\/5b23311a4442d22d607292f5443665ffe4a99fdb375d82527f15383bfcedb195.jpeg\/132.jpg')\" role=\"img\" aria-label=\"Paris: Abendlichter-Bootsfahrt mit den legend\u00e4ren Bateaux Mouches\">\n      <span class=\"lkx-pick\">\u2605 Unser Tipp<\/span><\/div>\n    <div class=\"lkx-hero-body\">\n      <div class=\"lkx-title\">Paris: Abendlichter-Bootsfahrt mit den legend\u00e4ren Bateaux Mouches<\/div>\n      <div class=\"lkx-proof\">\n      <span class=\"lkx-stars\">\u2605\u2605\u2605\u2605\u2605<\/span>\n      <b>4.1<\/b> \u00b7 338 Bewertungen\n    <\/div>\n      <div class=\"lkx-hero-bottom\"><div class=\"lkx-price\">ab <b>17\u00a0\u20ac<\/b><\/div><span class=\"lkx-cta lkx-cta-hero\">Das will ich erleben \u2192<\/span>\n      <\/div>\n    <\/div>\n  <\/a><div class=\"lkx-grid\"><a class=\"lkx-card\" href=\"https:\/\/www.getyourguide.com\/de-de\/paris-l16\/disneyland-paris-ticket-fur-2-parks-12345-tage-t395320\/?partner_id=MKZ64IS&amp;utm_medium=online_publisher&amp;cmp=emily-in-paris-drehorte\" target=\"_blank\" rel=\"sponsored noopener nofollow\">\n      <div class=\"lkx-card-img\" style=\"background-image:url('https:\/\/cdn.getyourguide.com\/img\/tour\/fea1f058382affdd2d631301246d665ee1005bb0b412acb3281a06f777f2191a.jpg\/132.jpg')\" role=\"img\" aria-label=\"Disneyland\u00ae Paris 1-Tagesticket\"><\/div>\n      <div class=\"lkx-card-body\">\n        <div class=\"lkx-title lkx-title-sm\">Disneyland\u00ae Paris 1-Tagesticket<\/div>\n        <div class=\"lkx-proof lkx-proof-sm\">\n      <span class=\"lkx-stars\">\u2605<\/span>\n      <b>4.6<\/b> \u00b7 53 765\n    <\/div>\n        <div class=\"lkx-card-bottom\"><span class=\"lkx-price lkx-price-sm\">ab <b>52\u00a0\u20ac<\/b><\/span><span class=\"lkx-cta lkx-cta-sm\">Termine ansehen \u2192<\/span>\n        <\/div>\n      <\/div>\n    <\/a><a class=\"lkx-card\" href=\"https:\/\/www.getyourguide.com\/de-de\/paris-l16\/friedhof-pere-lachaise-aussergewohnliche-gefuhrte-besichtigung-t1342647\/?partner_id=MKZ64IS&amp;utm_medium=online_publisher&amp;cmp=emily-in-paris-drehorte\" target=\"_blank\" rel=\"sponsored noopener nofollow\">\n      <div class=\"lkx-card-img\" style=\"background-image:url('https:\/\/cdn.getyourguide.com\/img\/tour\/964e6ec4c2b007c061c7945498ed07d8f2601315dbd97696c0d987810b6c8aa1.jpg\/132.jpg')\" role=\"img\" aria-label=\"Friedhof P\u00e8re-Lachaise: Au\u00dfergew\u00f6hnliche gef\u00fchrte Besichtigung\"><\/div>\n      <div class=\"lkx-card-body\">\n        <div class=\"lkx-title lkx-title-sm\">Friedhof P\u00e8re-Lachaise: Au\u00dfergew\u00f6hnliche gef\u00fchrte Besichtigung<\/div>\n        <div class=\"lkx-proof lkx-proof-sm\">\n      <span class=\"lkx-stars\">\u2605<\/span>\n      <b>0.0<\/b> \u00b7 0\n    <\/div>\n        <div class=\"lkx-card-bottom\"><span class=\"lkx-price lkx-price-sm\">ab <b>16\u00a0\u20ac<\/b><\/span><span class=\"lkx-cta lkx-cta-sm\">Termine ansehen \u2192<\/span>\n        <\/div>\n      <\/div>\n    <\/a><\/div><div class=\"lkx-disclosure\">\ud83d\udd17 Affiliate-Links \u2014 kein Aufpreis f\u00fcr dich, sie helfen uns, Inhalte zu erstellen. \u00b7 <a href=\"https:\/\/www.getyourguide.com\/de-de\/s\/?q=paris&amp;partner_id=MKZ64IS&amp;utm_medium=online_publisher\" target=\"_blank\" rel=\"sponsored noopener nofollow\">Alle Erlebnisse \u2192<\/a><\/div>\n<\/div>\n<!-- LKM_GYG_CARD end -->\n\n\n<div class=\"lk-stays-module\">\n<style>\n\/* \u2500\u2500\u2500 RESET PRO GUTENBERG \u2500\u2500\u2500 *\/\n.lk-stays-module * { box-sizing: border-box; margin: 0; padding: 0; }\n\n\/* \u2500\u2500\u2500 WRAPPER \u2500\u2500\u2500 *\/\n.lk-stays-module {\n  font-family: 'DM Sans', Georgia, sans-serif;\n  max-width: 100%;\n  margin: 2.5rem auto;\n  background: linear-gradient(135deg, #fdfaf5 0%, #fcf8f0 100%);\n  border: 1px solid #e8dfd4;\n  border-radius: 16px;\n  overflow: hidden;\n  box-shadow: 0 16px 48px rgba(195, 159, 118, 0.25), 0 4px 12px rgba(0,0,0,0.08);\n}\n\n\/* \u2500\u2500\u2500 HEADER \u2500\u2500\u2500 *\/\n.lk-stays-header {\n  position: relative;\n  padding: 24px 36px 24px;\n  background: linear-gradient(135deg, #c39f76 0%, #d4b188 60%, #c39f76 100%);\n  border-bottom: 1px solid rgba(255,255,255,.15);\n  display: flex;\n  align-items: center;\n  gap: 18px;\n}\n.lk-stays-header::before {\n  content: '';\n  position: absolute;\n  inset: 0;\n  background: url(\"data:image\/svg+xml,%3Csvg width='60' height='60' viewBox='0 0 60 60' xmlns='http:\/\/www.w3.org\/2000\/svg'%3E%3Cg fill='none' fill-rule='evenodd'%3E%3Cg fill='%23ffffff' fill-opacity='0.05'%3E%3Cpath d='M36 34v-4h-2v4h-4v2h4v4h2v-4h4v-2h-4zm0-30V0h-2v4h-4v2h4v4h2V6h4V4h-4zM6 34v-4H4v4H0v2h4v4h2v-4h4v-2H6zM6 4V0H4v4H0v2h4v4h2V6h4V4H6z'\/%3E%3C\/g%3E%3C\/g%3E%3C\/svg%3E\") repeat;\n  pointer-events: none;\n}\n.lk-stays-icon {\n  flex-shrink: 0;\n  width: 68px;\n  height: 68px;\n  border-radius: 14px;\n  background: linear-gradient(135deg, #fff 0%, #f9f6f0 100%);\n  display: flex;\n  align-items: center;\n  justify-content: center;\n  font-size: 26px;\n  box-shadow: 0 4px 12px rgba(0,0,0,0.15);\n}\n.lk-stays-eyebrow {\n  font-size: 10px;\n  font-weight: 500;\n  letter-spacing: 2.5px;\n  text-transform: uppercase;\n  color: rgba(255,255,255,.85);\n  margin: 0 0 5px 0;\n}\n.lk-stays-title {\n  font-family: 'Playfair Display', Georgia, serif;\n  font-size: 24px;\n  font-weight: 700;\n  color: #fff;\n  line-height: 1.2;\n  text-shadow: 0 1px 2px rgba(0,0,0,0.1);\n  margin: 0;\n}\n.lk-stays-subtitle {\n  font-size: 13px;\n  color: rgba(255,255,255,.75);\n  margin: 4px 0 0 0;\n  font-weight: 300;\n}\n\n\/* \u2500\u2500\u2500 CARDS GRID \u2500\u2500\u2500 *\/\n.lk-stays-grid {\n  display: grid;\n  grid-template-columns: 1fr 1fr;\n  gap: 1px;\n  background: rgba(195, 159, 118, 0.12);\n}\n\n\/* \u2500\u2500\u2500 SINGLE CARD \u2500\u2500\u2500 *\/\n.lk-stay-card {\n  background: #ffffff;\n  padding: 26px;\n  display: flex;\n  flex-direction: column;\n  gap: 11px;\n  transition: all 0.3s ease;\n  text-decoration: none;\n  color: inherit;\n  position: relative;\n}\n.lk-stay-card:hover {\n  background: #fffbf5;\n  transform: translateY(-2px);\n  box-shadow: 0 8px 24px rgba(195, 159, 118, 0.18);\n  z-index: 1;\n}\n.lk-stay-card.featured {\n  background: linear-gradient(135deg, #fffdf9 0%, #fff9f0 100%);\n  box-shadow: 0 4px 16px rgba(195, 159, 118, 0.15), inset 0 1px 0 rgba(195, 159, 118, 0.1);\n}\n.lk-stay-card.featured:hover {\n  background: linear-gradient(135deg, #fffbf5 0%, #fff8ed 100%);\n  box-shadow: 0 8px 24px rgba(195, 159, 118, 0.25), inset 0 1px 0 rgba(195, 159, 118, 0.15);\n}\n\n.lk-stay-badge {\n  display: inline-flex;\n  align-items: center;\n  gap: 5px;\n  font-size: 10px;\n  font-weight: 500;\n  letter-spacing: 1.5px;\n  text-transform: uppercase;\n  padding: 5px 11px;\n  border-radius: 20px;\n  width: fit-content;\n}\n.badge-top     { background: linear-gradient(135deg, #c39f76 0%, #d4b188 100%); color: #fff; border: 1px solid #c39f76; font-weight: 600; box-shadow: 0 2px 8px rgba(195,159,118,0.3); }\n.badge-luxury  { background: rgba(195,159,118,.12); color: #c39f76; border: 1px solid rgba(195,159,118,.25); }\n.badge-boutique{ background: rgba(54,133,252,.08); color: #3685fc; border: 1px solid rgba(54,133,252,.2); }\n.badge-nature  { background: rgba(130,190,100,.1); color: #6b9c4a; border: 1px solid rgba(130,190,100,.2); }\n.badge-remote  { background: rgba(195,159,118,.12); color: #a67e50; border: 1px solid rgba(195,159,118,.25); }\n\n.lk-stay-name {\n  font-family: 'Playfair Display', Georgia, serif;\n  font-size: 18px;\n  font-weight: 700;\n  color: #111827;\n  line-height: 1.3;\n}\n.lk-stay-desc {\n  font-size: 13.5px;\n  color: #525252;\n  line-height: 1.65;\n  font-weight: 300;\n  flex: 1;\n}\n\n.lk-stay-meta {\n  display: flex;\n  align-items: center;\n  gap: 12px;\n  flex-wrap: wrap;\n  margin-top: 4px;\n}\n.lk-stay-price {\n  font-size: 13px;\n  color: #6b7280;\n}\n.lk-stay-price strong {\n  color: #c39f76;\n  font-weight: 500;\n}\n.lk-stay-stars {\n  color: #c39f76;\n  font-size: 11px;\n  letter-spacing: 1px;\n}\n\n\/* \u2500\u2500\u2500 CTA BUTTON \u2500\u2500\u2500 *\/\n.lk-stay-cta {\n  display: inline-flex;\n  align-items: center;\n  justify-content: center;\n  gap: 7px;\n  margin-top: 8px;\n  padding: 11px 20px;\n  border-radius: 8px;\n  background: linear-gradient(135deg, #3685fc 0%, #2a6fd9 100%);\n  color: #fff;\n  font-size: 13px;\n  font-weight: 500;\n  text-decoration: none;\n  letter-spacing: .3px;\n  transition: all .2s ease;\n  cursor: pointer;\n  border: none;\n  text-align: center;\n  box-shadow: 0 4px 12px rgba(54, 133, 252, 0.25);\n}\n.lk-stay-cta:hover {\n  background: linear-gradient(135deg, #2a6fd9 0%, #1e5bc4 100%);\n  transform: translateY(-1px);\n  box-shadow: 0 6px 16px rgba(54, 133, 252, 0.35);\n}\n.lk-stay-cta svg { flex-shrink: 0; }\n\n\/* \u2500\u2500\u2500 FOOTER \u2500\u2500\u2500 *\/\n.lk-stays-footer {\n  padding: 18px 36px;\n  background: linear-gradient(to bottom, #fdfaf5 0%, #f9f4ed 100%);\n  border-top: 1px solid rgba(195, 159, 118, 0.15);\n  display: flex;\n  align-items: center;\n  justify-content: space-between;\n  flex-wrap: wrap;\n  gap: 12px;\n}\n.lk-stays-footer-note {\n  font-size: 11.5px;\n  color: #6b7280;\n  font-weight: 300;\n  line-height: 1.5;\n}\n.lk-stays-footer-note a {\n  color: #c39f76;\n  text-decoration: none;\n  font-weight: 400;\n}\n.lk-stays-footer-note a:hover {\n  text-decoration: underline;\n}\n.lk-stays-all-btn {\n  display: inline-flex;\n  align-items: center;\n  gap: 6px;\n  font-size: 12.5px;\n  font-weight: 500;\n  color: #c39f76;\n  text-decoration: none;\n  border: 1px solid rgba(195, 159, 118, 0.35);\n  padding: 8px 18px;\n  border-radius: 8px;\n  transition: all .2s ease;\n}\n.lk-stays-all-btn:hover {\n  background: rgba(195, 159, 118, 0.08);\n  border-color: rgba(195, 159, 118, 0.5);\n}\n\n\/* \u2500\u2500\u2500 RESPONSIVE \u2500\u2500\u2500 *\/\n@media (max-width: 600px) {\n  .lk-stays-grid { grid-template-columns: 1fr; }\n  .lk-stays-header { padding: 24px 20px; }\n  .lk-stays-footer { padding: 16px 20px; }\n  .lk-stay-card { padding: 22px; }\n  .lk-stays-title { font-size: 20px; }\n}\n<\/style>\n\n  <!-- HEADER -->\n  <div class=\"lk-stays-header\">\n    <img decoding=\"async\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/02\/lukas-a-lucka.jpg\" alt=\"\" style=\"width: 75px; height: 75px; border-radius: 8px; flex-shrink: 0; object-fit: cover; display: block; margin: 4px 0;\" title=\"\">\n    <div class=\"lk-stays-header-text\">\n      <div class=\"lk-stays-eyebrow\">Luk\u00e1\u0161 und Lucie empfehlen<\/div>\n      <div class=\"lk-stays-title\">Wo man in Paris \u00fcbernachten kann<\/div>\n      <div class=\"lk-stays-subtitle\">3 Unterk\u00fcnfte \u2014 Wellnesshotels, Hotels und weitere Unterkunftsm\u00f6glichkeiten<\/div>\n    <\/div>\n  <\/div>\n\n  <!-- CARDS -->\n  <div class=\"lk-stays-grid\">\n\n    <a class=\"lk-stay-card featured\" href=\"https:\/\/booking.stay22.com\/lukaskonecny\/AxKJ70l2yy?aid=lukaskonecny&#038;campaign=loudavymkrokemcz-nakupyvparizi&#038;product=allez&#038;habl=false&#038;isinc=false&#038;sid22=eyOhfbUVRdp25NRC&#038;conmeth=normal&#038;plng=cs-CZ&#038;pageCategory=travel&#038;address=Paris%2C+France&#038;source=direct&#038;ref22=https%3A%2F%2Floudavymkrokem.cz%2Fnakupy-v-parizi&#038;campaign=loudavymkrokemcz-vyletyzparize-loudavymkrokemcz-nejlepsimuzeaparize-loudavymkrokemcz-parizzdarma\" target=\"_blank\" rel=\"nofollow noopener\">\n      <span class=\"lk-stay-badge badge-top\">\u2b50 TOP WAHL<\/span>\n      <span class=\"lk-stay-badge badge-nature\">\ud83c\udfe8 Hotel<\/span>\n      <div class=\"lk-stay-name\">H\u00f4bou<\/div>\n      <div class=\"lk-stay-desc\">Authentisches franz\u00f6sisches Boutique-Hotel in Boulogne-Billancourt. Von den Autoren des Artikels als ideale Unterkunft f\u00fcr Familien mit Kindern ausgew\u00e4hlt. Auf den ersten Blick wirkt es unscheinbar, aber innerhalb der ersten paar Stunden werden Sie es lieben.<\/div>\n      <div class=\"lk-stay-meta\">\n        <span class=\"lk-stay-stars\">\u2605\u2605\u2605\u2605<\/span>\n        <span class=\"lk-stay-price\">Preise pr\u00fcfen<\/span>\n      <\/div>\n      <span class=\"lk-stay-cta\">\n        <svg width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg>\n        Verf\u00fcgbarkeit pr\u00fcfen\n      <\/span>\n    <\/a>\n\n    <a class=\"lk-stay-card\" href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&#038;campaign=loudavymkrokemcz&#038;campaign=de&#038;campaign=emilyinparispariz&#038;address=Pa%C5%99%C3%AD%C5%BE&#038;hotelname=H%C3%B4tel+Plaza+Ath%C3%A9n%C3%A9e&#038;search=H%C3%B4tel+Plaza+Ath%C3%A9n%C3%A9e&#038;category=accommodation\" target=\"_blank\" rel=\"nofollow noopener\">\n      <span class=\"lk-stay-badge badge-nature\">\u2b50 Luxury<\/span>\n      <div class=\"lk-stay-name\">H\u00f4tel Plaza Ath\u00e9n\u00e9e<\/div>\n      <div class=\"lk-stay-desc\">Luxushotel aus der 5. Staffel der Serie Emily in Paris, in dem sowohl Alfie als auch der Kunde Antoine wohnten. Im Winter gab es hier eine kleine Eisbahn. Ein Zimmer ist hier astronomisch teuer, erschwinglicher ist ein Cocktail in der hoteleigenen Bar.<\/div>\n      <div class=\"lk-stay-meta\">\n        <span class=\"lk-stay-stars\">\u2605\u2605\u2605\u2605<\/span>\n        <span class=\"lk-stay-price\">Cocktail in der Bar ab 25-60 EUR<\/span>\n      <\/div>\n      <span class=\"lk-stay-cta\">\n        <svg width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg>\n        Verf\u00fcgbarkeit pr\u00fcfen\n      <\/span>\n    <\/a>\n\n    <a class=\"lk-stay-card\" href=\"https:\/\/www.stay22.com\/allez\/roam?aid=lukaskonecny&#038;campaign=loudavymkrokemcz&#038;campaign=de&#038;campaign=emilyinparispariz&#038;address=pa\u0159\u00ed\u017e\" target=\"_blank\" rel=\"nofollow noopener\">\n      <span class=\"lk-stay-badge badge-nature\">\ud83d\udd0d Suchen<\/span>\n      <div class=\"lk-stay-name\">Alle Unterk\u00fcnfte in Paris anzeigen<\/div>\n      <div class=\"lk-stay-desc\">Erkunden Sie alle verf\u00fcgbaren Unterkunftsm\u00f6glichkeiten in Paris und finden Sie die beste Option nach Ihren Vorlieben und Ihrem Budget.<\/div>\n      <div class=\"lk-stay-meta\">\n        <span class=\"lk-stay-stars\">\u2605\u2605\u2605\u2605<\/span>\n        <span class=\"lk-stay-price\">Preise vergleichen<\/span>\n      <\/div>\n      <span class=\"lk-stay-cta\">\n        <svg width=\"14\" height=\"14\" viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\"><path d=\"M18 13v6a2 2 0 0 1-2 2H5a2 2 0 0 1-2-2V8a2 2 0 0 1 2-2h6\"\/><polyline points=\"15 3 21 3 21 9\"\/><line x1=\"10\" y1=\"14\" x2=\"21\" y2=\"3\"\/><\/svg>\n        Verf\u00fcgbarkeit pr\u00fcfen\n      <\/span>\n    <\/a>\n\n  <\/div>\n\n  \n<\/div>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Montmartre_die_fotogensten_Szenen_der_Serie\"><\/span><span class=\"ez-toc-section\" id=\"Montmartre_die_fotogensten_Szenen_der_Serie\"><\/span>Montmartre: die fotogensten Szenen der Serie<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Wenn du dir eine kleine Auszeit vom Trubel im Zentrum g\u00f6nnen m\u00f6chtest, solltest du dich unbedingt in den Norden von Paris ins bezaubernde 18. Arrondissement auf den H\u00fcgel Montmartre aufmachen. Mit seinen kopfsteingepflasterten Gassen und der leicht boh\u00e8mehaften Atmosph\u00e4re lieferte er der Serie die mit Abstand fotogensten und romantischsten Szenen. Die Metro bringt dich sicher hinauf \u2013 steig einfach an der beliebten Station Abbesses aus oder nimm den ruhigeren Weg von der Station Lamarck\u2013Caulaincourt und stell dich auf ein bisschen Steigung ein, die sich f\u00fcr die atemberaubenden Ausblicke aber absolut lohnt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"11_La_Maison_Rose\"><\/span><span class=\"ez-toc-section\" id=\"11_La_Maison_Rose\"><\/span>11. La Maison Rose<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart.jpg\" alt=\"Das rosa Restaurant La Maison Rose auf dem Montmartre, wo Emily und Mindy zu Mittag essen\" class=\"wp-image-158804\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart.jpg 2000w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-1536x1024.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-696x464.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-1392x928.jpg 1392w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-14-ruzova-rohova-restaurace-s-zelenymi-okenicemi-a-popinavymi-rostlinami-v-montmart-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\"><figcaption class=\"wp-element-caption\">Das rosa Restaurant La Maison Rose auf dem Montmartre, wo Emily und Mindy zu Mittag essen<\/figcaption><\/figure>\n\n\n\n<p>An der Ecke der Stra\u00dfe 2 Rue de l&#8217;Abreuvoir ist das bezaubernde rosa H\u00e4uschen mit Au\u00dfenpl\u00e4tzen nicht zu \u00fcbersehen \u2013 das Restaurant La Maison Rose, wo Emily und Mindy in der f\u00fcnften Folge der ersten Staffel gemeinsam zu Mittag essen und Mindy diese Stra\u00dfe als die sch\u00f6nste in ganz Paris bezeichnet. Das Restaurant hat eine unglaubliche Geschichte: Hier sa\u00dfen einst Meister wie Pablo Picasso oder Vincent van Gogh, und der ber\u00fchmte Maler Maurice Utrillo hat es auf seinen Bildern verewigt. Heute liegen die Preise pro Person zwischen 28 und 40 \u20ac, und trotz des Touristen-Hypes haben sie \u00fcberraschend gute Bewertungen. Mit nur 35 Pl\u00e4tzen im Inneren ist es unglaublich schwer, einen Tisch zu ergattern \u2013 du musst also weit im Voraus \u00fcber die offizielle Website <a href=\"https:\/\/lamaisonrose-montmartre.com\" target=\"_blank\" rel=\"nofollow noopener\">La Maison Rose<\/a> reservieren und dich trotzdem darauf einstellen, dass du manchmal kurz drau\u00dfen warten musst.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"12_Le_Mur_des_Je_taime_die_Liebeswand\"><\/span><span class=\"ez-toc-section\" id=\"12_Le_Mur_des_Je_taime_die_Liebeswand\"><\/span>12. Le Mur des Je t&#8217;aime (die Liebeswand)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Unweit der Metro-Station Abbesses liegt der kleine Park Square Jehan Rictus, und darin verborgen ein blaues Wunder namens Le Mur des Je t&#8217;aime \u2013 die Liebeswand, auf der der Satz \u201eIch liebe dich&#8220; in mehr als 311 Sprachen und 250 verschiedenen Dialekten der ganzen Welt geschrieben steht. Dieser Ort, dessen Besuch kostenlos ist, erscheint in der dritten Staffel, als K\u00fcchenchef Gabriel hier nerv\u00f6s die Wand betrachtet und romantisch \u00fcber den perfekten Ort f\u00fcr seinen bevorstehenden Heiratsantrag nachdenkt. Es ist ein ziemlich kleiner Platz, und tags\u00fcber ist es hier recht voll mit verliebten Paaren, die ihren \u201eIch liebe dich&#8220;-Schriftzug fotografieren \u2013 die beste Zeit f\u00fcr ein sch\u00f6nes, ruhiges Foto ist also auch hier am besten gleich nach dem Fr\u00fchst\u00fcck.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"13_Sacre-Coeur\"><\/span><span class=\"ez-toc-section\" id=\"13_Sacre-Coeur\"><\/span>13. Sacr\u00e9-C\u0153ur<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1333\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky.jpg\" alt=\"Die wei\u00dfe Basilika Sacr\u00e9-C\u0153ur auf der Spitze des Pariser Montmartre\" class=\"wp-image-158803\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky.jpg 2000w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-300x200.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-700x467.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-768x512.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-1536x1024.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-696x464.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-1392x928.jpg 1392w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/co-videt-v-parizi-13-bila-bazilika-sacre-c-ur-s-kupoli-pred-ni-travnik-s-navstevniky-1920x1280.jpg 1920w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\"><figcaption class=\"wp-element-caption\">Die wei\u00dfe Basilika Sacr\u00e9-C\u0153ur auf der Spitze des Pariser Montmartre<\/figcaption><\/figure>\n\n\n\n<p>Ganz oben auf der Spitze des Montmartre-H\u00fcgels an der Adresse 35 Rue du Chevalier de la Barre thront die schneewei\u00dfe Basilika Sacr\u00e9-C\u0153ur, die als Kulisse f\u00fcr eine gro\u00dfartige Serienszene aus der dritten Staffel dient \u2013 hier machen die Figuren einen Instagram-Livestream und genie\u00dfen den Blick \u00fcber die Stadt unter ihnen. Der Spaziergang rund um die Basilika und der Blick \u00fcber ganz Paris sind kostenlos, aber wenn du das wundersch\u00f6ne Innere besichtigen m\u00f6chtest, solltest du 6 \u20ac einplanen \u2013 der Aufstieg zur Kuppel kostet nochmal 7 \u20ac extra. An dieser Stelle m\u00f6chte ich ausdr\u00fccklich warnen: Der Vorplatz der Basilika ist oft extrem \u00fcberf\u00fcllt, hier trifft man regelm\u00e4\u00dfig auf aufdringliche Armbandverk\u00e4ufer, und vor allem muss man penibel auf seine Wertsachen achten, denn Taschendiebe sind hier leider an der Tagesordnung. Komm am besten fr\u00fch morgens, wenn es hier herrlich ruhig ist.<\/p>\n\n\n<p><!-- GYG:Montmartre --><\/p>\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Bruecken_und_grosse_Szenen_Parfuem_Strassenmusik_und_Seine\"><\/span><span class=\"ez-toc-section\" id=\"Bruecken_und_grosse_Szenen_Parfuem_Strassenmusik_und_Seine\"><\/span>Br\u00fccken und gro\u00dfe Szenen: Parf\u00fcm, Stra\u00dfenmusik und Seine<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"720\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-vecirek-eiffelovka.jpg\" alt=\"Emily auf einer Party mit dem beleuchteten Eiffelturm im Hintergrund, Serie Emily in Paris\" class=\"wp-image-159196\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-vecirek-eiffelovka.jpg 1280w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-vecirek-eiffelovka-300x169.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-vecirek-eiffelovka-700x394.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-vecirek-eiffelovka-768x432.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-vecirek-eiffelovka-696x392.jpg 696w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\"><figcaption class=\"wp-element-caption\">Emily auf einer Party mit dem beleuchteten Eiffelturm im Hintergrund, Serie Emily in Paris<\/figcaption><\/figure>\n\n\n\n<p>Die visuelle Seite der Serie nutzt die wundersch\u00f6ne Szenerie entlang der Pariser Seine und ihre verzierten Br\u00fccken voll aus. Sie dienen als perfekte dramatische und romantische Kulisse f\u00fcr die wichtigsten Drehmomente \u2013 und es w\u00e4re einfach schade, bei deinem Ausflug nicht wenigstens kurz \u00fcber sie hin\u00fcberzuschlendern.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"14_Pont_Alexandre_III\"><\/span><span class=\"ez-toc-section\" id=\"14_Pont_Alexandre_III\"><\/span>14. Pont Alexandre III<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1981\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii.jpg\" alt=\"Die verzierte Br\u00fccke Pont Alexandre III in Paris mit goldenen Statuen\" class=\"wp-image-159204\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii.jpg 1600w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-242x300.jpg 242w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-700x867.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-768x951.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-1241x1536.jpg 1241w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-324x400.jpg 324w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-696x862.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-alexandre-iii-1392x1723.jpg 1392w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\"><figcaption class=\"wp-element-caption\">Die verzierte Br\u00fccke Pont Alexandre III in Paris mit goldenen Statuen<\/figcaption><\/figure>\n\n\n\n<p>Die prachtvolle und reich verzierte Jugendstilbr\u00fccke Pont Alexandre III stammt aus dem Jahr 1900, liegt genau zwischen dem 7. und 8. Arrondissement unweit der Metro-Station Invalides und dient zu Beginn der ersten Staffel als Location f\u00fcr den Dreh jener provokanten Parf\u00fcmwerbung der Marke Maison Lavaux, bei der Emily sich mit dem Kunden \u00fcber die Angemessenheit von Nacktheit in der Werbung streitet. Die Br\u00fccke beeindruckt mit fantastischen goldenen Statuen und Laternen, und der Blick von hier \u00fcber die Seine zum Eiffelturm ist schlicht zauberhaft \u2013 und kostenlos. Sei aber darauf gefasst, dass dieser Spot besonders bei Sonnenuntergang extrem beliebt und ziemlich \u00fcberlaufen ist \u2013 Hochzeitsfotografen und normale Reisende tummeln sich hier gleicherma\u00dfen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"15_Pont_des_Arts\"><\/span><span class=\"ez-toc-section\" id=\"15_Pont_des_Arts\"><\/span>15. Pont des Arts<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"1200\" src=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts.jpg\" alt=\"Die Fu\u00dfg\u00e4ngerbr\u00fccke Pont des Arts \u00fcber die Seine mit dem Institut de France\" class=\"wp-image-159203\" title=\"\" srcset=\"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts.jpg 1600w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-300x225.jpg 300w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-700x525.jpg 700w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-768x576.jpg 768w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-1536x1152.jpg 1536w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-80x60.jpg 80w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-160x120.jpg 160w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-696x522.jpg 696w, https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pont-des-arts-1392x1044.jpg 1392w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\"><figcaption class=\"wp-element-caption\">Die Fu\u00dfg\u00e4ngerbr\u00fccke Pont des Arts \u00fcber die Seine mit dem Institut de France<\/figcaption><\/figure>\n\n\n\n<p>Die deutlich intimere h\u00f6lzerne Fu\u00dfg\u00e4ngerbr\u00fccke Pont des Arts, die zwischen dem ber\u00fchmten Louvre und dem Sitz des Institut de France liegt, spielte gleich mehrfach eine wichtige Rolle. Zum Beispiel findet am Ende der ersten Staffel das Gespr\u00e4ch zwischen Chefin Sylvie und Emily hier statt, und in der zweiten Staffel versucht Emilys Freundin Mindy hier etwas ungl\u00fccklich, als Stra\u00dfenmusikerin Geld zu verdienen. Diese Br\u00fccke war einst daf\u00fcr ber\u00fchmt, dass verliebte Paare sogenannte Liebesschl\u00f6sser ans Gel\u00e4nder h\u00e4ngten und die Schl\u00fcssel in die Seine warfen. Doch das Gel\u00e4nder wurde unter dem Gewicht des Metalls so schwer und besch\u00e4digt, dass die Stadt es entfernen und durch spezielle Glasplatten ersetzen musste \u2013 die Romantik ist geblieben, nur ohne die tausenden Vorh\u00e4ngeschl\u00f6sser. Der Besuch und die Ausblicke \u00fcber den Fluss sind selbstverst\u00e4ndlich kostenlos, und du wirst genie\u00dfen, wie Paris von hier aus eine ruhigere Atmosph\u00e4re ausstrahlt.<\/p>\n\n\n\n<p>Neben diesen Hauptstationen taucht die Serie auch kurz an weiteren sch\u00f6nen Orten auf, die eine kurze Erw\u00e4hnung verdienen, falls dir noch Zeit bleibt:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>H\u00f4tel Plaza Ath\u00e9n\u00e9e<\/strong> (25 Avenue Montaigne, 8. Arrondissement): das Luxushotel, in dem sowohl Alfie als auch der Kunde Antoine wohnen und wo es im Winter sogar eine kleine Eislaufbahn gab. Ein Zimmer ist astronomisch teuer, aber ein erschwinglicheres Erlebnis ist ein Cocktail an der Bar f\u00fcr 25 bis 60 \u20ac.<\/li>\n\n\n\n<li><strong>Galeries Lafayette<\/strong> (40 Boulevard Haussmann, 9. Arrondissement): das ikonische Kaufhaus, wo Emily und Camille auf dem Dach stehen und die Kadiance-Creme-Aktion aus der vierten Staffel stattfindet. Der Eintritt ins Haus und auf die Dachterrasse mit Aussicht ist kostenlos.<\/li>\n\n\n\n<li><strong>Mus\u00e9e d&#8217;Orsay<\/strong>: das ber\u00fchmte Museum f\u00fcr Impressionismus, wo in der neunten Episode der dritten Staffel die wundersch\u00f6ne Verlobungsszene von Gabriel und Camille an den ikonischen Uhren stattfindet. Der Eintritt kostet 16 \u20ac, montags ist geschlossen, Tickets findest du auf der offiziellen Website des <a href=\"https:\/\/www.musee-orsay.fr\" target=\"_blank\" rel=\"nofollow noopener\">Mus\u00e9e d&#8217;Orsay<\/a>.<\/li>\n\n\n\n<li><strong>Mus\u00e9e des Arts Forains<\/strong> (53 Avenue des Terroirs de France, 12. Arrondissement): ein Museum f\u00fcr Jahrmarktskunst, wo die unglaublich extravagante Party in der ersten Staffel gedreht wurde. Besichtigen kann man es aber nur mit einer vorab gebuchten F\u00fchrung f\u00fcr 15 bis 20 \u20ac.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Wo_essen_auf_Emilys_Spuren_ohne_zweite_Hypothek\"><\/span><span class=\"ez-toc-section\" id=\"Wo_essen_auf_Emilys_Spuren_ohne_zweite_Hypothek\"><\/span>Wo essen auf Emilys Spuren (ohne zweite Hypothek)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Wie ich schon mehrfach erw\u00e4hnt habe, sind die beliebten Serienrestaurants und historischen ber\u00fchmten Caf\u00e9s im Zentrum oft teuer \u2013 nicht selten handelt es sich um regelrechte Luxusadressen, bei denen du f\u00fcr den Namen und einen Stuhl auf dem B\u00fcrgersteig ordentlich draufzahlst, was das Budget nicht gerade schont. Wenn du es dir leisten kannst und willst: nur zu! Aber damit du in Paris nicht bei Brot und Wasser endest, gibt es auch fantastische und bezahlbare Alternativen.<\/p>\n\n\n\n<p>Eine tolle Idee ist es, gleich morgens bei der Boulangerie Moderne vorbeizuschauen und dir f\u00fcr ein paar Euro frisches, herrlich duftendes Geb\u00e4ck zu holen, das du auf dem Weg mitnimmst und mit einem Kaffee im nahegelegenen Jardin du Luxembourg mit gro\u00dfartiger Aussicht genie\u00dfen kannst. Was das Restaurant Terra Nera angeht: Ehrlich gesagt ist es zwar ein italienisches und kein klassisch franz\u00f6sisches Restaurant wie im Film, aber es wird dort wirklich gut gekocht, und die Preise f\u00fcr ein Abendessen sind im Pariser Kontext nicht katastrophal \u2013 nur Schnecken in Kr\u00e4uterbutter wirst du vergeblich suchen. Wenn ich euch etwas abseits der Emily-in-Paris-Welt empfehlen darf: Wir waren in Paris begeistert von den traditionellen historischen Speisehallen, den sogenannten Bouillons, wie zum Beispiel dem legend\u00e4ren Bouillon Chartier. Dort bekommt man eine sehr ordentliche franz\u00f6sische Klassik wie Zwiebelsuppe oder gebratenes H\u00e4hnchen in gro\u00dfem Trubel zu unglaublich g\u00fcnstigen Preisen. Alternativ probiere einfach irgendein unscheinbares Bistro zwei Stra\u00dfen abseits der gro\u00dfen Pl\u00e4tze.<\/p>\n\n\n\n<p>\ud83d\udca1 Tipp: Wenn du ein richtig tolles kulinarisches Erlebnis m\u00f6chtest, ohne Hunderte Euro f\u00fcr ein Mittagessen im Le Grand V\u00e9four auszugeben, halte nach Restaurants Ausschau, die ein sogenanntes Mittagsmen\u00fc (formule midi) anbieten. F\u00fcr ein Drei-G\u00e4nge-Mittagessen zahlst du oft sogar weniger als zwanzig Euro und isst genauso gut wie am Abend zum dreifachen Preis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Bevor_du_losgehst_sei_ruecksichtsvoll_gegenueber_den_Anwohnern\"><\/span><span class=\"ez-toc-section\" id=\"Bevor_du_losgehst_sei_ruecksichtsvoll_gegenueber_den_Anwohnern\"><\/span>Bevor du losgehst: sei r\u00fccksichtsvoll gegen\u00fcber den Anwohnern<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Wenn du dich in die Stadt aufmachst, um bekannte Seriendrehorte zu fotografieren, ist ein Hinweis besonders wichtig \u2013 und er betrifft die Pariser selbst. Der pl\u00f6tzliche und enorme Ruhm der Serie hat aus vielen ehemals ruhigen Vierteln \u00fcberf\u00fcllte Touristenziele gemacht. Der kleine Platz Place de l&#8217;Estrapade war fr\u00fcher ein unauff\u00e4lliger, sehr stiller Innenhof, an dem die Leute in Ruhe ihren Kaffee tranken. Heute ist er ein riesiger Touristenmagnet, und an den W\u00e4nden kann man sogar aufgespr\u00fchte Schriftz\u00fcge wie \u201eEmily n&#8217;est pas la bienvenue&#8220; (Emily ist hier nicht willkommen) finden \u2013 ein deutliches Zeichen f\u00fcr die enorme Frustration derer, die hier einfach nur wohnen m\u00f6chten.<\/p>\n\n\n\n<p>Auch wenn wir uns alle das sch\u00f6nste Foto mit Baskenm\u00fctze vor den Fenstern der Hauptfiguren w\u00fcnschen: Der Besitzer der Boulangerie Moderne, Thierry Rabineau, hat k\u00fcrzlich in einem Interview bedr\u00fcckt zugegeben, dass ihn das Verhalten der Fans tief verletzt. Von den sechs- bis siebenhundert Kunden t\u00e4glich sind vierzig Prozent Serienfans, von denen viele \u00fcberhaupt nichts kaufen. Und wenn sie dann im Urlaub nicht hineinkommen oder feststellen, dass Haus und B\u00e4ckerei nicht genauso aussehen wie bei Netflix, hinterlassen sie unfaire und giftige Bewertungen auf Google Maps. Ich m\u00f6chte daher im Namen aller Anwohner appellieren: Denkt daran, dass dies die Wohnungen und Gesch\u00e4fte ganz normaler Menschen und Familien sind. Kommt am besten sehr fr\u00fch morgens, sprecht leise, klingelt auf keinen Fall an den Hausglocken und fotografiert den Leuten nicht durch die Erdgeschoss-Fenster. Wenn ihr euch schon die M\u00fche macht hinzugehen, kauft euch ganz normal einen Kaffee oder einen Croissant, seid freundlich zu den Leuten hinter der Theke \u2013 und ihr werdet sehen, dass das Erlebnis f\u00fcr alle Beteiligten viel angenehmer und sch\u00f6ner wird.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Weiterlesen\"><\/span><span class=\"ez-toc-section\" id=\"Weiterlesen\"><\/span>Weiterlesen<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Interessiert dich die franz\u00f6sische Metropole und m\u00f6chtest du auch \u00fcber Orte lesen, die vielleicht nicht direkt mit der Serie zusammenh\u00e4ngen, aber bei deinem Besuch auf keinen Fall fehlen sollten? Dann schau dir unseren ausf\u00fchrlichen Guide an, in dem wir umfangreiche Tipps zusammengestellt haben, <a href=\"https:\/\/loudavymkrokem.cz\/de\/paris-beste-reiseziele\/\">was man in Paris noch sehen kann<\/a>. Und wenn du \u2013 so wie wir damals \u2013 mit der ganzen Familie und quirligen Kleinkindern im Kinderwagen in die Stadt der Liebe und Croissants f\u00e4hrst, dann helfen dir bestimmt unsere erprobten Tipps, wie du <a href=\"https:\/\/loudavymkrokem.cz\/de\/paris-mit-kindern\/\">Paris mit Kindern<\/a> stressfrei meistern kannst.<\/p>\n\n\n\n<p>Offizielle Informationen zu allen Sehensw\u00fcrdigkeiten, zum \u00f6ffentlichen Nahverkehr und zu aktuellen Neuigkeiten in verschiedenen Sprachen findest du auch auf der bew\u00e4hrten <a href=\"https:\/\/parisjetaime.com\" target=\"_blank\" rel=\"nofollow noopener\">offiziellen Tourismus-Website der Stadt Paris<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Haeufig_gestellte_Fragen_FAQ\"><\/span><span class=\"ez-toc-section\" id=\"Haeufig_gestellte_Fragen_FAQ\"><\/span>H\u00e4ufig gestellte Fragen (FAQ)<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-question-1778760755000\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Wo_wurde_die_Wohnung_aus_Emily_in_Paris_gedreht\"><\/span><span class=\"ez-toc-section\" id=\"Wo_wurde_die_Wohnung_aus_Emily_in_Paris_gedreht\"><\/span>Wo wurde die Wohnung aus Emily in Paris gedreht?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Die ber\u00fchmte Wohnung der Hauptfigur aus der Netflix-Produktion wurde am Platz Place de l&#8217;Estrapade Nummer 1 gedreht, der sich im 5. Pariser Arrondissement (Quartier Latin) in Gehweite des Jardin du Luxembourg und des Panth\u00e9on befindet.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1778760755001\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Kann_man_Emilys_Wohnung_von_innen_besichtigen\"><\/span><span class=\"ez-toc-section\" id=\"Kann_man_Emilys_Wohnung_von_innen_besichtigen\"><\/span>Kann man Emilys Wohnung von innen besichtigen?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Leider nein \u2013 es handelt sich um ein ganz normales privates Wohnhaus, in dem echte Pariser leben. Man kann die Adresse daher nur von der Stra\u00dfe aus durch die Eingangst\u00fcr betrachten. Bitte respektiert die Ruhe und Privatsph\u00e4re aller Bewohner und fotografiert r\u00fccksichtsvoll, am besten morgens.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1778760755002\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Welches_Restaurant_ist_Gabriels_Restaurant\"><\/span><span class=\"ez-toc-section\" id=\"Welches_Restaurant_ist_Gabriels_Restaurant\"><\/span>Welches Restaurant ist Gabriels Restaurant?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Gabriels Stammlokal, das in der ersten Staffel den Namen Les Deux Comp\u00e8res tr\u00e4gt, wurde im echten Restaurant Terra Nera an der Adresse 18 Rue des Foss\u00e9s Saint-Jacques gedreht. Entgegen der Erwartung vieler Fans bietet es in Wirklichkeit haupts\u00e4chlich italienische K\u00fcche.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1778760755003\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Kann_man_alle_Drehorte_an_einem_Tag_zu_Fuss_ablaufen\"><\/span><span class=\"ez-toc-section\" id=\"Kann_man_alle_Drehorte_an_einem_Tag_zu_Fuss_ablaufen\"><\/span>Kann man alle Drehorte an einem Tag zu Fu\u00df ablaufen?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Ja, das ist absolut machbar und ziemlich einfach. Die allermeisten Serien-Locations im Zentrum liegen nur wenige Gehminuten voneinander entfernt, sodass du die wichtigste Rundtour in gem\u00fctlichem Tempo in 2 bis 3 Stunden ohne gro\u00dfe Anstrengung schaffst.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1778760755004\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Gibt_es_gefuehrte_Touren_zu_den_Emily_in_Paris_Drehorten\"><\/span><span class=\"ez-toc-section\" id=\"Gibt_es_gefuehrte_Touren_zu_den_Emily_in_Paris_Drehorten\"><\/span>Gibt es gef\u00fchrte Touren zu den Emily in Paris Drehorten?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Auf jeden Fall! Nach dem riesigen Erfolg der Serie gibt es mittlerweile zahlreiche organisierte Spazierg\u00e4nge mit lokalen Guides, die du beispielsweise \u00fcber verschiedene Anbieter ab etwa 14,50 \u20ac pro Person buchen kannst.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1778760755005\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Wo_ist_die_Baeckerei_aus_Emily_in_Paris\"><\/span><span class=\"ez-toc-section\" id=\"Wo_ist_die_Baeckerei_aus_Emily_in_Paris\"><\/span>Wo ist die B\u00e4ckerei aus Emily in Paris?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Die handwerkliche B\u00e4ckerei mit den k\u00f6stlichen Croissants namens Boulangerie Moderne mit ihrer klassischen historischen Schaufensterfront findest du gleich neben dem italienischen Restaurant Terra Nera in derselben Stra\u00dfe an der Hausnummer 16. Es ist ein voll funktionsf\u00e4higer und preisgekr\u00f6nter Pariser Familienbetrieb.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-question-1778760755006\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \"><span class=\"ez-toc-section\" id=\"Wurde_die_5_Staffel_in_Paris_gedreht\"><\/span><span class=\"ez-toc-section\" id=\"Wurde_die_5_Staffel_in_Paris_gedreht\"><\/span>Wurde die 5. Staffel in Paris gedreht?<span class=\"ez-toc-section-end\"><\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<div class=\"rank-math-answer \">\n\n<p>Die f\u00fcnfte Staffel von Emily in Paris erschien zwar im Dezember 2025, doch die Handlung verlagert sich darin \u00fcberraschend zu gro\u00dfen Teilen von den Stra\u00dfen der franz\u00f6sischen Metropole in den S\u00fcden Europas nach Rom, wohin die Hauptfigur beruflich und privat aufbricht. Dieser Wechsel soll auch in der bereits best\u00e4tigten sechsten Staffel fortgesetzt werden.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Wir haben alle 15 Drehorte der Netflix-Serie Emily in Paris in Paris Frankreich recherchiert \u2013 von Emilys Wohnung \u00fcber die ber\u00fchmte B\u00e4ckerei bis zu den ikonischen Br\u00fccken \u00fcber der Seine. Mit genauen Adressen, Preisen und praktischen Tipps f\u00fcr deinen Rundgang.<\/p>\n","protected":false},"author":3,"featured_media":159193,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","rank_math_title":"","rank_math_description":"","rank_math_focus_keyword":"","rank_math_seo_score":""},"categories":[456,473,1497,451],"tags":[],"class_list":["post-161308","post","type-post","status-publish","format-standard","has-post-thumbnail","category-europa","category-frankreich","category-paris","category-reisen"],"acf":[],"featured_image_src":"https:\/\/loudavymkrokem.cz\/wp-content\/uploads\/2026\/05\/emily-in-paris-pariz-ulicka.jpg","author_info":{"display_name":"Lucie Kone\u010dn\u00e1","author_link":"https:\/\/loudavymkrokem.cz\/de\/author\/lucie-konecna\/"},"_links":{"self":[{"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/posts\/161308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/comments?post=161308"}],"version-history":[{"count":13,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/posts\/161308\/revisions"}],"predecessor-version":[{"id":308280,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/posts\/161308\/revisions\/308280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/media\/159193"}],"wp:attachment":[{"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/media?parent=161308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/categories?post=161308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loudavymkrokem.cz\/de\/wp-json\/wp\/v2\/tags?post=161308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}